{"id":5006,"count":3,"description":"","link":"https:\/\/www.mundoagropecuario.cl\/new\/tag\/lacteos-nutricion-y-salud\/","name":"L\u00e1cteos: Nutrici\u00f3n y Salud","slug":"lacteos-nutricion-y-salud","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u00e1cteos: Nutrici\u00f3n y Salud archivos - Mundoagropecuario<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mundoagropecuario.cl\/new\/tag\/lacteos-nutricion-y-salud\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u00e1cteos: Nutrici\u00f3n y Salud archivos - Mundoagropecuario\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mundoagropecuario.cl\/new\/tag\/lacteos-nutricion-y-salud\/\" \/>\n<meta property=\"og:site_name\" content=\"Mundoagropecuario\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MundoAgropecuar\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/tag\\\/lacteos-nutricion-y-salud\\\/\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/tag\\\/lacteos-nutricion-y-salud\\\/\",\"name\":\"L\u00e1cteos: Nutrici\u00f3n y Salud archivos - Mundoagropecuario\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/tag\\\/lacteos-nutricion-y-salud\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/tag\\\/lacteos-nutricion-y-salud\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u00e1cteos: Nutrici\u00f3n y Salud\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#website\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/\",\"name\":\"Mundoagropecuario\",\"description\":\"Mundo Agropecuario\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#organization\",\"name\":\"Revista de Agricultura\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/PORTAL-1-1.png\",\"contentUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/PORTAL-1-1.png\",\"width\":1026,\"height\":100,\"caption\":\"Revista de Agricultura\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mundo.agropecuario.3\",\"https:\\\/\\\/x.com\\\/MundoAgropecuar\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/mundo-agropecuario-934009201\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u00e1cteos: Nutrici\u00f3n y Salud archivos - Mundoagropecuario","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mundoagropecuario.cl\/new\/tag\/lacteos-nutricion-y-salud\/","og_locale":"es_ES","og_type":"article","og_title":"L\u00e1cteos: Nutrici\u00f3n y Salud archivos - Mundoagropecuario","og_url":"https:\/\/www.mundoagropecuario.cl\/new\/tag\/lacteos-nutricion-y-salud\/","og_site_name":"Mundoagropecuario","twitter_card":"summary_large_image","twitter_site":"@MundoAgropecuar","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.mundoagropecuario.cl\/new\/tag\/lacteos-nutricion-y-salud\/","url":"https:\/\/www.mundoagropecuario.cl\/new\/tag\/lacteos-nutricion-y-salud\/","name":"L\u00e1cteos: Nutrici\u00f3n y Salud archivos - Mundoagropecuario","isPartOf":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#website"},"breadcrumb":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/tag\/lacteos-nutricion-y-salud\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/www.mundoagropecuario.cl\/new\/tag\/lacteos-nutricion-y-salud\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.mundoagropecuario.cl\/new\/"},{"@type":"ListItem","position":2,"name":"L\u00e1cteos: Nutrici\u00f3n y Salud"}]},{"@type":"WebSite","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#website","url":"https:\/\/www.mundoagropecuario.cl\/new\/","name":"Mundoagropecuario","description":"Mundo Agropecuario","publisher":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mundoagropecuario.cl\/new\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#organization","name":"Revista de Agricultura","url":"https:\/\/www.mundoagropecuario.cl\/new\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/logo\/image\/","url":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/11\/PORTAL-1-1.png","contentUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/11\/PORTAL-1-1.png","width":1026,"height":100,"caption":"Revista de Agricultura"},"image":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mundo.agropecuario.3","https:\/\/x.com\/MundoAgropecuar","https:\/\/www.linkedin.com\/in\/mundo-agropecuario-934009201\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/tags\/5006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts?tags=5006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}