{"id":24996,"date":"2023-12-21T13:11:59","date_gmt":"2023-12-21T16:11:59","guid":{"rendered":"https:\/\/www.mundoagropecuario.cl\/new\/?p=24996"},"modified":"2024-01-04T16:39:47","modified_gmt":"2024-01-04T19:39:47","slug":"caida-en-recepcion-nacional-de-leche-cruda-no-cede-al-mes-de-octubre","status":"publish","type":"post","link":"https:\/\/www.mundoagropecuario.cl\/new\/caida-en-recepcion-nacional-de-leche-cruda-no-cede-al-mes-de-octubre\/","title":{"rendered":"Ca\u00edda en recepci\u00f3n nacional de leche cruda no cede al mes de octubre"},"content":{"rendered":"<p>De acuerdo a los datos divulgados por la Federaci\u00f3n Nacional de Productores de Leche (Fedeleche) en base a los antecedentes liberados por la Oficina de Estudios y Pol\u00edticas Agrarias (Odepa), la recepci\u00f3n nacional de leche cruda al mes de octubre de 2023 mantiene una ca\u00edda de un 3,7% en comparaci\u00f3n al mismo periodo del a\u00f1o anterior, bajando de 1.752 a 1.688,0 millones de litros.<\/p>\n<p>Lo anterior, supone una contracci\u00f3n interanual de 64,3 millones de litros y a su vez encadenar 17 meses consecutivos a la baja. En l\u00ednea, en el mes de octubre el resultado de la recepci\u00f3n de leche es tambi\u00e9n negativo.<\/p>\n<p>En cuanto al desempe\u00f1o por zona es mayormente negativo, salvo La Araucan\u00eda y una m\u00ednima alza en La Regi\u00f3n Metropolitana, el resto de las regiones presenta una ca\u00edda en la recepci\u00f3n de leche cruda acumulada al d\u00e9cimo mes del a\u00f1o.<\/p>\n<p><strong>Desempe\u00f1o regional<\/strong><\/p>\n<p>En el desglose del pa\u00eds lechero, la principal zona productora como es la regi\u00f3n de Los Lagos, donde se concentra un 42,9% de la recepci\u00f3n nacional de leche cruda se observa una baja de 7,3% respecto al mismo periodo de 2022, cayendo de 782,1 a 724,7 millones de litros, lo que supone una ca\u00edda interanual de 57,4 millones de litros.<\/p>\n<p>En la regi\u00f3n de Los R\u00edos, con una participaci\u00f3n a nivel nacional de 33,9%, la recepci\u00f3n de leche acumula un retroceso del 0,7% respecto del mismo periodo del a\u00f1o 2022, pasando de 575,9 a 571,8 millones de litros, lo cual supone una baja interanual de 4,0 millones de litros.<\/p>\n<p><a href=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/08\/leche12-jpg-1-scaled.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-24612 \" src=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/08\/leche12-jpg-1-scaled.jpeg\" alt=\"\" width=\"529\" height=\"290\" srcset=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/08\/leche12-jpg-1-scaled.jpeg 720w, https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/08\/leche12-jpg-1-243x133.jpeg 243w, https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/08\/leche12-jpg-1-730x400.jpeg 730w\" sizes=\"auto, (max-width: 529px) 100vw, 529px\" \/><\/a>En la otra vereda, la regi\u00f3n de La Araucan\u00eda, que supone un 7,2% de la recepci\u00f3n nacional, se observa un aumento del 3,7% frente al mismo periodo del a\u00f1o anterior, subiendo de 117,7 a 122,1 millones de litros con un avance interanual de 4,4 millones de litros.<\/p>\n<p>Por su parte, en la regi\u00f3n de Bio-Bio, que tiene una participaci\u00f3n de 2,3% a nivel nacional, la recepci\u00f3n de leche cruda muestra una ca\u00edda de 12,2% comparado con el mismo periodo del a\u00f1o pasado, cayendo de 44,8 a 39,4 millones de litros, con una merma de 5,5 millones de litros.<\/p>\n<p>En la regi\u00f3n de \u00d1uble, donde se concentra un 2,3% de la recepci\u00f3n nacional de leche cruda, la variaci\u00f3n fue negativa en un 4,9% respecto del a\u00f1o anterior, cayendo de 41,5 a 39,4 millones de litros, lo que supone un retroceso de 2,0 millones de litros.<\/p>\n<p>La Regi\u00f3n Metropolitana, con una participaci\u00f3n del 11,3%, presenta una m\u00ednima subida en un 0,1% respecto del a\u00f1o anterior, pasando de 190,4 a 190,6 millones de litros, con un alza de 183 mil litros.<\/p>\n<p><a href=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/12\/Cuadro-1-.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-24998 size-full\" src=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/12\/Cuadro-1-.jpeg\" alt=\"\" width=\"550\" height=\"400\" srcset=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/12\/Cuadro-1-.jpeg 550w, https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/12\/Cuadro-1--183x133.jpeg 183w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/a><\/p>\n<p><strong>\u00bfQu\u00e9 paso en octubre?<\/strong><\/p>\n<p>En el d\u00e9cimo mes del a\u00f1o, la recepci\u00f3n nacional de leche cruda muestra una variaci\u00f3n negativa de 1,7% respecto al mismo mes del a\u00f1o anterior, que se explica principalmente por lo que ocurri\u00f3 en la regi\u00f3n de Los Lagos y un alza en Los R\u00edos que permiti\u00f3 atenuar la ca\u00edda, alcanzando un volumen total de 232,8 millones, con un descenso interanual de 3,9 millones de litros.<\/p>\n<p>En la regi\u00f3n de Los Lagos, la recepci\u00f3n de leche cruda cae un 6,7%, alcanzando un total de 105,8 millones de litros. Lo anterior, supone una merma de 7,6 millones de litros frente al mismo mes de 2022.<\/p>\n<p>En la regi\u00f3n de Los R\u00edos se registra una nueva alza en un 4,3% respecto del mismo mes de 2022, alcanzando un volumen total de 81,0 millones de litros, lo que representa un incremento de 3,3 millones de litros.<\/p>\n<p>En la regi\u00f3n de La Araucan\u00eda la recepci\u00f3n de leche cruda sube un 6,2%, lo que supone alcanzar un total de 16,9 millones de litros, resultado que es superior en 1,0 mill\u00f3n de litros frente al mismo mes del a\u00f1o anterior.<\/p>\n<p>La regi\u00f3n de Bio-Bio presenta un descenso de 13,9% en relaci\u00f3n al mismo mes del a\u00f1o previo. Este valor supone alcanzar 4,4 millones de litros, lo que supone una baja interanual de 709 mil litros frente a 2022.<\/p>\n<p>En la regi\u00f3n de \u00d1uble se observ\u00f3 una variaci\u00f3n de un 7,9% frente al mismo mes del a\u00f1o anterior, sumando un total de 4,7 millones de litros. El dato supone un avance de 343 mil litros.<\/p>\n<p>Por \u00faltimo, la regi\u00f3n Metropolitana cierra con una variaci\u00f3n negativa de un 1,3%, alcanzando un total de 20,0 millones de litros, lo que supone un retroceso de 269 mil litros respecto al mismo mes de 2022.<\/p>\n<p>Fuente: Fedeleche FG<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En base a los antecedentes de Odepa, la recepci\u00f3n nacional de leche cruda al mes de octubre de 2023,  mantiene una ca\u00edda de un 3,7% en comparaci\u00f3n al mismo periodo del a\u00f1o anterior.<\/p>\n","protected":false},"author":2,"featured_media":24618,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1946],"tags":[2090,3127,2058,2051,5824,2066,7804],"class_list":["post-24996","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lacteos","tag-agricultura","tag-agro","tag-fedeleche","tag-leche","tag-leche-cruda","tag-odepa","tag-recepcion-nacional-de-leche-cruda"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ca\u00edda en recepci\u00f3n nacional de leche cruda no cede al mes de octubre - Mundoagropecuario<\/title>\n<meta name=\"description\" content=\"En base a los antecedentes de Odepa, la recepci\u00f3n nacional de leche cruda al mes de octubre de 2023, mantiene una ca\u00edda de un 3,7%.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mundoagropecuario.cl\/new\/caida-en-recepcion-nacional-de-leche-cruda-no-cede-al-mes-de-octubre\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ca\u00edda en recepci\u00f3n nacional de leche cruda no cede al mes de octubre - Mundoagropecuario\" \/>\n<meta property=\"og:description\" content=\"En base a los antecedentes de Odepa, la recepci\u00f3n nacional de leche cruda al mes de octubre de 2023, mantiene una ca\u00edda de un 3,7%.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mundoagropecuario.cl\/new\/caida-en-recepcion-nacional-de-leche-cruda-no-cede-al-mes-de-octubre\/\" \/>\n<meta property=\"og:site_name\" content=\"Mundoagropecuario\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mundo.agropecuario.3\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-21T16:11:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-04T19:39:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/08\/vaca-y-leche-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"391\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mundo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MundoAgropecuar\" \/>\n<meta name=\"twitter:site\" content=\"@MundoAgropecuar\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mundo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/caida-en-recepcion-nacional-de-leche-cruda-no-cede-al-mes-de-octubre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/caida-en-recepcion-nacional-de-leche-cruda-no-cede-al-mes-de-octubre\\\/\"},\"author\":{\"name\":\"mundo\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/person\\\/4e9f74a82a7dac260eb1c44b7eebeb18\"},\"headline\":\"Ca\u00edda en recepci\u00f3n nacional de leche cruda no cede al mes de octubre\",\"datePublished\":\"2023-12-21T16:11:59+00:00\",\"dateModified\":\"2024-01-04T19:39:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/caida-en-recepcion-nacional-de-leche-cruda-no-cede-al-mes-de-octubre\\\/\"},\"wordCount\":755,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/caida-en-recepcion-nacional-de-leche-cruda-no-cede-al-mes-de-octubre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/vaca-y-leche-1-scaled.jpg\",\"keywords\":[\"Agricultura\",\"Agro\",\"Fedeleche\",\"Leche\",\"Leche cruda\",\"Odepa\",\"Recepci\u00f3n nacional de leche cruda\"],\"articleSection\":[\"L\u00e1cteos\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/caida-en-recepcion-nacional-de-leche-cruda-no-cede-al-mes-de-octubre\\\/\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/caida-en-recepcion-nacional-de-leche-cruda-no-cede-al-mes-de-octubre\\\/\",\"name\":\"Ca\u00edda en recepci\u00f3n nacional de leche cruda no cede al mes de octubre - Mundoagropecuario\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/caida-en-recepcion-nacional-de-leche-cruda-no-cede-al-mes-de-octubre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/caida-en-recepcion-nacional-de-leche-cruda-no-cede-al-mes-de-octubre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/vaca-y-leche-1-scaled.jpg\",\"datePublished\":\"2023-12-21T16:11:59+00:00\",\"dateModified\":\"2024-01-04T19:39:47+00:00\",\"description\":\"En base a los antecedentes de Odepa, la recepci\u00f3n nacional de leche cruda al mes de octubre de 2023, mantiene una ca\u00edda de un 3,7%.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/caida-en-recepcion-nacional-de-leche-cruda-no-cede-al-mes-de-octubre\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/caida-en-recepcion-nacional-de-leche-cruda-no-cede-al-mes-de-octubre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/caida-en-recepcion-nacional-de-leche-cruda-no-cede-al-mes-de-octubre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/vaca-y-leche-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/vaca-y-leche-1-scaled.jpg\",\"width\":720,\"height\":391},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/caida-en-recepcion-nacional-de-leche-cruda-no-cede-al-mes-de-octubre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ca\u00edda en recepci\u00f3n nacional de leche cruda no cede al mes de octubre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#website\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/\",\"name\":\"Mundoagropecuario\",\"description\":\"Mundo Agropecuario\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#organization\",\"name\":\"Revista de Agricultura\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/PORTAL-1-1.png\",\"contentUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/PORTAL-1-1.png\",\"width\":1026,\"height\":100,\"caption\":\"Revista de Agricultura\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mundo.agropecuario.3\",\"https:\\\/\\\/x.com\\\/MundoAgropecuar\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/mundo-agropecuario-934009201\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/person\\\/4e9f74a82a7dac260eb1c44b7eebeb18\",\"name\":\"mundo\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/author\\\/mundo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ca\u00edda en recepci\u00f3n nacional de leche cruda no cede al mes de octubre - Mundoagropecuario","description":"En base a los antecedentes de Odepa, la recepci\u00f3n nacional de leche cruda al mes de octubre de 2023, mantiene una ca\u00edda de un 3,7%.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mundoagropecuario.cl\/new\/caida-en-recepcion-nacional-de-leche-cruda-no-cede-al-mes-de-octubre\/","og_locale":"es_ES","og_type":"article","og_title":"Ca\u00edda en recepci\u00f3n nacional de leche cruda no cede al mes de octubre - Mundoagropecuario","og_description":"En base a los antecedentes de Odepa, la recepci\u00f3n nacional de leche cruda al mes de octubre de 2023, mantiene una ca\u00edda de un 3,7%.","og_url":"https:\/\/www.mundoagropecuario.cl\/new\/caida-en-recepcion-nacional-de-leche-cruda-no-cede-al-mes-de-octubre\/","og_site_name":"Mundoagropecuario","article_publisher":"https:\/\/www.facebook.com\/mundo.agropecuario.3","article_published_time":"2023-12-21T16:11:59+00:00","article_modified_time":"2024-01-04T19:39:47+00:00","og_image":[{"width":720,"height":391,"url":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/08\/vaca-y-leche-1-scaled.jpg","type":"image\/jpeg"}],"author":"mundo","twitter_card":"summary_large_image","twitter_creator":"@MundoAgropecuar","twitter_site":"@MundoAgropecuar","twitter_misc":{"Escrito por":"mundo","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mundoagropecuario.cl\/new\/caida-en-recepcion-nacional-de-leche-cruda-no-cede-al-mes-de-octubre\/#article","isPartOf":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/caida-en-recepcion-nacional-de-leche-cruda-no-cede-al-mes-de-octubre\/"},"author":{"name":"mundo","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/person\/4e9f74a82a7dac260eb1c44b7eebeb18"},"headline":"Ca\u00edda en recepci\u00f3n nacional de leche cruda no cede al mes de octubre","datePublished":"2023-12-21T16:11:59+00:00","dateModified":"2024-01-04T19:39:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/caida-en-recepcion-nacional-de-leche-cruda-no-cede-al-mes-de-octubre\/"},"wordCount":755,"publisher":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#organization"},"image":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/caida-en-recepcion-nacional-de-leche-cruda-no-cede-al-mes-de-octubre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/08\/vaca-y-leche-1-scaled.jpg","keywords":["Agricultura","Agro","Fedeleche","Leche","Leche cruda","Odepa","Recepci\u00f3n nacional de leche cruda"],"articleSection":["L\u00e1cteos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.mundoagropecuario.cl\/new\/caida-en-recepcion-nacional-de-leche-cruda-no-cede-al-mes-de-octubre\/","url":"https:\/\/www.mundoagropecuario.cl\/new\/caida-en-recepcion-nacional-de-leche-cruda-no-cede-al-mes-de-octubre\/","name":"Ca\u00edda en recepci\u00f3n nacional de leche cruda no cede al mes de octubre - Mundoagropecuario","isPartOf":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/caida-en-recepcion-nacional-de-leche-cruda-no-cede-al-mes-de-octubre\/#primaryimage"},"image":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/caida-en-recepcion-nacional-de-leche-cruda-no-cede-al-mes-de-octubre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/08\/vaca-y-leche-1-scaled.jpg","datePublished":"2023-12-21T16:11:59+00:00","dateModified":"2024-01-04T19:39:47+00:00","description":"En base a los antecedentes de Odepa, la recepci\u00f3n nacional de leche cruda al mes de octubre de 2023, mantiene una ca\u00edda de un 3,7%.","breadcrumb":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/caida-en-recepcion-nacional-de-leche-cruda-no-cede-al-mes-de-octubre\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mundoagropecuario.cl\/new\/caida-en-recepcion-nacional-de-leche-cruda-no-cede-al-mes-de-octubre\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoagropecuario.cl\/new\/caida-en-recepcion-nacional-de-leche-cruda-no-cede-al-mes-de-octubre\/#primaryimage","url":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/08\/vaca-y-leche-1-scaled.jpg","contentUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/08\/vaca-y-leche-1-scaled.jpg","width":720,"height":391},{"@type":"BreadcrumbList","@id":"https:\/\/www.mundoagropecuario.cl\/new\/caida-en-recepcion-nacional-de-leche-cruda-no-cede-al-mes-de-octubre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.mundoagropecuario.cl\/new\/"},{"@type":"ListItem","position":2,"name":"Ca\u00edda en recepci\u00f3n nacional de leche cruda no cede al mes de octubre"}]},{"@type":"WebSite","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#website","url":"https:\/\/www.mundoagropecuario.cl\/new\/","name":"Mundoagropecuario","description":"Mundo Agropecuario","publisher":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mundoagropecuario.cl\/new\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#organization","name":"Revista de Agricultura","url":"https:\/\/www.mundoagropecuario.cl\/new\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/logo\/image\/","url":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/11\/PORTAL-1-1.png","contentUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/11\/PORTAL-1-1.png","width":1026,"height":100,"caption":"Revista de Agricultura"},"image":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mundo.agropecuario.3","https:\/\/x.com\/MundoAgropecuar","https:\/\/www.linkedin.com\/in\/mundo-agropecuario-934009201\/"]},{"@type":"Person","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/person\/4e9f74a82a7dac260eb1c44b7eebeb18","name":"mundo","url":"https:\/\/www.mundoagropecuario.cl\/new\/author\/mundo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts\/24996","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/comments?post=24996"}],"version-history":[{"count":3,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts\/24996\/revisions"}],"predecessor-version":[{"id":25000,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts\/24996\/revisions\/25000"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/media\/24618"}],"wp:attachment":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/media?parent=24996"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/categories?post=24996"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/tags?post=24996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}