{"id":24841,"date":"2023-11-14T12:15:04","date_gmt":"2023-11-14T15:15:04","guid":{"rendered":"https:\/\/www.mundoagropecuario.cl\/new\/?p=24841"},"modified":"2023-11-20T11:55:07","modified_gmt":"2023-11-20T14:55:07","slug":"la-razon-por-la-que-la-tecnologia-uht-es-vital-para-la-industria-lactea","status":"publish","type":"post","link":"https:\/\/www.mundoagropecuario.cl\/new\/la-razon-por-la-que-la-tecnologia-uht-es-vital-para-la-industria-lactea\/","title":{"rendered":"La raz\u00f3n por la que la tecnolog\u00eda UHT es vital para la industria l\u00e1ctea"},"content":{"rendered":"<p>Los productos l\u00e1cteos, como la leche, el yogur y el queso son alimentos de alta densidad nutricional gracias a sus aportes en prote\u00ednas y vitaminas. Esta raz\u00f3n hace que su consumo sea cada vez m\u00e1s alto. Por ejemplo, el consumo medio per c\u00e1pita calculado de productos l\u00e1cteos fue de 118,2 kg en 2021, seg\u00fan datos de Consorcio Lechero.<\/p>\n<p>Esto significa un alto nivel de producci\u00f3n y de tecnolog\u00eda que permita a los productos l\u00e1cteos conservar sus propiedades. Para eso, deben ser sometidos a tratamientos eficientes que sean capaces de garantizar su seguridad alimentaria, prolongar su vida \u00fatil, eliminar pat\u00f3genos, preservar nutrientes y proporcionar un producto final de alta calidad y sabor.<\/p>\n<p><a href=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/11\/People_men-working-production-machine_2020-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-24842 alignright\" src=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/11\/People_men-working-production-machine_2020-scaled.jpg\" alt=\"\" width=\"654\" height=\"356\" srcset=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/11\/People_men-working-production-machine_2020-scaled.jpg 720w, https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/11\/People_men-working-production-machine_2020-244x133.jpg 244w, https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/11\/People_men-working-production-machine_2020-735x400.jpg 735w\" sizes=\"auto, (max-width: 654px) 100vw, 654px\" \/><\/a>Teniendo esto en cuenta, el tratamiento a altas temperaturas (UHT) ha demostrado ser un pilar esencial en la producci\u00f3n de productos l\u00e1cteos seguros y de calidad. Este proceso consiste en calentar el producto a m\u00e1s de 135\u00b0C, lo que resulta en la destrucci\u00f3n de todos los microorganismos, garantizando que el producto final sea, adem\u00e1s, apto para una distribuci\u00f3n responsable con el medio ambiente.<\/p>\n<p>Esta tecnolog\u00eda se aplica a una amplia gama de productos, como la leche UHT, leches saborizadas, cremas UHT, y otras alternativas a los productos l\u00e1cteos. Adem\u00e1s, este m\u00e9todo se utiliza para esterilizar alimentos preparados, como sopas, salsas, postres, preparaciones a base de tomate y frutas, y alimentos para beb\u00e9s.<\/p>\n<p>En el tratamiento a temperaturas ultra-altas (UHT), el objetivo es maximizar la destrucci\u00f3n de microorganismos mientras se minimizan los cambios qu\u00edmicos en el producto. Esto implica encontrar la combinaci\u00f3n \u00f3ptima de temperatura y tiempo de procesamiento para diferentes tipos de alimentos.<\/p>\n<p>Para esto Tetra Pak, l\u00edder en la industria de procesamiento y envasado de alimentos, ofrece dos m\u00e9todos alternativos de tratamiento UHT: el directo y el indirecto. En el proceso directo, el vapor se inyecta brevemente en el producto para luego seguirle un enfriamiento instant\u00e1neo. El poco tiempo que dura el proceso permite lograr una muy buena calidad del producto.<\/p>\n<p>El m\u00e9todo indirecto, por otro lado, permite que el producto tome la temperatura adecuada mediante intercambiadores de calor, sin entrar en contacto directo con la fuente cal\u00f3rica. La alta rentabilidad de este m\u00e9todo radica en la eficiente recuperaci\u00f3n de la energ\u00eda t\u00e9rmica.<\/p>\n<p><strong>Incidencia en la huella de carbono<\/strong><\/p>\n<p><a href=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/11\/Tetra-Pak-la\u0301cteo-scaled.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-24844 \" src=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/11\/Tetra-Pak-la\u0301cteo-scaled.jpeg\" alt=\"\" width=\"595\" height=\"333\" srcset=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/11\/Tetra-Pak-la\u0301cteo-scaled.jpeg 715w, https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/11\/Tetra-Pak-la\u0301cteo-238x133.jpeg 238w\" sizes=\"auto, (max-width: 595px) 100vw, 595px\" \/><\/a>Otro dato que suma la tecnolog\u00eda UHT es c\u00f3mo esta puede ayudar a reducir el impacto ambiental, considerando que genera un menor consumo de energ\u00eda al no ser necesario el almacenamiento y la distribuci\u00f3n con cadena de fr\u00edo, incidiendo directamente en una menor huella de carbono.<\/p>\n<p>Adem\u00e1s, la capacidad del m\u00e9todo de ser energ\u00e9ticamente eficiente tambi\u00e9n contribuye a reducir el desperdicio de alimentos, ya que los productos tienen mayor tiempo de duraci\u00f3n y, en consecuencia, se reducen las devoluciones y reclamos por productos en mal estado.<\/p>\n<p>La tecnolog\u00eda UHT de Tetra Pak contin\u00faa desempe\u00f1ando un papel crucial en la evoluci\u00f3n y sostenibilidad de la industria l\u00e1ctea. Esta innovaci\u00f3n asegura la seguridad y calidad de los productos l\u00e1cteos que llegan a los hogares de millones de consumidores cada d\u00eda y mejoran sus resultados operacionales y ambientales.<\/p>\n<p><strong>Acerca de Tetra Pak<\/strong><\/p>\n<p>Tetra Pak es una compa\u00f1\u00eda de origen sueco l\u00edder en el procesamiento y envasado de alimentos del mundo. Trabajamos en estrecha colaboraci\u00f3n con nuestros clientes y proveedores para ofrecer productos seguros, innovadores y responsables medioambientalmente que cada d\u00eda cubren las necesidades de cientos de millones de personas en m\u00e1s de 170 pa\u00edses de todo el mundo.<\/p>\n<p>Con 25.000 empleados en m\u00e1s de 85 pa\u00edses, creemos en un liderazgo industrial responsable y en un enfoque sustentable de la empresa. Nuestro lema, &#8220;PROTEGE LO BUENO &#x2122;&#8221;, refleja nuestra visi\u00f3n de producir alimentos seguros y disponibles en todas partes. M\u00e1s informaci\u00f3n en: www.tetrapak.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta tecnolog\u00eda se aplica a una amplia gama de productos, como la leche UHT, leches saborizadas, cremas UHT, y otras alternativas a los productos l\u00e1cteos.<\/p>\n","protected":false},"author":2,"featured_media":24843,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1946],"tags":[1957,8491,2068,8490,8492,8489,7811],"class_list":["post-24841","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lacteos","tag-consorcio-lechero","tag-cremas-uht","tag-industria-lactea","tag-leches-saborizadas","tag-sostenibilidad-de-la-industria-lactea","tag-tecnologia-uht","tag-tetrapak"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La raz\u00f3n por la que la tecnolog\u00eda UHT es vital para la industria l\u00e1ctea - Mundoagropecuario<\/title>\n<meta name=\"description\" content=\"Esta tecnolog\u00eda se aplica a una amplia gama de productos, como la leche UHT, leches saborizadas, cremas UHT, y otros productos l\u00e1cteos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mundoagropecuario.cl\/new\/la-razon-por-la-que-la-tecnologia-uht-es-vital-para-la-industria-lactea\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La raz\u00f3n por la que la tecnolog\u00eda UHT es vital para la industria l\u00e1ctea - Mundoagropecuario\" \/>\n<meta property=\"og:description\" content=\"Esta tecnolog\u00eda se aplica a una amplia gama de productos, como la leche UHT, leches saborizadas, cremas UHT, y otros productos l\u00e1cteos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mundoagropecuario.cl\/new\/la-razon-por-la-que-la-tecnologia-uht-es-vital-para-la-industria-lactea\/\" \/>\n<meta property=\"og:site_name\" content=\"Mundoagropecuario\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mundo.agropecuario.3\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-14T15:15:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-20T14:55:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/11\/Dry-Lubrication-379-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"697\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mundo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MundoAgropecuar\" \/>\n<meta name=\"twitter:site\" content=\"@MundoAgropecuar\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mundo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/la-razon-por-la-que-la-tecnologia-uht-es-vital-para-la-industria-lactea\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/la-razon-por-la-que-la-tecnologia-uht-es-vital-para-la-industria-lactea\\\/\"},\"author\":{\"name\":\"mundo\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/person\\\/4e9f74a82a7dac260eb1c44b7eebeb18\"},\"headline\":\"La raz\u00f3n por la que la tecnolog\u00eda UHT es vital para la industria l\u00e1ctea\",\"datePublished\":\"2023-11-14T15:15:04+00:00\",\"dateModified\":\"2023-11-20T14:55:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/la-razon-por-la-que-la-tecnologia-uht-es-vital-para-la-industria-lactea\\\/\"},\"wordCount\":687,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/la-razon-por-la-que-la-tecnologia-uht-es-vital-para-la-industria-lactea\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Dry-Lubrication-379-scaled.jpg\",\"keywords\":[\"Consorcio Lechero\",\"cremas UHT\",\"Industria l\u00e1ctea\",\"leches saborizadas\",\"sostenibilidad de la industria l\u00e1ctea.\",\"tecnolog\u00eda UHT\",\"tetrapak\"],\"articleSection\":[\"L\u00e1cteos\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/la-razon-por-la-que-la-tecnologia-uht-es-vital-para-la-industria-lactea\\\/\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/la-razon-por-la-que-la-tecnologia-uht-es-vital-para-la-industria-lactea\\\/\",\"name\":\"La raz\u00f3n por la que la tecnolog\u00eda UHT es vital para la industria l\u00e1ctea - Mundoagropecuario\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/la-razon-por-la-que-la-tecnologia-uht-es-vital-para-la-industria-lactea\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/la-razon-por-la-que-la-tecnologia-uht-es-vital-para-la-industria-lactea\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Dry-Lubrication-379-scaled.jpg\",\"datePublished\":\"2023-11-14T15:15:04+00:00\",\"dateModified\":\"2023-11-20T14:55:07+00:00\",\"description\":\"Esta tecnolog\u00eda se aplica a una amplia gama de productos, como la leche UHT, leches saborizadas, cremas UHT, y otros productos l\u00e1cteos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/la-razon-por-la-que-la-tecnologia-uht-es-vital-para-la-industria-lactea\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/la-razon-por-la-que-la-tecnologia-uht-es-vital-para-la-industria-lactea\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/la-razon-por-la-que-la-tecnologia-uht-es-vital-para-la-industria-lactea\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Dry-Lubrication-379-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Dry-Lubrication-379-scaled.jpg\",\"width\":697,\"height\":400,\"caption\":\"Dry Lubrication image, within Tetra Pak Consumables service category\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/la-razon-por-la-que-la-tecnologia-uht-es-vital-para-la-industria-lactea\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La raz\u00f3n por la que la tecnolog\u00eda UHT es vital para la industria l\u00e1ctea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#website\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/\",\"name\":\"Mundoagropecuario\",\"description\":\"Mundo Agropecuario\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#organization\",\"name\":\"Revista de Agricultura\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/PORTAL-1-1.png\",\"contentUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/PORTAL-1-1.png\",\"width\":1026,\"height\":100,\"caption\":\"Revista de Agricultura\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mundo.agropecuario.3\",\"https:\\\/\\\/x.com\\\/MundoAgropecuar\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/mundo-agropecuario-934009201\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/person\\\/4e9f74a82a7dac260eb1c44b7eebeb18\",\"name\":\"mundo\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/author\\\/mundo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La raz\u00f3n por la que la tecnolog\u00eda UHT es vital para la industria l\u00e1ctea - Mundoagropecuario","description":"Esta tecnolog\u00eda se aplica a una amplia gama de productos, como la leche UHT, leches saborizadas, cremas UHT, y otros productos l\u00e1cteos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mundoagropecuario.cl\/new\/la-razon-por-la-que-la-tecnologia-uht-es-vital-para-la-industria-lactea\/","og_locale":"es_ES","og_type":"article","og_title":"La raz\u00f3n por la que la tecnolog\u00eda UHT es vital para la industria l\u00e1ctea - Mundoagropecuario","og_description":"Esta tecnolog\u00eda se aplica a una amplia gama de productos, como la leche UHT, leches saborizadas, cremas UHT, y otros productos l\u00e1cteos.","og_url":"https:\/\/www.mundoagropecuario.cl\/new\/la-razon-por-la-que-la-tecnologia-uht-es-vital-para-la-industria-lactea\/","og_site_name":"Mundoagropecuario","article_publisher":"https:\/\/www.facebook.com\/mundo.agropecuario.3","article_published_time":"2023-11-14T15:15:04+00:00","article_modified_time":"2023-11-20T14:55:07+00:00","og_image":[{"width":697,"height":400,"url":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/11\/Dry-Lubrication-379-scaled.jpg","type":"image\/jpeg"}],"author":"mundo","twitter_card":"summary_large_image","twitter_creator":"@MundoAgropecuar","twitter_site":"@MundoAgropecuar","twitter_misc":{"Escrito por":"mundo","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mundoagropecuario.cl\/new\/la-razon-por-la-que-la-tecnologia-uht-es-vital-para-la-industria-lactea\/#article","isPartOf":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/la-razon-por-la-que-la-tecnologia-uht-es-vital-para-la-industria-lactea\/"},"author":{"name":"mundo","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/person\/4e9f74a82a7dac260eb1c44b7eebeb18"},"headline":"La raz\u00f3n por la que la tecnolog\u00eda UHT es vital para la industria l\u00e1ctea","datePublished":"2023-11-14T15:15:04+00:00","dateModified":"2023-11-20T14:55:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/la-razon-por-la-que-la-tecnologia-uht-es-vital-para-la-industria-lactea\/"},"wordCount":687,"publisher":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#organization"},"image":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/la-razon-por-la-que-la-tecnologia-uht-es-vital-para-la-industria-lactea\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/11\/Dry-Lubrication-379-scaled.jpg","keywords":["Consorcio Lechero","cremas UHT","Industria l\u00e1ctea","leches saborizadas","sostenibilidad de la industria l\u00e1ctea.","tecnolog\u00eda UHT","tetrapak"],"articleSection":["L\u00e1cteos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.mundoagropecuario.cl\/new\/la-razon-por-la-que-la-tecnologia-uht-es-vital-para-la-industria-lactea\/","url":"https:\/\/www.mundoagropecuario.cl\/new\/la-razon-por-la-que-la-tecnologia-uht-es-vital-para-la-industria-lactea\/","name":"La raz\u00f3n por la que la tecnolog\u00eda UHT es vital para la industria l\u00e1ctea - Mundoagropecuario","isPartOf":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/la-razon-por-la-que-la-tecnologia-uht-es-vital-para-la-industria-lactea\/#primaryimage"},"image":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/la-razon-por-la-que-la-tecnologia-uht-es-vital-para-la-industria-lactea\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/11\/Dry-Lubrication-379-scaled.jpg","datePublished":"2023-11-14T15:15:04+00:00","dateModified":"2023-11-20T14:55:07+00:00","description":"Esta tecnolog\u00eda se aplica a una amplia gama de productos, como la leche UHT, leches saborizadas, cremas UHT, y otros productos l\u00e1cteos.","breadcrumb":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/la-razon-por-la-que-la-tecnologia-uht-es-vital-para-la-industria-lactea\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mundoagropecuario.cl\/new\/la-razon-por-la-que-la-tecnologia-uht-es-vital-para-la-industria-lactea\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoagropecuario.cl\/new\/la-razon-por-la-que-la-tecnologia-uht-es-vital-para-la-industria-lactea\/#primaryimage","url":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/11\/Dry-Lubrication-379-scaled.jpg","contentUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/11\/Dry-Lubrication-379-scaled.jpg","width":697,"height":400,"caption":"Dry Lubrication image, within Tetra Pak Consumables service category"},{"@type":"BreadcrumbList","@id":"https:\/\/www.mundoagropecuario.cl\/new\/la-razon-por-la-que-la-tecnologia-uht-es-vital-para-la-industria-lactea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.mundoagropecuario.cl\/new\/"},{"@type":"ListItem","position":2,"name":"La raz\u00f3n por la que la tecnolog\u00eda UHT es vital para la industria l\u00e1ctea"}]},{"@type":"WebSite","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#website","url":"https:\/\/www.mundoagropecuario.cl\/new\/","name":"Mundoagropecuario","description":"Mundo Agropecuario","publisher":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mundoagropecuario.cl\/new\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#organization","name":"Revista de Agricultura","url":"https:\/\/www.mundoagropecuario.cl\/new\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/logo\/image\/","url":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/11\/PORTAL-1-1.png","contentUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/11\/PORTAL-1-1.png","width":1026,"height":100,"caption":"Revista de Agricultura"},"image":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mundo.agropecuario.3","https:\/\/x.com\/MundoAgropecuar","https:\/\/www.linkedin.com\/in\/mundo-agropecuario-934009201\/"]},{"@type":"Person","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/person\/4e9f74a82a7dac260eb1c44b7eebeb18","name":"mundo","url":"https:\/\/www.mundoagropecuario.cl\/new\/author\/mundo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts\/24841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/comments?post=24841"}],"version-history":[{"count":1,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts\/24841\/revisions"}],"predecessor-version":[{"id":24845,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts\/24841\/revisions\/24845"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/media\/24843"}],"wp:attachment":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/media?parent=24841"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/categories?post=24841"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/tags?post=24841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}