{"id":24825,"date":"2023-11-08T13:35:41","date_gmt":"2023-11-08T16:35:41","guid":{"rendered":"https:\/\/www.mundoagropecuario.cl\/new\/?p=24825"},"modified":"2023-11-15T13:51:37","modified_gmt":"2023-11-15T16:51:37","slug":"exportaciones-de-lacteos-acumulan-baja-de-135-al-tercer-trintres-del-ano","status":"publish","type":"post","link":"https:\/\/www.mundoagropecuario.cl\/new\/exportaciones-de-lacteos-acumulan-baja-de-135-al-tercer-trintres-del-ano\/","title":{"rendered":"Exportaciones de l\u00e1cteos acumulan baja de 13,5% al tercer trintres del a\u00f1o"},"content":{"rendered":"<p>De acuerdo a los datos del Bolet\u00edn de Avance de Comercio Exterior de Productos L\u00e1cteos elaborado por la Oficina de Estudios y Pol\u00edticas Agrarias -Odepa-, y reproducidos por la Federaci\u00f3n Nacional de Productores de Leche (Fedeleche), las exportaciones de productos l\u00e1cteos al tercer trimestre del a\u00f1o suman un total de US$ 174,1 millones. Lo anterior, supone una ca\u00edda de 13,5% frente al mismo periodo de 2022 y una disminuci\u00f3n interanual de US$ 27,2 millones. La ca\u00edda en las exportaciones de los grandes &#8216;players&#8217; del sector explicar\u00edan este escenario.<\/p>\n<p>En tanto, en el mes de septiembre de 2023, las exportaciones del sector siguen el mismo comportamiento y muestran una ca\u00edda de 27,7% respecto del a\u00f1o anterior, llegando a US$ 14,5 millones, mientras en volumen bajaron un 29,3% hasta sumar 5.071 toneladas.<\/p>\n<p>El precio promedio de las exportaciones l\u00e1cteas cerr\u00f3 en septiembre en US$ 2.860 por toneladas lo que representa un alza de 2,14% respecto de 2022.<\/p>\n<p><strong>Desempe\u00f1o &#8220;TOP 5&#8221;<\/strong><\/p>\n<p><a href=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/08\/primer-plano-leche-organica-queso-gourmet-1-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-24611 size-full alignright\" src=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/08\/primer-plano-leche-organica-queso-gourmet-1-scaled.jpg\" alt=\"\" width=\"600\" height=\"400\" srcset=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/08\/primer-plano-leche-organica-queso-gourmet-1-scaled.jpg 600w, https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/08\/primer-plano-leche-organica-queso-gourmet-1-200x133.jpg 200w, https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/08\/primer-plano-leche-organica-queso-gourmet-1-768x512.jpg 768w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a>En cuanto a los principales pa\u00edses de destino se aprecia una canasta diversificada al noveno mes del a\u00f1o con Estados Unidos manteni\u00e9ndose en el primer lugar con una participaci\u00f3n sobre el total de 23,3%. Lo anterior, supone embarques por US$ 40,6 millones, lo que representa una variaci\u00f3n de 0,05% respecto de 2022 y en valor US$ 224 mil.<\/p>\n<p>Los env\u00edos a Emiratos \u00c1rabes Unidos se ubican en el segundo lugar concentrando un 16,9% sobre el total, valoriz\u00e1ndose en US$ 29,5 millones, lo que se traduce en un alza de 22,8% y US$ 6,0 millones adicionales.<\/p>\n<p>Con una participaci\u00f3n que alcanza un 11,4%, M\u00e9xico se mantiene en el tercer sitial, con una comparaci\u00f3n anual que presenta una ca\u00edda de 13,0% frente a 2022, facturando en total US$ 19,9 millones, valor que representa un retroceso de US$ 2,9 millones.<\/p>\n<p>Per\u00fa se mantiene en la cuarta ubicaci\u00f3n, alcanzando una participaci\u00f3n del sobre del 8,3%, pese al retroceso de un 15,6% en comparaci\u00f3n con el a\u00f1o pasado. As\u00ed, a la fecha, acumula un total por US$ 14,5 millones frente al a\u00f1o anterior, con una diferencia de US$ 2,7 millones.<\/p>\n<p>Por su parte, las exportaciones de productos l\u00e1cteos a Colombia siguen en el quinto lugar con una participaci\u00f3n de 6,9% sobre el total, cayendo un 6,5% frente al a\u00f1o anterior y un valor total de US$ 11,3 millones, siendo una ca\u00edda de US$ 22,2 millones.<\/p>\n<p>Estos cinco destinos se mantienen concentrando un 66,5% sobre el total.<\/p>\n<p><strong>Desempe\u00f1o por producto<\/strong><\/p>\n<p>La leche condesa lidera las exportaciones de l\u00e1cteos al mes de septiembre, representando en valor un 25,8% sobre el total.\u00a0 No obstante, los embarques de esta categor\u00eda cayeron un 2,65% frente al mismo lapso de 2022, sumando un total de US$ 44,9 millones. Mientras en volumen los env\u00edos alcanzaron 23.792 toneladas, lo que supone una ca\u00edda de 19,53% respecto a igual lapso de 2022.<\/p>\n<p>En el segundo lugar se situaron las dem\u00e1s preparaciones en base a productos l\u00e1cteos alcanzando un monto total por US$ 33,5 millones, lo que supone un alza interanual de 24,4%. En volumen, las exportaciones sumaron 7.557 toneladas, lo cual representa una variaci\u00f3n de 0,23% por arriba del a\u00f1o previo.<\/p>\n<p>Los quesos son el tercer producto m\u00e1s exportado por nuestro pa\u00eds con env\u00edos que sumaron US$ 23,6 millones, un 13,5% sobre el total, y lo que representa a su vez un retroceso de 14,97% respecto al mismo lapso del a\u00f1o previo. En volumen suman 4.983 toneladas, una baja de 15,62% frente al a\u00f1o 2022.<\/p>\n<p>Los env\u00edos de preparaciones infantiles escalaron al cuarto lugar, representando un 10,0% sobre el total y gracias a que subi\u00f3 un 0,38% hasta alcanzar US$17,4 millones, aunque en volumen present\u00f3 una baja de 16,54% respecto de 2022 hasta sumar 3.548 toneladas<\/p>\n<p>Finalmente, las exportaciones de sueros que suponen un 7,8% del valor total exportado, presentan una ca\u00edda de 27,9% sumando un monto por US$ 13,6 millones, mientras en volumen bajaron un 4,7% hasta 12.520 toneladas.<\/p>\n<p>Fuente: Comunicaciones Fedeleche FG \/\u00a0 Odepa<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cabe se\u00f1alar que, en t\u00e9rminos de volumen, los embarques l\u00e1cteos cerraron al mes de septiembre con una disminuci\u00f3n de 16,0% frente al a\u00f1o anterior. hasta alcanzar 54.668 toneladas, con 11.387 toneladas menos.\u00a0<\/p>\n","protected":false},"author":2,"featured_media":24636,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1946],"tags":[2090,3127,1105,7469,2058,2141,2051,5002,5790],"class_list":["post-24825","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lacteos","tag-agricultura","tag-agro","tag-exportaciones","tag-exportaciones-de-lacteos","tag-fedeleche","tag-lacteos","tag-leche","tag-productores","tag-productos-lacteos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Exportaciones de l\u00e1cteos acumulan baja de 13,5% al tercer trintres del a\u00f1o - Mundoagropecuario<\/title>\n<meta name=\"description\" content=\"Cabe se\u00f1alar que, en t\u00e9rminos de volumen, los embarques l\u00e1cteos cerraron al mes de septiembre con una disminuci\u00f3n de 16,0%.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mundoagropecuario.cl\/new\/exportaciones-de-lacteos-acumulan-baja-de-135-al-tercer-trintres-del-ano\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exportaciones de l\u00e1cteos acumulan baja de 13,5% al tercer trintres del a\u00f1o - Mundoagropecuario\" \/>\n<meta property=\"og:description\" content=\"Cabe se\u00f1alar que, en t\u00e9rminos de volumen, los embarques l\u00e1cteos cerraron al mes de septiembre con una disminuci\u00f3n de 16,0%.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mundoagropecuario.cl\/new\/exportaciones-de-lacteos-acumulan-baja-de-135-al-tercer-trintres-del-ano\/\" \/>\n<meta property=\"og:site_name\" content=\"Mundoagropecuario\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mundo.agropecuario.3\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-08T16:35:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-15T16:51:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/09\/Leche-exportaciones2-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"388\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mundo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MundoAgropecuar\" \/>\n<meta name=\"twitter:site\" content=\"@MundoAgropecuar\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mundo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/exportaciones-de-lacteos-acumulan-baja-de-135-al-tercer-trintres-del-ano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/exportaciones-de-lacteos-acumulan-baja-de-135-al-tercer-trintres-del-ano\\\/\"},\"author\":{\"name\":\"mundo\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/person\\\/4e9f74a82a7dac260eb1c44b7eebeb18\"},\"headline\":\"Exportaciones de l\u00e1cteos acumulan baja de 13,5% al tercer trintres del a\u00f1o\",\"datePublished\":\"2023-11-08T16:35:41+00:00\",\"dateModified\":\"2023-11-15T16:51:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/exportaciones-de-lacteos-acumulan-baja-de-135-al-tercer-trintres-del-ano\\\/\"},\"wordCount\":649,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/exportaciones-de-lacteos-acumulan-baja-de-135-al-tercer-trintres-del-ano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Leche-exportaciones2-scaled.jpeg\",\"keywords\":[\"Agricultura\",\"Agro\",\"Exportaciones\",\"Exportaciones de l\u00e1cteos\",\"Fedeleche\",\"L\u00e1cteos\",\"Leche\",\"productores\",\"productos l\u00e1cteos\"],\"articleSection\":[\"L\u00e1cteos\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/exportaciones-de-lacteos-acumulan-baja-de-135-al-tercer-trintres-del-ano\\\/\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/exportaciones-de-lacteos-acumulan-baja-de-135-al-tercer-trintres-del-ano\\\/\",\"name\":\"Exportaciones de l\u00e1cteos acumulan baja de 13,5% al tercer trintres del a\u00f1o - Mundoagropecuario\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/exportaciones-de-lacteos-acumulan-baja-de-135-al-tercer-trintres-del-ano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/exportaciones-de-lacteos-acumulan-baja-de-135-al-tercer-trintres-del-ano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Leche-exportaciones2-scaled.jpeg\",\"datePublished\":\"2023-11-08T16:35:41+00:00\",\"dateModified\":\"2023-11-15T16:51:37+00:00\",\"description\":\"Cabe se\u00f1alar que, en t\u00e9rminos de volumen, los embarques l\u00e1cteos cerraron al mes de septiembre con una disminuci\u00f3n de 16,0%.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/exportaciones-de-lacteos-acumulan-baja-de-135-al-tercer-trintres-del-ano\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/exportaciones-de-lacteos-acumulan-baja-de-135-al-tercer-trintres-del-ano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/exportaciones-de-lacteos-acumulan-baja-de-135-al-tercer-trintres-del-ano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Leche-exportaciones2-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Leche-exportaciones2-scaled.jpeg\",\"width\":720,\"height\":388},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/exportaciones-de-lacteos-acumulan-baja-de-135-al-tercer-trintres-del-ano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Exportaciones de l\u00e1cteos acumulan baja de 13,5% al tercer trintres del a\u00f1o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#website\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/\",\"name\":\"Mundoagropecuario\",\"description\":\"Mundo Agropecuario\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#organization\",\"name\":\"Revista de Agricultura\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/PORTAL-1-1.png\",\"contentUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/PORTAL-1-1.png\",\"width\":1026,\"height\":100,\"caption\":\"Revista de Agricultura\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mundo.agropecuario.3\",\"https:\\\/\\\/x.com\\\/MundoAgropecuar\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/mundo-agropecuario-934009201\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/person\\\/4e9f74a82a7dac260eb1c44b7eebeb18\",\"name\":\"mundo\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/author\\\/mundo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exportaciones de l\u00e1cteos acumulan baja de 13,5% al tercer trintres del a\u00f1o - Mundoagropecuario","description":"Cabe se\u00f1alar que, en t\u00e9rminos de volumen, los embarques l\u00e1cteos cerraron al mes de septiembre con una disminuci\u00f3n de 16,0%.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mundoagropecuario.cl\/new\/exportaciones-de-lacteos-acumulan-baja-de-135-al-tercer-trintres-del-ano\/","og_locale":"es_ES","og_type":"article","og_title":"Exportaciones de l\u00e1cteos acumulan baja de 13,5% al tercer trintres del a\u00f1o - Mundoagropecuario","og_description":"Cabe se\u00f1alar que, en t\u00e9rminos de volumen, los embarques l\u00e1cteos cerraron al mes de septiembre con una disminuci\u00f3n de 16,0%.","og_url":"https:\/\/www.mundoagropecuario.cl\/new\/exportaciones-de-lacteos-acumulan-baja-de-135-al-tercer-trintres-del-ano\/","og_site_name":"Mundoagropecuario","article_publisher":"https:\/\/www.facebook.com\/mundo.agropecuario.3","article_published_time":"2023-11-08T16:35:41+00:00","article_modified_time":"2023-11-15T16:51:37+00:00","og_image":[{"width":720,"height":388,"url":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/09\/Leche-exportaciones2-scaled.jpeg","type":"image\/jpeg"}],"author":"mundo","twitter_card":"summary_large_image","twitter_creator":"@MundoAgropecuar","twitter_site":"@MundoAgropecuar","twitter_misc":{"Escrito por":"mundo","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mundoagropecuario.cl\/new\/exportaciones-de-lacteos-acumulan-baja-de-135-al-tercer-trintres-del-ano\/#article","isPartOf":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/exportaciones-de-lacteos-acumulan-baja-de-135-al-tercer-trintres-del-ano\/"},"author":{"name":"mundo","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/person\/4e9f74a82a7dac260eb1c44b7eebeb18"},"headline":"Exportaciones de l\u00e1cteos acumulan baja de 13,5% al tercer trintres del a\u00f1o","datePublished":"2023-11-08T16:35:41+00:00","dateModified":"2023-11-15T16:51:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/exportaciones-de-lacteos-acumulan-baja-de-135-al-tercer-trintres-del-ano\/"},"wordCount":649,"publisher":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#organization"},"image":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/exportaciones-de-lacteos-acumulan-baja-de-135-al-tercer-trintres-del-ano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/09\/Leche-exportaciones2-scaled.jpeg","keywords":["Agricultura","Agro","Exportaciones","Exportaciones de l\u00e1cteos","Fedeleche","L\u00e1cteos","Leche","productores","productos l\u00e1cteos"],"articleSection":["L\u00e1cteos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.mundoagropecuario.cl\/new\/exportaciones-de-lacteos-acumulan-baja-de-135-al-tercer-trintres-del-ano\/","url":"https:\/\/www.mundoagropecuario.cl\/new\/exportaciones-de-lacteos-acumulan-baja-de-135-al-tercer-trintres-del-ano\/","name":"Exportaciones de l\u00e1cteos acumulan baja de 13,5% al tercer trintres del a\u00f1o - Mundoagropecuario","isPartOf":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/exportaciones-de-lacteos-acumulan-baja-de-135-al-tercer-trintres-del-ano\/#primaryimage"},"image":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/exportaciones-de-lacteos-acumulan-baja-de-135-al-tercer-trintres-del-ano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/09\/Leche-exportaciones2-scaled.jpeg","datePublished":"2023-11-08T16:35:41+00:00","dateModified":"2023-11-15T16:51:37+00:00","description":"Cabe se\u00f1alar que, en t\u00e9rminos de volumen, los embarques l\u00e1cteos cerraron al mes de septiembre con una disminuci\u00f3n de 16,0%.","breadcrumb":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/exportaciones-de-lacteos-acumulan-baja-de-135-al-tercer-trintres-del-ano\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mundoagropecuario.cl\/new\/exportaciones-de-lacteos-acumulan-baja-de-135-al-tercer-trintres-del-ano\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoagropecuario.cl\/new\/exportaciones-de-lacteos-acumulan-baja-de-135-al-tercer-trintres-del-ano\/#primaryimage","url":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/09\/Leche-exportaciones2-scaled.jpeg","contentUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/09\/Leche-exportaciones2-scaled.jpeg","width":720,"height":388},{"@type":"BreadcrumbList","@id":"https:\/\/www.mundoagropecuario.cl\/new\/exportaciones-de-lacteos-acumulan-baja-de-135-al-tercer-trintres-del-ano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.mundoagropecuario.cl\/new\/"},{"@type":"ListItem","position":2,"name":"Exportaciones de l\u00e1cteos acumulan baja de 13,5% al tercer trintres del a\u00f1o"}]},{"@type":"WebSite","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#website","url":"https:\/\/www.mundoagropecuario.cl\/new\/","name":"Mundoagropecuario","description":"Mundo Agropecuario","publisher":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mundoagropecuario.cl\/new\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#organization","name":"Revista de Agricultura","url":"https:\/\/www.mundoagropecuario.cl\/new\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/logo\/image\/","url":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/11\/PORTAL-1-1.png","contentUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/11\/PORTAL-1-1.png","width":1026,"height":100,"caption":"Revista de Agricultura"},"image":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mundo.agropecuario.3","https:\/\/x.com\/MundoAgropecuar","https:\/\/www.linkedin.com\/in\/mundo-agropecuario-934009201\/"]},{"@type":"Person","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/person\/4e9f74a82a7dac260eb1c44b7eebeb18","name":"mundo","url":"https:\/\/www.mundoagropecuario.cl\/new\/author\/mundo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts\/24825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/comments?post=24825"}],"version-history":[{"count":1,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts\/24825\/revisions"}],"predecessor-version":[{"id":24826,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts\/24825\/revisions\/24826"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/media\/24636"}],"wp:attachment":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/media?parent=24825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/categories?post=24825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/tags?post=24825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}