{"id":24700,"date":"2023-09-25T12:35:21","date_gmt":"2023-09-25T15:35:21","guid":{"rendered":"https:\/\/www.mundoagropecuario.cl\/new\/?p=24700"},"modified":"2023-10-02T13:56:58","modified_gmt":"2023-10-02T16:56:58","slug":"arrigoni-busca-adaptacion-de-la-uva-de-vino-al-cambio-climatico","status":"publish","type":"post","link":"https:\/\/www.mundoagropecuario.cl\/new\/arrigoni-busca-adaptacion-de-la-uva-de-vino-al-cambio-climatico\/","title":{"rendered":"Arrigoni busca adaptaci\u00f3n de la uva de vino al cambio clim\u00e1tico"},"content":{"rendered":"<p>En los \u00faltimos a\u00f1os, los eventos clim\u00e1ticos extremos y las altas temperaturas, que a menudo causan perjuicios irreversibles a los cultivos, han puesto a dura prueba a todo el sector vitivin\u00edcola. En respuesta a estas dificultades, el Grupo Arrigoni se ha distinguido por su enfoque innovador ante el problema y por su importante inversi\u00f3n en investigaci\u00f3n y desarrollo, que ha permitido hallar soluciones novedosas, como las gamas Iride\u00ae y Fructus\u00ae, ya adoptadas con \u00e9xito por varias bodegas, entre las que se encuentra la empresa Terre dei Pallavicini, de Roma. Estos sistemas de protecci\u00f3n salvaguardan la vid no solo frente a aves, insectos, granizo, heladas, sol y viento, sino que tambi\u00e9n brindan un microclima y unas condiciones de crecimiento mejores. Todo ello, adem\u00e1s, contribuye activamente a determinar la futura calidad del vino.<\/p>\n<p><a href=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2018\/07\/uvas.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-7522 \" src=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2018\/07\/uvas.jpg\" alt=\"\" width=\"552\" height=\"228\" \/><\/a>Seg\u00fan un estudio realizado por el instituto nacional franc\u00e9s de investigaci\u00f3n agron\u00f3mica (INRA) y publicado en 2020 en la revista cient\u00edfica estadounidense\u202fPNAS, si en el plazo del 2050 las temperaturas medias ascendieran dos grados cent\u00edgrados m\u00e1s, \u202fel 56% de las actuales regiones vitivin\u00edcolas del mundo se ver\u00edan perjudicadas. El estudio, concretamente, se concentr\u00f3 en las variedades internacionales m\u00e1s cultivadas, entre las que se encuentran cabernet-sauvignon, merlot, chardonnay, pinot negro, riesling y syrah, que representan el 35% de las superficies vin\u00edcolas del mundo y entre el 64 y el 87% en Australia, Chile, Francia, Nueva Zelanda, Suiza y los Estados Unidos de Am\u00e9rica.<\/p>\n<p>Para Arrigoni, por tanto, surge la necesidad urgente de neutralizar los inevitables cambios que el calentamiento global del planeta est\u00e1 creando en la vid y, en consecuencia, en el vino producido. La empresa ha detectado dos grandes tipos de riesgo a este respecto. El primero est\u00e1 ligado a las fluctuaciones clim\u00e1ticas anuales, que pueden determinar vendimias con notables variaciones cuantitativas y cualitativas. El segundo tipo de riesgo, en cambio, est\u00e1 relacionado con los cambios clim\u00e1ticos en el planeta, que desencadenan un proceso de migraci\u00f3n del cultivo a \u00e1reas de producci\u00f3n no tradicionales.<\/p>\n<p>Fructus\u00ae, en particular, es la gama de coberturas antigranizo concebida por Arrigoni para los productores de uva y en general para la fruticultura, que puede contribuir de modo decisivo tanto para sortear las adversidades atmosf\u00e9ricas, como para amparar estos cultivos de otras potenciales amenazas.<\/p>\n<p>Iride\u00ae, en cambio, es la l\u00ednea que garantiza una s\u00f3lida protecci\u00f3n frente al granizo, as\u00ed como ante las aves, gracias a su red con mallas de elasticidad ligera que, por sus caracter\u00edsticas intr\u00ednsecas, se adapta a un sinf\u00edn de instalaciones.<\/p>\n<p>El testimonio directo de la eficacia de estas soluciones nos lo ofrece Giulio Senni, administrador delegado de la empresa agr\u00edcola \u201cTerre dei Pallavicini\u201d, de Colonna (Roma), una de las mayores y m\u00e1s antiguas bodegas romanas. \u201cEn nuestra empresa producimos vino desde 1670 y hoy disponemos de unas setenta hect\u00e1reas de vi\u00f1edos&#8221;, explica Senni. Cultivamos sobre todo variedades de baya blanca, como la Malvasia Puntinata, y creemos decididamente en el relanzamiento de las variedades aut\u00f3ctonas. En los \u00faltimos a\u00f1os hemos asistido a temperaturas muy elevadas, con picos devastadores para la vi\u00f1a. Esto provoca retrasos vegetativos y quemaduras. M\u00e1s a\u00fan, algunas patolog\u00edas se ven aceleradas por la crisis clim\u00e1tica y por el estr\u00e9s de las vides. Ante esta situaci\u00f3n, considero que los productos de Arrigoni, en especial Iride\u00ae y Fructus\u00ae, pueden constituir dos soluciones v\u00e1lidas tanto en el sombreado de las hileras, como en la protecci\u00f3n de la planta y de los racimos de quemaduras y del sufrimiento que las altas temperaturas prolongadas pueden generar.\u201d<\/p>\n<p>Con respecto a la investigaci\u00f3n acerca de la uva de vino, desde 2019 Arrigoni y la Universidad de Palermo vienen colaborando en un estudio, que ha llegado a su conclusi\u00f3n este a\u00f1o, para valorar las mejores soluciones antiquemaduras. A este prop\u00f3sito Rosario Di Lorenzo, profesor numerario del Departamento de ciencias agrarias, alimentarias y forestales de la Universidad de Palermo, que est\u00e1 trabajando en la investigaci\u00f3n, comenta: \u201cLas temperaturas inciden en la capacidad metab\u00f3lica de la vid e influyen, por consiguiente, en la din\u00e1mica de los procesos de crecimiento y sobre todo en los procesos de maduraci\u00f3n. Uno de los principales problemas que est\u00e1 planteando el cambio clim\u00e1tico es el denominado desacoplamiento entre los distintos par\u00e1metros cualitativos, es decir, las cualidades tecnol\u00f3gica, fen\u00f3lica y arom\u00e1tica, porque se trata de metabolitos que siguen procesos de s\u00edntesis diferentes y, por lo tanto, se ven influenciados de manera distinta por las altas temperaturas.\u201d Daniele Miccich\u00e9, estudiante de doctorado del curso Biodiversity in Agriculture and Forestry de la Universidad de Palermo, comentando los primeros resultados, a\u00f1ade: \u201cEn lo clim\u00e1tico hemos realizado evaluaciones con una c\u00e1mara t\u00e9rmica, para tomar la temperatura de racimos protegidos y no protegidos. A este respecto hemos constatado que la cobertura determina una evidente reducci\u00f3n, estad\u00edsticamente significativa, de la temperatura del racimo, y este es un aspecto que no se puede subestimar.\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mientras la bodega \u201cTerre dei Pallavicini\u201d elige los productos agrotextiles Iride\u00ae y Fructus\u00ae, el Grupo prosigue su investigaci\u00f3n junto con la Universidad de Palermo para evaluar las mejores soluciones para las quemaduras.<\/p>\n","protected":false},"author":2,"featured_media":24701,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1945],"tags":[2090,3127,4412,2756,8369,8366,8364,2078,8365,8367,8368,8363],"class_list":["post-24700","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agricultura","tag-agricultura","tag-agro","tag-arrigoni","tag-aves","tag-biodiversity-in-agriculture-and-forestry","tag-granizo","tag-grupo-arrigoni","tag-heladas","tag-insectos","tag-sol-y-viento","tag-universidad-de-palermo","tag-uva-de-vino"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arrigoni busca adaptaci\u00f3n de la uva de vino al cambio clim\u00e1tico - Mundoagropecuario<\/title>\n<meta name=\"description\" content=\"Mientras la bodega \u201cTerre dei Pallavicini\u201d elige los productos agrotextiles Iride\u00ae y Fructus\u00ae, el Grupo prosigue su investigaci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mundoagropecuario.cl\/new\/arrigoni-busca-adaptacion-de-la-uva-de-vino-al-cambio-climatico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arrigoni busca adaptaci\u00f3n de la uva de vino al cambio clim\u00e1tico - Mundoagropecuario\" \/>\n<meta property=\"og:description\" content=\"Mientras la bodega \u201cTerre dei Pallavicini\u201d elige los productos agrotextiles Iride\u00ae y Fructus\u00ae, el Grupo prosigue su investigaci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mundoagropecuario.cl\/new\/arrigoni-busca-adaptacion-de-la-uva-de-vino-al-cambio-climatico\/\" \/>\n<meta property=\"og:site_name\" content=\"Mundoagropecuario\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mundo.agropecuario.3\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-25T15:35:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-02T16:56:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/09\/Arrigoni-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"401\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mundo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MundoAgropecuar\" \/>\n<meta name=\"twitter:site\" content=\"@MundoAgropecuar\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mundo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/arrigoni-busca-adaptacion-de-la-uva-de-vino-al-cambio-climatico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/arrigoni-busca-adaptacion-de-la-uva-de-vino-al-cambio-climatico\\\/\"},\"author\":{\"name\":\"mundo\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/person\\\/4e9f74a82a7dac260eb1c44b7eebeb18\"},\"headline\":\"Arrigoni busca adaptaci\u00f3n de la uva de vino al cambio clim\u00e1tico\",\"datePublished\":\"2023-09-25T15:35:21+00:00\",\"dateModified\":\"2023-10-02T16:56:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/arrigoni-busca-adaptacion-de-la-uva-de-vino-al-cambio-climatico\\\/\"},\"wordCount\":864,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/arrigoni-busca-adaptacion-de-la-uva-de-vino-al-cambio-climatico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Arrigoni-scaled.jpeg\",\"keywords\":[\"Agricultura\",\"Agro\",\"Arrigoni\",\"aves\",\"Biodiversity in Agriculture and Forestry\",\"granizo\",\"Grupo Arrigoni\",\"Heladas\",\"insectos\",\"sol y viento\",\"Universidad de Palermo\",\"Uva de vino\"],\"articleSection\":[\"Agricultura\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/arrigoni-busca-adaptacion-de-la-uva-de-vino-al-cambio-climatico\\\/\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/arrigoni-busca-adaptacion-de-la-uva-de-vino-al-cambio-climatico\\\/\",\"name\":\"Arrigoni busca adaptaci\u00f3n de la uva de vino al cambio clim\u00e1tico - Mundoagropecuario\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/arrigoni-busca-adaptacion-de-la-uva-de-vino-al-cambio-climatico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/arrigoni-busca-adaptacion-de-la-uva-de-vino-al-cambio-climatico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Arrigoni-scaled.jpeg\",\"datePublished\":\"2023-09-25T15:35:21+00:00\",\"dateModified\":\"2023-10-02T16:56:58+00:00\",\"description\":\"Mientras la bodega \u201cTerre dei Pallavicini\u201d elige los productos agrotextiles Iride\u00ae y Fructus\u00ae, el Grupo prosigue su investigaci\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/arrigoni-busca-adaptacion-de-la-uva-de-vino-al-cambio-climatico\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/arrigoni-busca-adaptacion-de-la-uva-de-vino-al-cambio-climatico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/arrigoni-busca-adaptacion-de-la-uva-de-vino-al-cambio-climatico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Arrigoni-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Arrigoni-scaled.jpeg\",\"width\":720,\"height\":401},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/arrigoni-busca-adaptacion-de-la-uva-de-vino-al-cambio-climatico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arrigoni busca adaptaci\u00f3n de la uva de vino al cambio clim\u00e1tico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#website\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/\",\"name\":\"Mundoagropecuario\",\"description\":\"Mundo Agropecuario\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#organization\",\"name\":\"Revista de Agricultura\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/PORTAL-1-1.png\",\"contentUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/PORTAL-1-1.png\",\"width\":1026,\"height\":100,\"caption\":\"Revista de Agricultura\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mundo.agropecuario.3\",\"https:\\\/\\\/x.com\\\/MundoAgropecuar\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/mundo-agropecuario-934009201\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/person\\\/4e9f74a82a7dac260eb1c44b7eebeb18\",\"name\":\"mundo\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/author\\\/mundo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arrigoni busca adaptaci\u00f3n de la uva de vino al cambio clim\u00e1tico - Mundoagropecuario","description":"Mientras la bodega \u201cTerre dei Pallavicini\u201d elige los productos agrotextiles Iride\u00ae y Fructus\u00ae, el Grupo prosigue su investigaci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mundoagropecuario.cl\/new\/arrigoni-busca-adaptacion-de-la-uva-de-vino-al-cambio-climatico\/","og_locale":"es_ES","og_type":"article","og_title":"Arrigoni busca adaptaci\u00f3n de la uva de vino al cambio clim\u00e1tico - Mundoagropecuario","og_description":"Mientras la bodega \u201cTerre dei Pallavicini\u201d elige los productos agrotextiles Iride\u00ae y Fructus\u00ae, el Grupo prosigue su investigaci\u00f3n.","og_url":"https:\/\/www.mundoagropecuario.cl\/new\/arrigoni-busca-adaptacion-de-la-uva-de-vino-al-cambio-climatico\/","og_site_name":"Mundoagropecuario","article_publisher":"https:\/\/www.facebook.com\/mundo.agropecuario.3","article_published_time":"2023-09-25T15:35:21+00:00","article_modified_time":"2023-10-02T16:56:58+00:00","og_image":[{"width":720,"height":401,"url":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/09\/Arrigoni-scaled.jpeg","type":"image\/jpeg"}],"author":"mundo","twitter_card":"summary_large_image","twitter_creator":"@MundoAgropecuar","twitter_site":"@MundoAgropecuar","twitter_misc":{"Escrito por":"mundo","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mundoagropecuario.cl\/new\/arrigoni-busca-adaptacion-de-la-uva-de-vino-al-cambio-climatico\/#article","isPartOf":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/arrigoni-busca-adaptacion-de-la-uva-de-vino-al-cambio-climatico\/"},"author":{"name":"mundo","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/person\/4e9f74a82a7dac260eb1c44b7eebeb18"},"headline":"Arrigoni busca adaptaci\u00f3n de la uva de vino al cambio clim\u00e1tico","datePublished":"2023-09-25T15:35:21+00:00","dateModified":"2023-10-02T16:56:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/arrigoni-busca-adaptacion-de-la-uva-de-vino-al-cambio-climatico\/"},"wordCount":864,"publisher":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#organization"},"image":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/arrigoni-busca-adaptacion-de-la-uva-de-vino-al-cambio-climatico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/09\/Arrigoni-scaled.jpeg","keywords":["Agricultura","Agro","Arrigoni","aves","Biodiversity in Agriculture and Forestry","granizo","Grupo Arrigoni","Heladas","insectos","sol y viento","Universidad de Palermo","Uva de vino"],"articleSection":["Agricultura"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.mundoagropecuario.cl\/new\/arrigoni-busca-adaptacion-de-la-uva-de-vino-al-cambio-climatico\/","url":"https:\/\/www.mundoagropecuario.cl\/new\/arrigoni-busca-adaptacion-de-la-uva-de-vino-al-cambio-climatico\/","name":"Arrigoni busca adaptaci\u00f3n de la uva de vino al cambio clim\u00e1tico - Mundoagropecuario","isPartOf":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/arrigoni-busca-adaptacion-de-la-uva-de-vino-al-cambio-climatico\/#primaryimage"},"image":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/arrigoni-busca-adaptacion-de-la-uva-de-vino-al-cambio-climatico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/09\/Arrigoni-scaled.jpeg","datePublished":"2023-09-25T15:35:21+00:00","dateModified":"2023-10-02T16:56:58+00:00","description":"Mientras la bodega \u201cTerre dei Pallavicini\u201d elige los productos agrotextiles Iride\u00ae y Fructus\u00ae, el Grupo prosigue su investigaci\u00f3n.","breadcrumb":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/arrigoni-busca-adaptacion-de-la-uva-de-vino-al-cambio-climatico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mundoagropecuario.cl\/new\/arrigoni-busca-adaptacion-de-la-uva-de-vino-al-cambio-climatico\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoagropecuario.cl\/new\/arrigoni-busca-adaptacion-de-la-uva-de-vino-al-cambio-climatico\/#primaryimage","url":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/09\/Arrigoni-scaled.jpeg","contentUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/09\/Arrigoni-scaled.jpeg","width":720,"height":401},{"@type":"BreadcrumbList","@id":"https:\/\/www.mundoagropecuario.cl\/new\/arrigoni-busca-adaptacion-de-la-uva-de-vino-al-cambio-climatico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.mundoagropecuario.cl\/new\/"},{"@type":"ListItem","position":2,"name":"Arrigoni busca adaptaci\u00f3n de la uva de vino al cambio clim\u00e1tico"}]},{"@type":"WebSite","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#website","url":"https:\/\/www.mundoagropecuario.cl\/new\/","name":"Mundoagropecuario","description":"Mundo Agropecuario","publisher":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mundoagropecuario.cl\/new\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#organization","name":"Revista de Agricultura","url":"https:\/\/www.mundoagropecuario.cl\/new\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/logo\/image\/","url":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/11\/PORTAL-1-1.png","contentUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/11\/PORTAL-1-1.png","width":1026,"height":100,"caption":"Revista de Agricultura"},"image":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mundo.agropecuario.3","https:\/\/x.com\/MundoAgropecuar","https:\/\/www.linkedin.com\/in\/mundo-agropecuario-934009201\/"]},{"@type":"Person","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/person\/4e9f74a82a7dac260eb1c44b7eebeb18","name":"mundo","url":"https:\/\/www.mundoagropecuario.cl\/new\/author\/mundo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts\/24700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/comments?post=24700"}],"version-history":[{"count":1,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts\/24700\/revisions"}],"predecessor-version":[{"id":24702,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts\/24700\/revisions\/24702"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/media\/24701"}],"wp:attachment":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/media?parent=24700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/categories?post=24700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/tags?post=24700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}