{"id":24421,"date":"2023-07-20T14:21:04","date_gmt":"2023-07-20T17:21:04","guid":{"rendered":"https:\/\/www.mundoagropecuario.cl\/new\/?p=24421"},"modified":"2023-07-31T13:10:13","modified_gmt":"2023-07-31T16:10:13","slug":"comparativo-mayo-2022-23-recepcion-nacional-de-leche-cruda-anota-retroceso-de-63","status":"publish","type":"post","link":"https:\/\/www.mundoagropecuario.cl\/new\/comparativo-mayo-2022-23-recepcion-nacional-de-leche-cruda-anota-retroceso-de-63\/","title":{"rendered":"Comparativo mayo 2022\/23: Recepci\u00f3n nacional de leche cruda anota retroceso de 6,3%"},"content":{"rendered":"<p>De acuerdo a los datos divulgados por la Federaci\u00f3n Gremial Nacional de Productores de Leche (Fedeleche) en base a los antecedentes liberados por la Oficina de Estudios y Pol\u00edticas Agrarias (Odepa), la recepci\u00f3n nacional de leche cruda al mes de mayo de 2023 presenta una disminuci\u00f3n de un 5,8% en comparaci\u00f3n al mismo periodo del a\u00f1o anterior, bajando de 902,1 a 849,9 millones de litros.<\/p>\n<p>Lo anterior, supone una contracci\u00f3n interanual de 52,2 millones de litros y a su vez completar doce meses consecutivos a la baja.<\/p>\n<p>En cuanto al desempe\u00f1o productivo, la Regi\u00f3n Metropolitana y La Araucan\u00eda presentan un alza en recepci\u00f3n , mientras las regiones de \u00d1uble, Bio-Bio, Los R\u00edos y Los Lagos el resultado es negativo.<\/p>\n<p><a href=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/07\/cuadro1.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-24423 size-full\" src=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/07\/cuadro1.jpeg\" alt=\"\" width=\"541\" height=\"400\" srcset=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/07\/cuadro1.jpeg 541w, https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/07\/cuadro1-180x133.jpeg 180w\" sizes=\"auto, (max-width: 541px) 100vw, 541px\" \/><\/a><\/p>\n<p><span style=\"color: #000080;\"><strong>Desempe\u00f1o regional<\/strong><\/span><\/p>\n<p>En el desglose por zona, la regi\u00f3n de Los Lagos, donde se concentra un 44,5% de la recepci\u00f3n nacional de leche cruda, presenta una baja de 7,6% respecto al mismo periodo de 2022, cayendo de 409,6 a 378,4 millones de litros, lo que supone una ca\u00edda interanual de 31,2 millones.<\/p>\n<p>En la regi\u00f3n de Los R\u00edos, con una participaci\u00f3n a nivel nacional de 32,5%, la recepci\u00f3n de leche acumula un retroceso del 5,4% respecto del mismo periodo del a\u00f1o 2022, pasando de 292,3 a 276,6 millones de litros, lo cual supone una baja interanual de 15,7 millones.<\/p>\n<p><a href=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/03\/leche-cruda--scaled.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-23756 \" src=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/03\/leche-cruda--1024x682.jpeg\" alt=\"\" width=\"367\" height=\"244\" srcset=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/03\/leche-cruda--1024x682.jpeg 1024w, https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/03\/leche-cruda--586x390.jpeg 586w, https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/03\/leche-cruda--768x512.jpeg 768w, https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/03\/leche-cruda--scaled.jpeg 601w\" sizes=\"auto, (max-width: 367px) 100vw, 367px\" \/><\/a>En la regi\u00f3n de La Araucan\u00eda, que supone un 7,3% de la recepci\u00f3n nacional, se observa un aumento del 1,1% frente al mismo periodo del a\u00f1o anterior, subiendo de 61,2 a 61,8 millones de litros con un avance interanual de 670 mil litros.<\/p>\n<p>Por su parte, en la regi\u00f3n de Bio-Bio, que representa un 2,3% a nivel nacional, la recepci\u00f3n de leche cruda muestra una ca\u00edda de 15,8% comparado con el mismo periodo del a\u00f1o pasado, cayendo de 23,2 a 19,6 millones de litros, con una merma de 3,7 millones de litros.<\/p>\n<p>En la regi\u00f3n de \u00d1uble, donde se concentra un 2,2% de la recepci\u00f3n nacional de leche cruda, la variaci\u00f3n fue negativa de un 11,6% respecto del a\u00f1o anterior, cayendo de 21,5 a 19,0 millones de litros, lo que supone un retroceso de 2,5 millones de litros.<\/p>\n<p>La Regi\u00f3n Metropolitana, con una participaci\u00f3n del 11,1%, present\u00f3 una leve alza de un 0,3% respecto del a\u00f1o anterior, pasando de 94,2 a\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 94,5 millones de litros, con un aumento de 236 mil litros.<\/p>\n<p><strong><span style=\"color: #000080;\">\u00bfQu\u00e9 paso en mayo?<\/span><\/strong><\/p>\n<p>En el quinto mes del a\u00f1o, la recepci\u00f3n nacional de leche cruda muestra una ca\u00edda de 6,3% respecto al mismo mes del a\u00f1o anterior, alcanzando un total de 154,4 millones y una merma interanual de 10,4 millones de litros.<\/p>\n<p>En la regi\u00f3n de Los Lagos, la recepci\u00f3n de leche cruda termin\u00f3 cayendo 11,1%, alcanzando un total de 63,1 millones de litros. Lo anterior, supone una merma de 7,9 millones de litros frente al mismo mes de 2022.<\/p>\n<p><a href=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/03\/leche-cruda-708.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-23757 \" src=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/03\/leche-cruda-708.jpeg\" alt=\"\" width=\"566\" height=\"364\" \/><\/a>En la regi\u00f3n de Los R\u00edos se registr\u00f3 una ca\u00edda de un 2,5% respecto del mismo mes de 2022, alcanzando un volumen total de 54,0 millones de litros, lo que representa una merma de 1,4 millones de litros.<\/p>\n<p>En la regi\u00f3n de La Araucan\u00eda la recepci\u00f3n de leche cruda sube un 1,5%, lo que supone alcanzar un total de 11,4 millones de litros, resultado que es superior en 171 mil litros frente al mismo mes del a\u00f1o anterior.<\/p>\n<p>La regi\u00f3n de Bio-Bio present\u00f3 un descenso de un 17,5% en relaci\u00f3n al mismo mes del a\u00f1o previo. Este valor supone alcanzar 3,7 millones de litros, una baja interanual de 744 mil litros frente a 2022.<\/p>\n<p>En la regi\u00f3n de \u00d1uble se observ\u00f3 una ca\u00edda de un 2,6% frente al mismo mes del a\u00f1o anterior, sumando un total de 3,7 millones de litros. El dato supone un retroceso de 98 mil litros.<\/p>\n<p>Por \u00faltimo, la regi\u00f3n Metropolitana present\u00f3 una variaci\u00f3n negativa de un 2,2%, alcanzando un total de 18,8 millones de litros, lo que supone una merma de 414 mil litros respecto al mismo mes de 2022.<\/p>\n<p><a href=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/07\/cuadro2.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-24422 \" src=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/07\/cuadro2.jpeg\" alt=\"\" width=\"666\" height=\"424\" \/><\/a><\/p>\n<p>Fuente: Fedeleche &amp; Odepa<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comparado con el a\u00f1o anterior, la recepci\u00f3n de leche cruda en la Regi\u00f3n Metropolitana y La Araucan\u00eda presentan un alza leve, mientras en las regiones de \u00d1uble, Bio-Bio, Los R\u00edos y Los Lagos la tendencia observa es a la baja.<\/p>\n","protected":false},"author":2,"featured_media":24265,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1946],"tags":[2090,3127,2058,2141,2051,7804],"class_list":["post-24421","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lacteos","tag-agricultura","tag-agro","tag-fedeleche","tag-lacteos","tag-leche","tag-recepcion-nacional-de-leche-cruda"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comparativo mayo 2022\/23: Recepci\u00f3n nacional de leche cruda anota retroceso de 6,3% - Mundoagropecuario<\/title>\n<meta name=\"description\" content=\"Comparado con el a\u00f1o anterior, la recepci\u00f3n de leche cruda en la Regi\u00f3n Metropolitana y La Araucan\u00eda presentan un alza leve.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mundoagropecuario.cl\/new\/comparativo-mayo-2022-23-recepcion-nacional-de-leche-cruda-anota-retroceso-de-63\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comparativo mayo 2022\/23: Recepci\u00f3n nacional de leche cruda anota retroceso de 6,3% - Mundoagropecuario\" \/>\n<meta property=\"og:description\" content=\"Comparado con el a\u00f1o anterior, la recepci\u00f3n de leche cruda en la Regi\u00f3n Metropolitana y La Araucan\u00eda presentan un alza leve.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mundoagropecuario.cl\/new\/comparativo-mayo-2022-23-recepcion-nacional-de-leche-cruda-anota-retroceso-de-63\/\" \/>\n<meta property=\"og:site_name\" content=\"Mundoagropecuario\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mundo.agropecuario.3\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-20T17:21:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-31T16:10:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/06\/vacas-lecheras-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"385\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mundo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MundoAgropecuar\" \/>\n<meta name=\"twitter:site\" content=\"@MundoAgropecuar\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mundo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/comparativo-mayo-2022-23-recepcion-nacional-de-leche-cruda-anota-retroceso-de-63\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/comparativo-mayo-2022-23-recepcion-nacional-de-leche-cruda-anota-retroceso-de-63\\\/\"},\"author\":{\"name\":\"mundo\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/person\\\/4e9f74a82a7dac260eb1c44b7eebeb18\"},\"headline\":\"Comparativo mayo 2022\\\/23: Recepci\u00f3n nacional de leche cruda anota retroceso de 6,3%\",\"datePublished\":\"2023-07-20T17:21:04+00:00\",\"dateModified\":\"2023-07-31T16:10:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/comparativo-mayo-2022-23-recepcion-nacional-de-leche-cruda-anota-retroceso-de-63\\\/\"},\"wordCount\":665,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/comparativo-mayo-2022-23-recepcion-nacional-de-leche-cruda-anota-retroceso-de-63\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/vacas-lecheras-scaled.jpeg\",\"keywords\":[\"Agricultura\",\"Agro\",\"Fedeleche\",\"L\u00e1cteos\",\"Leche\",\"Recepci\u00f3n nacional de leche cruda\"],\"articleSection\":[\"L\u00e1cteos\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/comparativo-mayo-2022-23-recepcion-nacional-de-leche-cruda-anota-retroceso-de-63\\\/\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/comparativo-mayo-2022-23-recepcion-nacional-de-leche-cruda-anota-retroceso-de-63\\\/\",\"name\":\"Comparativo mayo 2022\\\/23: Recepci\u00f3n nacional de leche cruda anota retroceso de 6,3% - Mundoagropecuario\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/comparativo-mayo-2022-23-recepcion-nacional-de-leche-cruda-anota-retroceso-de-63\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/comparativo-mayo-2022-23-recepcion-nacional-de-leche-cruda-anota-retroceso-de-63\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/vacas-lecheras-scaled.jpeg\",\"datePublished\":\"2023-07-20T17:21:04+00:00\",\"dateModified\":\"2023-07-31T16:10:13+00:00\",\"description\":\"Comparado con el a\u00f1o anterior, la recepci\u00f3n de leche cruda en la Regi\u00f3n Metropolitana y La Araucan\u00eda presentan un alza leve.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/comparativo-mayo-2022-23-recepcion-nacional-de-leche-cruda-anota-retroceso-de-63\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/comparativo-mayo-2022-23-recepcion-nacional-de-leche-cruda-anota-retroceso-de-63\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/comparativo-mayo-2022-23-recepcion-nacional-de-leche-cruda-anota-retroceso-de-63\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/vacas-lecheras-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/vacas-lecheras-scaled.jpeg\",\"width\":720,\"height\":385},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/comparativo-mayo-2022-23-recepcion-nacional-de-leche-cruda-anota-retroceso-de-63\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comparativo mayo 2022\\\/23: Recepci\u00f3n nacional de leche cruda anota retroceso de 6,3%\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#website\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/\",\"name\":\"Mundoagropecuario\",\"description\":\"Mundo Agropecuario\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#organization\",\"name\":\"Revista de Agricultura\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/PORTAL-1-1.png\",\"contentUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/PORTAL-1-1.png\",\"width\":1026,\"height\":100,\"caption\":\"Revista de Agricultura\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mundo.agropecuario.3\",\"https:\\\/\\\/x.com\\\/MundoAgropecuar\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/mundo-agropecuario-934009201\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/person\\\/4e9f74a82a7dac260eb1c44b7eebeb18\",\"name\":\"mundo\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/author\\\/mundo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comparativo mayo 2022\/23: Recepci\u00f3n nacional de leche cruda anota retroceso de 6,3% - Mundoagropecuario","description":"Comparado con el a\u00f1o anterior, la recepci\u00f3n de leche cruda en la Regi\u00f3n Metropolitana y La Araucan\u00eda presentan un alza leve.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mundoagropecuario.cl\/new\/comparativo-mayo-2022-23-recepcion-nacional-de-leche-cruda-anota-retroceso-de-63\/","og_locale":"es_ES","og_type":"article","og_title":"Comparativo mayo 2022\/23: Recepci\u00f3n nacional de leche cruda anota retroceso de 6,3% - Mundoagropecuario","og_description":"Comparado con el a\u00f1o anterior, la recepci\u00f3n de leche cruda en la Regi\u00f3n Metropolitana y La Araucan\u00eda presentan un alza leve.","og_url":"https:\/\/www.mundoagropecuario.cl\/new\/comparativo-mayo-2022-23-recepcion-nacional-de-leche-cruda-anota-retroceso-de-63\/","og_site_name":"Mundoagropecuario","article_publisher":"https:\/\/www.facebook.com\/mundo.agropecuario.3","article_published_time":"2023-07-20T17:21:04+00:00","article_modified_time":"2023-07-31T16:10:13+00:00","og_image":[{"width":720,"height":385,"url":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/06\/vacas-lecheras-scaled.jpeg","type":"image\/jpeg"}],"author":"mundo","twitter_card":"summary_large_image","twitter_creator":"@MundoAgropecuar","twitter_site":"@MundoAgropecuar","twitter_misc":{"Escrito por":"mundo","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mundoagropecuario.cl\/new\/comparativo-mayo-2022-23-recepcion-nacional-de-leche-cruda-anota-retroceso-de-63\/#article","isPartOf":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/comparativo-mayo-2022-23-recepcion-nacional-de-leche-cruda-anota-retroceso-de-63\/"},"author":{"name":"mundo","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/person\/4e9f74a82a7dac260eb1c44b7eebeb18"},"headline":"Comparativo mayo 2022\/23: Recepci\u00f3n nacional de leche cruda anota retroceso de 6,3%","datePublished":"2023-07-20T17:21:04+00:00","dateModified":"2023-07-31T16:10:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/comparativo-mayo-2022-23-recepcion-nacional-de-leche-cruda-anota-retroceso-de-63\/"},"wordCount":665,"publisher":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#organization"},"image":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/comparativo-mayo-2022-23-recepcion-nacional-de-leche-cruda-anota-retroceso-de-63\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/06\/vacas-lecheras-scaled.jpeg","keywords":["Agricultura","Agro","Fedeleche","L\u00e1cteos","Leche","Recepci\u00f3n nacional de leche cruda"],"articleSection":["L\u00e1cteos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.mundoagropecuario.cl\/new\/comparativo-mayo-2022-23-recepcion-nacional-de-leche-cruda-anota-retroceso-de-63\/","url":"https:\/\/www.mundoagropecuario.cl\/new\/comparativo-mayo-2022-23-recepcion-nacional-de-leche-cruda-anota-retroceso-de-63\/","name":"Comparativo mayo 2022\/23: Recepci\u00f3n nacional de leche cruda anota retroceso de 6,3% - Mundoagropecuario","isPartOf":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/comparativo-mayo-2022-23-recepcion-nacional-de-leche-cruda-anota-retroceso-de-63\/#primaryimage"},"image":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/comparativo-mayo-2022-23-recepcion-nacional-de-leche-cruda-anota-retroceso-de-63\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/06\/vacas-lecheras-scaled.jpeg","datePublished":"2023-07-20T17:21:04+00:00","dateModified":"2023-07-31T16:10:13+00:00","description":"Comparado con el a\u00f1o anterior, la recepci\u00f3n de leche cruda en la Regi\u00f3n Metropolitana y La Araucan\u00eda presentan un alza leve.","breadcrumb":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/comparativo-mayo-2022-23-recepcion-nacional-de-leche-cruda-anota-retroceso-de-63\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mundoagropecuario.cl\/new\/comparativo-mayo-2022-23-recepcion-nacional-de-leche-cruda-anota-retroceso-de-63\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoagropecuario.cl\/new\/comparativo-mayo-2022-23-recepcion-nacional-de-leche-cruda-anota-retroceso-de-63\/#primaryimage","url":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/06\/vacas-lecheras-scaled.jpeg","contentUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2023\/06\/vacas-lecheras-scaled.jpeg","width":720,"height":385},{"@type":"BreadcrumbList","@id":"https:\/\/www.mundoagropecuario.cl\/new\/comparativo-mayo-2022-23-recepcion-nacional-de-leche-cruda-anota-retroceso-de-63\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.mundoagropecuario.cl\/new\/"},{"@type":"ListItem","position":2,"name":"Comparativo mayo 2022\/23: Recepci\u00f3n nacional de leche cruda anota retroceso de 6,3%"}]},{"@type":"WebSite","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#website","url":"https:\/\/www.mundoagropecuario.cl\/new\/","name":"Mundoagropecuario","description":"Mundo Agropecuario","publisher":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mundoagropecuario.cl\/new\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#organization","name":"Revista de Agricultura","url":"https:\/\/www.mundoagropecuario.cl\/new\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/logo\/image\/","url":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/11\/PORTAL-1-1.png","contentUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/11\/PORTAL-1-1.png","width":1026,"height":100,"caption":"Revista de Agricultura"},"image":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mundo.agropecuario.3","https:\/\/x.com\/MundoAgropecuar","https:\/\/www.linkedin.com\/in\/mundo-agropecuario-934009201\/"]},{"@type":"Person","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/person\/4e9f74a82a7dac260eb1c44b7eebeb18","name":"mundo","url":"https:\/\/www.mundoagropecuario.cl\/new\/author\/mundo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts\/24421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/comments?post=24421"}],"version-history":[{"count":1,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts\/24421\/revisions"}],"predecessor-version":[{"id":24424,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts\/24421\/revisions\/24424"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/media\/24265"}],"wp:attachment":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/media?parent=24421"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/categories?post=24421"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/tags?post=24421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}