{"id":22894,"date":"2022-09-26T10:56:56","date_gmt":"2022-09-26T13:56:56","guid":{"rendered":"https:\/\/www.mundoagropecuario.cl\/new\/?p=22894"},"modified":"2022-09-29T12:03:54","modified_gmt":"2022-09-29T15:03:54","slug":"apicultores-afianzaron-lazos-internacionales-en-turquia-e-invitaron-a-asistir-a-apimondia-chile-2023","status":"publish","type":"post","link":"https:\/\/www.mundoagropecuario.cl\/new\/apicultores-afianzaron-lazos-internacionales-en-turquia-e-invitaron-a-asistir-a-apimondia-chile-2023\/","title":{"rendered":"Apicultores afianzaron lazos internacionales en Turqu\u00eda e invitaron a asistir a Apimondia Chile 2023"},"content":{"rendered":"<blockquote>\n<h2><span style=\"color: #003366;\">En el encuentro participaron ponencias de todo el mundo, organizadas por las siete comisiones que potencian desde la parte social hasta la parte m\u00e1s cient\u00edfica.<\/span><\/h2>\n<\/blockquote>\n<p>Una comitiva de 50 apicultores y apicultoras de nuestro pa\u00eds participaron, durante cuatro d\u00edas, en el evento mundial m\u00e1s importante de su rubro: Apimondia 2022, cuya sede tuvo lugar en Estambul, Turqu\u00eda.\u00a0 La instancia, cont\u00f3 con expositores de todo el mundo, entre ellos, del doctor de la Comisi\u00f3n Chilena de Energ\u00eda Nuclear (CCHEN), Enrique Mej\u00edas, quien present\u00f3 su trabajo para erradicar la enfermedad de Loque Americana con irradiaci\u00f3n gamma. Adem\u00e1s, se expuso maquinaria, equipos y herramientas de alta tecnolog\u00eda provenientes de distintos pa\u00edses.<\/p>\n<p><a href=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2022\/09\/1-Minagri_Apimondia2022_Subsecretario_abeja.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-22895 alignleft\" src=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2022\/09\/1-Minagri_Apimondia2022_Subsecretario_abeja-586x440.jpeg\" alt=\"\" width=\"464\" height=\"416\" \/><\/a>El apicultor de la regi\u00f3n Metropolitana, tesorero de la Red Ap\u00edcola Nacional y socio de la RedAmonte, Gustavo Espinoza, evalu\u00f3 positivamente la visita al pa\u00eds de Medio Oriente, donde adem\u00e1s se promovi\u00f3 lo que ser\u00e1 el evento del pr\u00f3ximo a\u00f1o en Chile y\u00a0 donde se compartieron las \u00faltimas tendencias en el mundo ap\u00edcola. \u201cSon hartas las cosas que ocurren simult\u00e1neamente, por supuesto como chilenos la del doctor Mej\u00edas fue la m\u00e1s importante, pero hubo muchas m\u00e1s. Fuimos como delegaci\u00f3n a recibir la responsabilidad de organizar Apimondia 2023\u201d, se\u00f1ala.\u00a0 \u201cAdem\u00e1s, la visita del embajador de Chile en Turqu\u00eda, Rodrigo Arcos y del subsecretario de Agricultura, Jos\u00e9 Guajardo Reyes, fue un respaldo tremendo\u201d, agreg\u00f3.<\/p>\n<p>En el evento nuestro pa\u00eds tuvo uno de los pabellones m\u00e1s amplios y visitados durante el desarrollo del encuentro, donde la delegaci\u00f3n pudo discutir sus conocimientos sobre el rubro y tambi\u00e9n invitar a la comunidad ap\u00edcola global para asistir a Apimondia Chile 2023.<\/p>\n<p>En esta oportunidad la comitiva fue encabezada por la Federaci\u00f3n Red Ap\u00edcola Nacional F.G. gremio que agrupa actualmente a m\u00faltiples organizaciones ap\u00edcolas regionales de nuestro pa\u00eds, quienes estuvieron acompa\u00f1ados del Ministerio de Agricultura, ProChile, empresarios y apicultores. Al evento asistieron miles de personas de 118 pa\u00edses de todo el mundo.<\/p>\n<p><strong><span style=\"color: #003366;\">Espacio para el intercambio de experiencias e innovaci\u00f3n<\/span><\/strong><\/p>\n<p>&#8220;Esta fue una tremenda oportunidad para Chile, para aprender y tambi\u00e9n para dar a conocer lo que somos a la comunidad internacional ap\u00edcola. La apicultura es m\u00e1s que miel, tiene muchos aspectos y potencialidades, en esta oportunidad nuestro pa\u00eds ha invitado al mundo para que vengan a conocer nuestra apicultura, la biodiversidad de su naturaleza y la calidez de su gente&#8221;, coment\u00f3 el subsecretario de Agricultura, Jos\u00e9 Guajardo Reyes, quien acompa\u00f1\u00f3 a la comitiva y dio el discurso que cerr\u00f3 la intervenci\u00f3n chilena en la ceremonia de clausura de Apimondia 2022.<\/p>\n<p>Por su parte Paulina Valderrama, directora General (s) de ProChile, valor\u00f3 la participaci\u00f3n chilena en Apimondia Turqu\u00eda, como un espacio de intercambio de informaci\u00f3n, exhibici\u00f3n de la oferta ap\u00edcola nacional y generaci\u00f3n de nuevos v\u00ednculos comerciales. \u201cEstamos muy contentos de haber brindado apoyo para que nuestra presencia en Turqu\u00eda fuese destacada y lo logramos, a trav\u00e9s de un pabell\u00f3n pa\u00eds en la ApiExpo y la realizaci\u00f3n de la Noche de Chile, en la que se invit\u00f3 a los delegados y a las principales contrapartes del mundo ap\u00edcola a participar de Apimondia Chile 2023. Adem\u00e1s, se fortaleci\u00f3 la delegaci\u00f3n chilena presente a trav\u00e9s de una misi\u00f3n de empresarios y apicultores de las regiones de Coquimbo, Maule y la Regi\u00f3n Metropolitana\u201d, dijo.<\/p>\n<p>\u201cCreemos que Apimondia Chile 2023 ser\u00e1 una gran oportunidad no s\u00f3lo para que los visitantes puedan disfrutar de nuestro pa\u00eds y su cultura, si no que para que puedan conocer nuestra actividad ap\u00edcola, mostrando al mundo que somos un proveedor confiable y de prestigio internacional\u201d, agreg\u00f3.<\/p>\n<p>Bernarda Salazar, apicultora de la Regi\u00f3n de \u00d1uble, presidenta del Comit\u00e9 Ap\u00edcola de Bulnes y directora de la Federaci\u00f3n Red Ap\u00edcola Nacional, lider\u00f3 esta comitiva destacando c\u00f3mo los subproductos de la colmena, como jalea real y prop\u00f3leo se utilizan con la \u00faltima tecnolog\u00eda y cada vez m\u00e1s profesionalmente.<\/p>\n<p>&#8220;Siempre hay cosas que podemos mejorar y aprender. Ahora tenemos claro lo bueno y lo malo para organizar un congreso lo mejor posible el pr\u00f3ximo a\u00f1o, por eso quiero invitar a que el 2023 asistan, en primer lugar, los apicultores chilenos, pero tambi\u00e9n el p\u00fablico en general, que nos sumemos y unamos todos ya que no siempre vamos a tener la posibilidad de organizar un evento como \u00e9ste en Chile, es un privilegio y debemos dejar muy bien parado el nombre de nuestro pa\u00eds&#8221;, expres\u00f3 Bernarda.<\/p>\n<p>Ana Mar\u00eda Aravena, apicultora de San Vicente, en tanto, agreg\u00f3 que \u201cpara m\u00ed fue un orgullo haber sido parte de esta delegaci\u00f3n nacional que trabaj\u00f3 tanto para asistir a Turqu\u00eda. Esta instancia es muy positiva para los apicultores, por eso insto a todos nuestros apicultores nacionales, y a nuestras autoridades, a que sean parte del evento en Chile el 2023&#8243;, asever\u00f3<\/p>\n<p>Es importante se\u00f1alar que las organizaciones y empresas que apoyaron dicho proyecto en esta oportunidad fueron el Ministerio de Agricultura, ProChile, Indap, Fundaci\u00f3n para la Innovaci\u00f3n Agraria (FIA), el Servicio Agr\u00edcola y Ganadero (SAG), Sernatur, la Embajada de Chile en Turqu\u00eda, IICA Chile, el Instituto de Investigaciones Agropecuarias (INIA) y las empresas Agroapicultura, Honeygroup Chile, Ap\u00edcola 360, Ap\u00edcola Los Cristales, Apiquality, Apicoop, Mieles del Sur y la Federaci\u00f3n Red Ap\u00edcola Nacional F.G.<\/p>\n<p><strong><span style=\"color: #003366;\">Congreso Mundial en Chile 2023<\/span><\/strong><\/p>\n<p>Nuestro pa\u00eds ser\u00e1 por primera vez anfitri\u00f3n del 48\u00b0 Congreso Mundial de Apicultura Apimondia 2023, evento que se desarrollar\u00e1 en el Centro de Convenciones de Espacio Riesco en Santiago, desde el 4 hasta el 8 de septiembre de 2023, instancia donde se espera contar con miles de asistentes de todo el mundo.<\/p>\n<p>\u201cLa invitaci\u00f3n es a que todos puedan participar de Apimondia 2023, queremos convocar especialmente a toda la comunidad de Am\u00e9rica, ya que no siempre se celebra un evento de esta magnitud en nuestro continente, pero tambi\u00e9n invitar a la comunidad ap\u00edcola global a que vengan a Chile, aqu\u00ed podr\u00e1n conocer la experiencia de la apicultura nacional, que es producto de nuestro recorrido hist\u00f3rico particular, adem\u00e1s podr\u00e1n disfrutar los diversos paisajes de nuestra tierra, que esperamos poder dar a conocer por medio del enfoque del turismo social, donde quienes asistan podr\u00e1n conocer lo que es ser chileno y vivir su ruralidad\u201d, manifest\u00f3 el presidente de la Federaci\u00f3n Red Ap\u00edcola Nacional F.G, Misael Cuevas, quien adem\u00e1s lidera la Comisi\u00f3n Organizadora Local de Apimondia 2023.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el evento nuestro pa\u00eds tuvo uno de los pabellones m\u00e1s amplios y visitados durante el desarrollo del encuentro, donde la delegaci\u00f3n pudo discutir sus conocimientos sobre el rubro y tambi\u00e9n invitar a la comunidad ap\u00edcola global.<\/p>\n","protected":false},"author":2,"featured_media":22896,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1945],"tags":[2090,3127,1982,7437,7440,2052,7439,7438],"class_list":["post-22894","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agricultura","tag-agricultura","tag-agro","tag-apicultores","tag-apimondia-2022","tag-apimondia-2023","tag-inia","tag-red-apicola-nacional","tag-red-apicola-nacional-f-g"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Apicultores afianzaron lazos internacionales en Turqu\u00eda e invitaron a asistir a Apimondia Chile 2023 - Mundoagropecuario<\/title>\n<meta name=\"description\" content=\"Creemos que Apimondia Chile 2023 ser\u00e1 una gran oportunidad no s\u00f3lo para que los visitantes puedan disfrutar de nuestro pa\u00eds.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mundoagropecuario.cl\/new\/apicultores-afianzaron-lazos-internacionales-en-turquia-e-invitaron-a-asistir-a-apimondia-chile-2023\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Apicultores afianzaron lazos internacionales en Turqu\u00eda e invitaron a asistir a Apimondia Chile 2023 - Mundoagropecuario\" \/>\n<meta property=\"og:description\" content=\"Creemos que Apimondia Chile 2023 ser\u00e1 una gran oportunidad no s\u00f3lo para que los visitantes puedan disfrutar de nuestro pa\u00eds.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mundoagropecuario.cl\/new\/apicultores-afianzaron-lazos-internacionales-en-turquia-e-invitaron-a-asistir-a-apimondia-chile-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Mundoagropecuario\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mundo.agropecuario.3\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-26T13:56:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-29T15:03:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2022\/09\/4-Minagri_Apimondia2022_delegacion.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mundo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MundoAgropecuar\" \/>\n<meta name=\"twitter:site\" content=\"@MundoAgropecuar\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mundo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/apicultores-afianzaron-lazos-internacionales-en-turquia-e-invitaron-a-asistir-a-apimondia-chile-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/apicultores-afianzaron-lazos-internacionales-en-turquia-e-invitaron-a-asistir-a-apimondia-chile-2023\\\/\"},\"author\":{\"name\":\"mundo\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/person\\\/4e9f74a82a7dac260eb1c44b7eebeb18\"},\"headline\":\"Apicultores afianzaron lazos internacionales en Turqu\u00eda e invitaron a asistir a Apimondia Chile 2023\",\"datePublished\":\"2022-09-26T13:56:56+00:00\",\"dateModified\":\"2022-09-29T15:03:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/apicultores-afianzaron-lazos-internacionales-en-turquia-e-invitaron-a-asistir-a-apimondia-chile-2023\\\/\"},\"wordCount\":1129,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/apicultores-afianzaron-lazos-internacionales-en-turquia-e-invitaron-a-asistir-a-apimondia-chile-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/4-Minagri_Apimondia2022_delegacion.jpg\",\"keywords\":[\"Agricultura\",\"Agro\",\"apicultores\",\"Apimondia 2022.\",\"Apimondia 2023.\",\"INIA\",\"Red Ap\u00edcola Nacional\",\"Red Ap\u00edcola Nacional F.G.\"],\"articleSection\":[\"Agricultura\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/apicultores-afianzaron-lazos-internacionales-en-turquia-e-invitaron-a-asistir-a-apimondia-chile-2023\\\/\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/apicultores-afianzaron-lazos-internacionales-en-turquia-e-invitaron-a-asistir-a-apimondia-chile-2023\\\/\",\"name\":\"Apicultores afianzaron lazos internacionales en Turqu\u00eda e invitaron a asistir a Apimondia Chile 2023 - Mundoagropecuario\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/apicultores-afianzaron-lazos-internacionales-en-turquia-e-invitaron-a-asistir-a-apimondia-chile-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/apicultores-afianzaron-lazos-internacionales-en-turquia-e-invitaron-a-asistir-a-apimondia-chile-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/4-Minagri_Apimondia2022_delegacion.jpg\",\"datePublished\":\"2022-09-26T13:56:56+00:00\",\"dateModified\":\"2022-09-29T15:03:54+00:00\",\"description\":\"Creemos que Apimondia Chile 2023 ser\u00e1 una gran oportunidad no s\u00f3lo para que los visitantes puedan disfrutar de nuestro pa\u00eds.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/apicultores-afianzaron-lazos-internacionales-en-turquia-e-invitaron-a-asistir-a-apimondia-chile-2023\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/apicultores-afianzaron-lazos-internacionales-en-turquia-e-invitaron-a-asistir-a-apimondia-chile-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/apicultores-afianzaron-lazos-internacionales-en-turquia-e-invitaron-a-asistir-a-apimondia-chile-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/4-Minagri_Apimondia2022_delegacion.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/4-Minagri_Apimondia2022_delegacion.jpg\",\"width\":601,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/apicultores-afianzaron-lazos-internacionales-en-turquia-e-invitaron-a-asistir-a-apimondia-chile-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Apicultores afianzaron lazos internacionales en Turqu\u00eda e invitaron a asistir a Apimondia Chile 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#website\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/\",\"name\":\"Mundoagropecuario\",\"description\":\"Mundo Agropecuario\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#organization\",\"name\":\"Revista de Agricultura\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/PORTAL-1-1.png\",\"contentUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/PORTAL-1-1.png\",\"width\":1026,\"height\":100,\"caption\":\"Revista de Agricultura\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mundo.agropecuario.3\",\"https:\\\/\\\/x.com\\\/MundoAgropecuar\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/mundo-agropecuario-934009201\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/person\\\/4e9f74a82a7dac260eb1c44b7eebeb18\",\"name\":\"mundo\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/author\\\/mundo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Apicultores afianzaron lazos internacionales en Turqu\u00eda e invitaron a asistir a Apimondia Chile 2023 - Mundoagropecuario","description":"Creemos que Apimondia Chile 2023 ser\u00e1 una gran oportunidad no s\u00f3lo para que los visitantes puedan disfrutar de nuestro pa\u00eds.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mundoagropecuario.cl\/new\/apicultores-afianzaron-lazos-internacionales-en-turquia-e-invitaron-a-asistir-a-apimondia-chile-2023\/","og_locale":"es_ES","og_type":"article","og_title":"Apicultores afianzaron lazos internacionales en Turqu\u00eda e invitaron a asistir a Apimondia Chile 2023 - Mundoagropecuario","og_description":"Creemos que Apimondia Chile 2023 ser\u00e1 una gran oportunidad no s\u00f3lo para que los visitantes puedan disfrutar de nuestro pa\u00eds.","og_url":"https:\/\/www.mundoagropecuario.cl\/new\/apicultores-afianzaron-lazos-internacionales-en-turquia-e-invitaron-a-asistir-a-apimondia-chile-2023\/","og_site_name":"Mundoagropecuario","article_publisher":"https:\/\/www.facebook.com\/mundo.agropecuario.3","article_published_time":"2022-09-26T13:56:56+00:00","article_modified_time":"2022-09-29T15:03:54+00:00","og_image":[{"width":1024,"height":682,"url":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2022\/09\/4-Minagri_Apimondia2022_delegacion.jpg","type":"image\/jpeg"}],"author":"mundo","twitter_card":"summary_large_image","twitter_creator":"@MundoAgropecuar","twitter_site":"@MundoAgropecuar","twitter_misc":{"Escrito por":"mundo","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mundoagropecuario.cl\/new\/apicultores-afianzaron-lazos-internacionales-en-turquia-e-invitaron-a-asistir-a-apimondia-chile-2023\/#article","isPartOf":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/apicultores-afianzaron-lazos-internacionales-en-turquia-e-invitaron-a-asistir-a-apimondia-chile-2023\/"},"author":{"name":"mundo","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/person\/4e9f74a82a7dac260eb1c44b7eebeb18"},"headline":"Apicultores afianzaron lazos internacionales en Turqu\u00eda e invitaron a asistir a Apimondia Chile 2023","datePublished":"2022-09-26T13:56:56+00:00","dateModified":"2022-09-29T15:03:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/apicultores-afianzaron-lazos-internacionales-en-turquia-e-invitaron-a-asistir-a-apimondia-chile-2023\/"},"wordCount":1129,"publisher":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#organization"},"image":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/apicultores-afianzaron-lazos-internacionales-en-turquia-e-invitaron-a-asistir-a-apimondia-chile-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2022\/09\/4-Minagri_Apimondia2022_delegacion.jpg","keywords":["Agricultura","Agro","apicultores","Apimondia 2022.","Apimondia 2023.","INIA","Red Ap\u00edcola Nacional","Red Ap\u00edcola Nacional F.G."],"articleSection":["Agricultura"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.mundoagropecuario.cl\/new\/apicultores-afianzaron-lazos-internacionales-en-turquia-e-invitaron-a-asistir-a-apimondia-chile-2023\/","url":"https:\/\/www.mundoagropecuario.cl\/new\/apicultores-afianzaron-lazos-internacionales-en-turquia-e-invitaron-a-asistir-a-apimondia-chile-2023\/","name":"Apicultores afianzaron lazos internacionales en Turqu\u00eda e invitaron a asistir a Apimondia Chile 2023 - Mundoagropecuario","isPartOf":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/apicultores-afianzaron-lazos-internacionales-en-turquia-e-invitaron-a-asistir-a-apimondia-chile-2023\/#primaryimage"},"image":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/apicultores-afianzaron-lazos-internacionales-en-turquia-e-invitaron-a-asistir-a-apimondia-chile-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2022\/09\/4-Minagri_Apimondia2022_delegacion.jpg","datePublished":"2022-09-26T13:56:56+00:00","dateModified":"2022-09-29T15:03:54+00:00","description":"Creemos que Apimondia Chile 2023 ser\u00e1 una gran oportunidad no s\u00f3lo para que los visitantes puedan disfrutar de nuestro pa\u00eds.","breadcrumb":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/apicultores-afianzaron-lazos-internacionales-en-turquia-e-invitaron-a-asistir-a-apimondia-chile-2023\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mundoagropecuario.cl\/new\/apicultores-afianzaron-lazos-internacionales-en-turquia-e-invitaron-a-asistir-a-apimondia-chile-2023\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoagropecuario.cl\/new\/apicultores-afianzaron-lazos-internacionales-en-turquia-e-invitaron-a-asistir-a-apimondia-chile-2023\/#primaryimage","url":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2022\/09\/4-Minagri_Apimondia2022_delegacion.jpg","contentUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2022\/09\/4-Minagri_Apimondia2022_delegacion.jpg","width":601,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.mundoagropecuario.cl\/new\/apicultores-afianzaron-lazos-internacionales-en-turquia-e-invitaron-a-asistir-a-apimondia-chile-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.mundoagropecuario.cl\/new\/"},{"@type":"ListItem","position":2,"name":"Apicultores afianzaron lazos internacionales en Turqu\u00eda e invitaron a asistir a Apimondia Chile 2023"}]},{"@type":"WebSite","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#website","url":"https:\/\/www.mundoagropecuario.cl\/new\/","name":"Mundoagropecuario","description":"Mundo Agropecuario","publisher":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mundoagropecuario.cl\/new\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#organization","name":"Revista de Agricultura","url":"https:\/\/www.mundoagropecuario.cl\/new\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/logo\/image\/","url":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/11\/PORTAL-1-1.png","contentUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/11\/PORTAL-1-1.png","width":1026,"height":100,"caption":"Revista de Agricultura"},"image":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mundo.agropecuario.3","https:\/\/x.com\/MundoAgropecuar","https:\/\/www.linkedin.com\/in\/mundo-agropecuario-934009201\/"]},{"@type":"Person","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/person\/4e9f74a82a7dac260eb1c44b7eebeb18","name":"mundo","url":"https:\/\/www.mundoagropecuario.cl\/new\/author\/mundo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts\/22894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/comments?post=22894"}],"version-history":[{"count":1,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts\/22894\/revisions"}],"predecessor-version":[{"id":22897,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts\/22894\/revisions\/22897"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/media\/22896"}],"wp:attachment":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/media?parent=22894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/categories?post=22894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/tags?post=22894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}