{"id":21058,"date":"2021-11-29T11:02:12","date_gmt":"2021-11-29T14:02:12","guid":{"rendered":"https:\/\/www.mundoagropecuario.cl\/new\/?p=21058"},"modified":"2021-12-01T11:41:05","modified_gmt":"2021-12-01T14:41:05","slug":"copa-milo-chile-2021-vuelve-a-osorno-el-campeonato-de-baby-futbol-mixto-mas-grande-de-chile","status":"publish","type":"post","link":"https:\/\/www.mundoagropecuario.cl\/new\/copa-milo-chile-2021-vuelve-a-osorno-el-campeonato-de-baby-futbol-mixto-mas-grande-de-chile\/","title":{"rendered":"\u201cCopa MILO Chile 2021\u201d: vuelve a Osorno el campeonato de baby-f\u00fatbol mixto m\u00e1s grande de Chile"},"content":{"rendered":"<blockquote>\n<h2><span style=\"color: #333300;\">El campeonato se est\u00e1 desarrollando desde el 25 de septiembre y el 16 de enero de 2022 y busca, por medio del f\u00fatbol, fomentar en ni\u00f1os y ni\u00f1as los valores que se aprenden a trav\u00e9s del deporte. En Osorno el campeonato se jugar\u00e1 este s\u00e1bado 4 y domingo 5 de diciembre.<\/span><\/h2>\n<\/blockquote>\n<p>Ya se viene la \u201cCopa MILO Chile 2021\u201d, el campeonato mixto de baby-f\u00fatbol a nivel nacional para ni\u00f1as y ni\u00f1os entre 9 y 12 a\u00f1os. Abarca once ciudades del pa\u00eds y se est\u00e1 desarrollando desde el 25 septiembre hasta el 16 de enero del 2022.<\/p>\n<p>El equipo que se consagre campe\u00f3n participar\u00e1 del \u201cMILO Soccer Camp 2022\u201d, un campamento de f\u00fatbol para todo el equipo por 5 d\u00edas. \u00a1Y atentos!, que no solo el mejor equipo de cada ciudad clasificar\u00e1 a la gran final, sino que tambi\u00e9n lo har\u00e1n los Equipos Esp\u00edritu MILO, es decir, aquellos que destaquen por su actitud dentro y fuera de la cancha y que demuestren valores como la humildad, el esfuerzo, el respeto y el trabajo en equipo. En cada Campeonato se premiar\u00e1 a los equipos Campeones y a los dos equipos Tarjeta Verde Esp\u00edritu MILO.<\/p>\n<p><a href=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2021\/11\/COPA-MILO-1-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-21059 alignright\" src=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2021\/11\/COPA-MILO-1-586x440.jpg\" alt=\"\" width=\"507\" height=\"323\" \/><\/a>La copa dio su puntapi\u00e9 inicial en Santiago. Posteriormente, los partidos siguieron en Iquique (2-3 octubre), Antofagasta (9-10 octubre), La Serena (16-17 octubre), Vi\u00f1a del Mar (23-24 octubre), Talca (30-31 octubre), Concepci\u00f3n (6-7 noviembre), Temuco (13-14 noviembre), Valdivia (27-28 noviembre). Las pr\u00f3ximas fechas ser\u00e1n en Osorno (4-5 diciembre), Puerto Montt (11-12 diciembre) y la gran final, tambi\u00e9n a disputarse en Santiago, el 16 de enero del 2022.<\/p>\n<p><strong><span style=\"color: #333300;\">Din\u00e1mica de campeonato<\/span><\/strong><\/p>\n<p>Si tienes entre 9 y 12 a\u00f1os, y quieres participar de la \u201cCopa MILO Chile 2021\u201d, puedes formar equipo con tus amigos y amigas, hermanos, primos, etc. Los equipos deben estar conformados por 3 ni\u00f1as, 3 ni\u00f1os y el s\u00e9ptimo jugador a elecci\u00f3n (2 ni\u00f1as y 2 ni\u00f1os en cancha, el quinto a elecci\u00f3n).<\/p>\n<p>La fase de grupos se disputar\u00e1 los s\u00e1bados, entre 09:30 y 18:30 horas (3 horas m\u00e1ximo por equipo), mientras que los playoffs se jugar\u00e1n los domingos entre 10:00 y 13:00 horas. Cada partido tendr\u00e1 una duraci\u00f3n de 10 minutos por lado y 5 de descanso, y los horarios de inicio pueden variar seg\u00fan la inscripci\u00f3n de equipos.<\/p>\n<p>Para m\u00e1s informaci\u00f3n y conocer en detalle el proceso de inscripci\u00f3n de tu equipo, reglas, bases y premios de la \u201cCopa MILO Chile 2021\u201d ingresa a www.copamilo.cl .<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ya se viene la \u201cCopa MILO Chile 2021\u201d, el campeonato mixto de baby-f\u00fatbol a nivel nacional para ni\u00f1as y ni\u00f1os entre 9 y 12 a\u00f1os. Abarca once ciudades del pa\u00eds y se est\u00e1 desarrollando desde el 25 septiembre hasta el 16 de enero del 2022.<\/p>\n","protected":false},"author":2,"featured_media":21060,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1946],"tags":[4124,3127,6620,6619,2051],"class_list":["post-21058","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lacteos","tag-agricola","tag-agro","tag-baby-futbol","tag-copa-milo-chile-2021","tag-leche"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201cCopa MILO Chile 2021\u201d: vuelve a Osorno el campeonato de baby-f\u00fatbol mixto m\u00e1s grande de Chile - Mundoagropecuario<\/title>\n<meta name=\"description\" content=\"\u201cCopa MILO Chile 2021\u201d, el campeonato mixto de baby-f\u00fatbol a nivel nacional para ni\u00f1as y ni\u00f1os entre 9 y 12 a\u00f1os.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mundoagropecuario.cl\/new\/copa-milo-chile-2021-vuelve-a-osorno-el-campeonato-de-baby-futbol-mixto-mas-grande-de-chile\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cCopa MILO Chile 2021\u201d: vuelve a Osorno el campeonato de baby-f\u00fatbol mixto m\u00e1s grande de Chile - Mundoagropecuario\" \/>\n<meta property=\"og:description\" content=\"\u201cCopa MILO Chile 2021\u201d, el campeonato mixto de baby-f\u00fatbol a nivel nacional para ni\u00f1as y ni\u00f1os entre 9 y 12 a\u00f1os.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mundoagropecuario.cl\/new\/copa-milo-chile-2021-vuelve-a-osorno-el-campeonato-de-baby-futbol-mixto-mas-grande-de-chile\/\" \/>\n<meta property=\"og:site_name\" content=\"Mundoagropecuario\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mundo.agropecuario.3\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-29T14:02:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-01T14:41:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2021\/11\/COPA-MILO.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"872\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mundo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MundoAgropecuar\" \/>\n<meta name=\"twitter:site\" content=\"@MundoAgropecuar\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mundo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/copa-milo-chile-2021-vuelve-a-osorno-el-campeonato-de-baby-futbol-mixto-mas-grande-de-chile\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/copa-milo-chile-2021-vuelve-a-osorno-el-campeonato-de-baby-futbol-mixto-mas-grande-de-chile\\\/\"},\"author\":{\"name\":\"mundo\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/person\\\/4e9f74a82a7dac260eb1c44b7eebeb18\"},\"headline\":\"\u201cCopa MILO Chile 2021\u201d: vuelve a Osorno el campeonato de baby-f\u00fatbol mixto m\u00e1s grande de Chile\",\"datePublished\":\"2021-11-29T14:02:12+00:00\",\"dateModified\":\"2021-12-01T14:41:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/copa-milo-chile-2021-vuelve-a-osorno-el-campeonato-de-baby-futbol-mixto-mas-grande-de-chile\\\/\"},\"wordCount\":429,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/copa-milo-chile-2021-vuelve-a-osorno-el-campeonato-de-baby-futbol-mixto-mas-grande-de-chile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/COPA-MILO.jpg\",\"keywords\":[\"agricola\",\"Agro\",\"baby-f\u00fatbol\",\"Copa MILO Chile 2021\",\"Leche\"],\"articleSection\":[\"L\u00e1cteos\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/copa-milo-chile-2021-vuelve-a-osorno-el-campeonato-de-baby-futbol-mixto-mas-grande-de-chile\\\/\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/copa-milo-chile-2021-vuelve-a-osorno-el-campeonato-de-baby-futbol-mixto-mas-grande-de-chile\\\/\",\"name\":\"\u201cCopa MILO Chile 2021\u201d: vuelve a Osorno el campeonato de baby-f\u00fatbol mixto m\u00e1s grande de Chile - Mundoagropecuario\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/copa-milo-chile-2021-vuelve-a-osorno-el-campeonato-de-baby-futbol-mixto-mas-grande-de-chile\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/copa-milo-chile-2021-vuelve-a-osorno-el-campeonato-de-baby-futbol-mixto-mas-grande-de-chile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/COPA-MILO.jpg\",\"datePublished\":\"2021-11-29T14:02:12+00:00\",\"dateModified\":\"2021-12-01T14:41:05+00:00\",\"description\":\"\u201cCopa MILO Chile 2021\u201d, el campeonato mixto de baby-f\u00fatbol a nivel nacional para ni\u00f1as y ni\u00f1os entre 9 y 12 a\u00f1os.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/copa-milo-chile-2021-vuelve-a-osorno-el-campeonato-de-baby-futbol-mixto-mas-grande-de-chile\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/copa-milo-chile-2021-vuelve-a-osorno-el-campeonato-de-baby-futbol-mixto-mas-grande-de-chile\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/copa-milo-chile-2021-vuelve-a-osorno-el-campeonato-de-baby-futbol-mixto-mas-grande-de-chile\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/COPA-MILO.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/COPA-MILO.jpg\",\"width\":440,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/copa-milo-chile-2021-vuelve-a-osorno-el-campeonato-de-baby-futbol-mixto-mas-grande-de-chile\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cCopa MILO Chile 2021\u201d: vuelve a Osorno el campeonato de baby-f\u00fatbol mixto m\u00e1s grande de Chile\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#website\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/\",\"name\":\"Mundoagropecuario\",\"description\":\"Mundo Agropecuario\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#organization\",\"name\":\"Revista de Agricultura\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/PORTAL-1-1.png\",\"contentUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/PORTAL-1-1.png\",\"width\":1026,\"height\":100,\"caption\":\"Revista de Agricultura\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mundo.agropecuario.3\",\"https:\\\/\\\/x.com\\\/MundoAgropecuar\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/mundo-agropecuario-934009201\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/person\\\/4e9f74a82a7dac260eb1c44b7eebeb18\",\"name\":\"mundo\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/author\\\/mundo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cCopa MILO Chile 2021\u201d: vuelve a Osorno el campeonato de baby-f\u00fatbol mixto m\u00e1s grande de Chile - Mundoagropecuario","description":"\u201cCopa MILO Chile 2021\u201d, el campeonato mixto de baby-f\u00fatbol a nivel nacional para ni\u00f1as y ni\u00f1os entre 9 y 12 a\u00f1os.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mundoagropecuario.cl\/new\/copa-milo-chile-2021-vuelve-a-osorno-el-campeonato-de-baby-futbol-mixto-mas-grande-de-chile\/","og_locale":"es_ES","og_type":"article","og_title":"\u201cCopa MILO Chile 2021\u201d: vuelve a Osorno el campeonato de baby-f\u00fatbol mixto m\u00e1s grande de Chile - Mundoagropecuario","og_description":"\u201cCopa MILO Chile 2021\u201d, el campeonato mixto de baby-f\u00fatbol a nivel nacional para ni\u00f1as y ni\u00f1os entre 9 y 12 a\u00f1os.","og_url":"https:\/\/www.mundoagropecuario.cl\/new\/copa-milo-chile-2021-vuelve-a-osorno-el-campeonato-de-baby-futbol-mixto-mas-grande-de-chile\/","og_site_name":"Mundoagropecuario","article_publisher":"https:\/\/www.facebook.com\/mundo.agropecuario.3","article_published_time":"2021-11-29T14:02:12+00:00","article_modified_time":"2021-12-01T14:41:05+00:00","og_image":[{"width":960,"height":872,"url":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2021\/11\/COPA-MILO.jpg","type":"image\/jpeg"}],"author":"mundo","twitter_card":"summary_large_image","twitter_creator":"@MundoAgropecuar","twitter_site":"@MundoAgropecuar","twitter_misc":{"Escrito por":"mundo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mundoagropecuario.cl\/new\/copa-milo-chile-2021-vuelve-a-osorno-el-campeonato-de-baby-futbol-mixto-mas-grande-de-chile\/#article","isPartOf":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/copa-milo-chile-2021-vuelve-a-osorno-el-campeonato-de-baby-futbol-mixto-mas-grande-de-chile\/"},"author":{"name":"mundo","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/person\/4e9f74a82a7dac260eb1c44b7eebeb18"},"headline":"\u201cCopa MILO Chile 2021\u201d: vuelve a Osorno el campeonato de baby-f\u00fatbol mixto m\u00e1s grande de Chile","datePublished":"2021-11-29T14:02:12+00:00","dateModified":"2021-12-01T14:41:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/copa-milo-chile-2021-vuelve-a-osorno-el-campeonato-de-baby-futbol-mixto-mas-grande-de-chile\/"},"wordCount":429,"publisher":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#organization"},"image":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/copa-milo-chile-2021-vuelve-a-osorno-el-campeonato-de-baby-futbol-mixto-mas-grande-de-chile\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2021\/11\/COPA-MILO.jpg","keywords":["agricola","Agro","baby-f\u00fatbol","Copa MILO Chile 2021","Leche"],"articleSection":["L\u00e1cteos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.mundoagropecuario.cl\/new\/copa-milo-chile-2021-vuelve-a-osorno-el-campeonato-de-baby-futbol-mixto-mas-grande-de-chile\/","url":"https:\/\/www.mundoagropecuario.cl\/new\/copa-milo-chile-2021-vuelve-a-osorno-el-campeonato-de-baby-futbol-mixto-mas-grande-de-chile\/","name":"\u201cCopa MILO Chile 2021\u201d: vuelve a Osorno el campeonato de baby-f\u00fatbol mixto m\u00e1s grande de Chile - Mundoagropecuario","isPartOf":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/copa-milo-chile-2021-vuelve-a-osorno-el-campeonato-de-baby-futbol-mixto-mas-grande-de-chile\/#primaryimage"},"image":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/copa-milo-chile-2021-vuelve-a-osorno-el-campeonato-de-baby-futbol-mixto-mas-grande-de-chile\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2021\/11\/COPA-MILO.jpg","datePublished":"2021-11-29T14:02:12+00:00","dateModified":"2021-12-01T14:41:05+00:00","description":"\u201cCopa MILO Chile 2021\u201d, el campeonato mixto de baby-f\u00fatbol a nivel nacional para ni\u00f1as y ni\u00f1os entre 9 y 12 a\u00f1os.","breadcrumb":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/copa-milo-chile-2021-vuelve-a-osorno-el-campeonato-de-baby-futbol-mixto-mas-grande-de-chile\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mundoagropecuario.cl\/new\/copa-milo-chile-2021-vuelve-a-osorno-el-campeonato-de-baby-futbol-mixto-mas-grande-de-chile\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoagropecuario.cl\/new\/copa-milo-chile-2021-vuelve-a-osorno-el-campeonato-de-baby-futbol-mixto-mas-grande-de-chile\/#primaryimage","url":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2021\/11\/COPA-MILO.jpg","contentUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2021\/11\/COPA-MILO.jpg","width":440,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.mundoagropecuario.cl\/new\/copa-milo-chile-2021-vuelve-a-osorno-el-campeonato-de-baby-futbol-mixto-mas-grande-de-chile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.mundoagropecuario.cl\/new\/"},{"@type":"ListItem","position":2,"name":"\u201cCopa MILO Chile 2021\u201d: vuelve a Osorno el campeonato de baby-f\u00fatbol mixto m\u00e1s grande de Chile"}]},{"@type":"WebSite","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#website","url":"https:\/\/www.mundoagropecuario.cl\/new\/","name":"Mundoagropecuario","description":"Mundo Agropecuario","publisher":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mundoagropecuario.cl\/new\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#organization","name":"Revista de Agricultura","url":"https:\/\/www.mundoagropecuario.cl\/new\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/logo\/image\/","url":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/11\/PORTAL-1-1.png","contentUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/11\/PORTAL-1-1.png","width":1026,"height":100,"caption":"Revista de Agricultura"},"image":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mundo.agropecuario.3","https:\/\/x.com\/MundoAgropecuar","https:\/\/www.linkedin.com\/in\/mundo-agropecuario-934009201\/"]},{"@type":"Person","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/person\/4e9f74a82a7dac260eb1c44b7eebeb18","name":"mundo","url":"https:\/\/www.mundoagropecuario.cl\/new\/author\/mundo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts\/21058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/comments?post=21058"}],"version-history":[{"count":1,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts\/21058\/revisions"}],"predecessor-version":[{"id":21061,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts\/21058\/revisions\/21061"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/media\/21060"}],"wp:attachment":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/media?parent=21058"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/categories?post=21058"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/tags?post=21058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}