{"id":18340,"date":"2021-03-19T12:08:59","date_gmt":"2021-03-19T15:08:59","guid":{"rendered":"https:\/\/www.mundoagropecuario.cl\/new\/?p=18340"},"modified":"2021-03-23T11:55:18","modified_gmt":"2021-03-23T14:55:18","slug":"ministra-destaco-el-trabajo-del-consorcio-tecnologico-de-la-fruta-de-asoex-para-el-desarrollo-de-frutas-100-chilenas","status":"publish","type":"post","link":"https:\/\/www.mundoagropecuario.cl\/new\/ministra-destaco-el-trabajo-del-consorcio-tecnologico-de-la-fruta-de-asoex-para-el-desarrollo-de-frutas-100-chilenas\/","title":{"rendered":"Ministra destac\u00f3 el trabajo del Consorcio Tecnol\u00f3gico de la Fruta de ASOEX para el desarrollo de frutas 100% chilenas"},"content":{"rendered":"<blockquote>\n<h2><span style=\"color: #003300;\">La Ministra de Agricultura, Mar\u00eda Emilia Undurraga, visit\u00f3 el Huerto Santa Rosa de Vida Produce Company en Llay-Llay, para conocer el trabajo que desarrolla el Consorcio Tecnol\u00f3gico de la Fruta de ASOEX en lo que se refiere a nuevas variedades chilenas de uvas de mesa.\u00a0<\/span><\/h2>\n<\/blockquote>\n<p>&#8220;El poder estar ac\u00e1 y ver el esfuerzo de tantos a\u00f1os es gratificante. Los agricultores estamos acostumbrados a esto de esperar los ciclos biol\u00f3gicos, lo que es parte tambi\u00e9n importante de respetar el medioambiente, y este clima, que en ocasiones nos juega malas pasadas. Por ello, es tan importante poder vincularnos para que, a trav\u00e9s de la investigaci\u00f3n, avancemos juntos. Para que la investigaci\u00f3n no qued\u00e9 en las universidades, sino que baje a la realidad de los productores&#8221;, precis\u00f3 la autoridad.<\/p>\n<p>&#8220;La fruticultura no es s\u00f3lo una actividad econ\u00f3mica, que se puede analizar con cifras de exportaciones o de empleo, que por cierto son muy relevantes, sino que tambi\u00e9n es el coraz\u00f3n del desarrollo de muchas regiones, de muchas comunas, y eso a nosotros como Ministerio nos impulsa a trabajar con mucha m\u00e1s fuerza para que la innovaci\u00f3n, la tecnolog\u00eda llegue a todos esos rincones. Ustedes como gremio, nosotros como Ministerio y Corfo, dentro de lo p\u00fablico, y la universidad, hemos entendido que si trabajamos en coordinaci\u00f3n podemos llegar con mejores soluciones a un mundo que est\u00e1 cambiando&#8221;, agreg\u00f3.<\/p>\n<p>La ministra destac\u00f3, asimismo, la relevancia que tiene desarrollar fruta mirando al consumidor. &#8220;Ya no estamos frente a una agricultura que produce s\u00f3lo cantidad, sino que produce mirando a quien consume, y aunque parezca l\u00f3gico antes no era as\u00ed, se produc\u00eda lo que se ten\u00eda y despu\u00e9s se vend\u00eda. Hoy estamos entendiendo que tenemos que ir al consumidor para producir aquello que tendr\u00e1 mayor valor en el futuro&#8221;.<\/p>\n<p><a href=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2021\/03\/Asoex-ministra--scaled.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-18342 alignright\" src=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2021\/03\/Asoex-ministra--586x391.jpeg\" alt=\"\" width=\"469\" height=\"303\" \/><\/a>Por su parte,<span style=\"color: #003300;\"> Ronald Bown, Presidente de ASOEX<\/span> y del Consorcio Tecnol\u00f3gico de la Fruta, indic\u00f3: &#8220;Nos alegra poder mostrar a la Ministra los avances de nuestros programas de mejoramiento gen\u00e9tico, especialmente el de uva de mesa, un sector que desde hace alg\u00fan tiempo se ha visto complicado por factores clim\u00e1ticos adversos como las lluvias, as\u00ed como tambi\u00e9n la sequ\u00eda que afecta al pa\u00eds y una mayor competencia en los mercados de destino. Por ello, sabemos que las selecciones avanzadas de uvas de mesa que tenemos hasta ahora, pueden ser claves para mejorar la competitividad de esta industria, ya que, est\u00e1n desarrolladas seg\u00fan las caracter\u00edsticas de producci\u00f3n, post cosecha y calidad que requiere Chile,\u00a0 y las caracter\u00edsticas de calibre, color, sabor y crocancia que piden los mercados internacionales&#8221;.<\/p>\n<p>Agreg\u00f3: \u201cComo Consorcio llevamos cerca de 15 a\u00f1os trabajando en el desarrollo de frutas para Chile. Llevamos adelante cinco programas de mejoramiento gen\u00e9tico en cerezas, carozos (duraznos, ciruelos y nectarines), frambuesas, manzanas y uvas de mesa. Contamos para ello con el apoyo de Corfo, la Universidad Cat\u00f3lica de Chile e INIA. Gracias a lo cual ya hemos logrado selecciones avanzadas muy prometedoras, adem\u00e1s de ser los creadores de las primeras tres variedades de frambuesas de Chile, conocidas como Santas, las cuales est\u00e1n siendo plantadas por peque\u00f1os agricultores del pa\u00eds y comunidades ind\u00edgenas de La Araucan\u00eda, as\u00ed como tambi\u00e9n en otros pa\u00edses de Europa y Sudam\u00e9rica&#8221;.<\/p>\n<p>En tanto, <span style=\"color: #003300;\">Pablo Terrazas, vicepresidente de Corfo,<\/span> se\u00f1al\u00f3 que \u201cno es posible pensar una econom\u00eda robusta, sin el fortalecimiento de sus empresas a trav\u00e9s del desarrollo tecnol\u00f3gico e innovaci\u00f3n. Para ello Corfo, a trav\u00e9s de instrumentos como los Consorcios Tecnol\u00f3gicos, promueve la colaboraci\u00f3n de todos los actores de las distintas cadenas productivas, como es la fruticultura, en base a desaf\u00edos comunes para la generaci\u00f3n de nuevo conocimiento con visi\u00f3n de mercado. Actualmente, existen ocho de estas iniciativas en el sector frut\u00edcola, que consideran desarrollos y adaptaci\u00f3n de nuevas variedades, as\u00ed como generaci\u00f3n de paquetes tecnol\u00f3gicos para cada una. En particular son doce las especies frutales que est\u00e1n siendo parte de los programas, registrando a la fecha nueve variedades nuevas entre nectarines, duraznos, uva de mesa y frambuesa, con cerca de 1.000 Ha en producci\u00f3n, m\u00e1s de 40 MM USD de ingreso por exportaciones y miles de empleos asociados, resultados que se van incrementando a\u00f1o a a\u00f1o\u201d.<\/p>\n<p>En el mismo sentido, Macarena Aljaro, Directora de Programas Tecnol\u00f3gicos de Corfo, destac\u00f3 el trabajo del Consorcio, el cual tendr\u00e1 un gran impacto en la fruticultura del pa\u00eds. &#8220;El impacto social que tiene la agricultura es tremendo. El desarrollo de los territorios est\u00e1 vinculado necesariamente al desarrollo agr\u00edcola, donde la generaci\u00f3n de innovaci\u00f3n adquiere cada vez m\u00e1s importancia, y es donde Corfo viene apoyando al sector desde hace ya muchos a\u00f1os. Hoy, vemos los frutos de este trabajo mancomunado, y que sin dudas tendr\u00e1 un impacto positivo para la agricultura, los y las agricultores, y para el pa\u00eds&#8221;.<\/p>\n<p><strong><span style=\"color: #003300;\">Uvas de Mesa<\/span><\/strong><\/p>\n<p>Respecto al desarrollo de uvas de mesa, Ronald Bown explic\u00f3 que se est\u00e1 buscando un ideotipo consensuado entre la academia y la industria. \u201cNuestro objetivo es desarrollar variedades para la exportaci\u00f3n de frutas, y que entre sus caracter\u00edsticas sean sin semilla, con colores definidos y de bajo costo productivo como es que requieran menor cantidad de mano de obra, as\u00ed como tambi\u00e9n que tengan buena poscosecha, aspectos en los cuales vamos muy bien encaminados\u201d.<\/p>\n<p>&#8220;Hoy a la ministra le mostramos 17 selecciones que hemos generado en el marco de este programa, algunas de las cuales se vislumbran con muchas posibilidades de convertirse en variedades. Adem\u00e1s, pudimos mostrarle algunos avances que tenemos en variedades con resistencia a hongos, como es el caso del o\u00eddio, lo cual, va en estrecha relaci\u00f3n a la sustentabilidad, ya que, significar\u00e1 contar con uvas que requieran menos aplicaciones, pero adem\u00e1s frutas con menores costos para los productores&#8221;, explic\u00f3.<\/p>\n<p>Bown adelant\u00f3 que, actualmente, se est\u00e1 trabajando en el proceso de registro en Chile y patentamiento en Estados Unidos, de una variedad de uva rosado, la cual ya ha sido probada en 6 localidades del pa\u00eds, desde Copiap\u00f3 a Rancagua, con muy buenos resultados. &#8220;Se trata de una selecci\u00f3n crocante, color rojo intenso, una larga vida en post cosecha y muy buen sabor&#8221;, coment\u00f3.<\/p>\n<p>Cabe destacar que en esta visita ademas participaron, el Seremi de Agricultura de la Regi\u00f3n de Valpara\u00edso, Humberto Lepe; el Director de INIA La Cruz, Patricio Fuenzalida; adem\u00e1s del Gerente del Consorcio Tecnol\u00f3gico de la Fruta, Sergio Maureira; la Coordinadora de la entidad, Mar\u00eda Fernanda \u00c1lvarez, Patricio Arce, Director T\u00e9cnico del Programa de Mejoramiento Gen\u00e9tico de Uva de Mesa y el Asesor Rodrigo Sapiain, quien est\u00e1 abocado a realizar los protocolos de manejo para entregar informaci\u00f3n t\u00e9cnica de manejo, y producci\u00f3n a quienes adquieran las nuevas variedades.<\/p>\n<p><strong><span style=\"color: #003300;\">Frambuesas<\/span><\/strong><\/p>\n<p>La secretaria de estado, junto a destacar el trabajo que est\u00e1 desarrollando el Consorcio Tecnol\u00f3gico de la Fruta para lograr uvas de mesa chilenas pensando en los consumidores del mundo, tambi\u00e9n tuvo la oportunidad de ver las primeras variedades de frambuesas chilenas desarrolladas por el Programa de Mejoramiento Gen\u00e9tico del Frambueso, las cuales dijo tendr\u00e1n un impacto importante para mejorar la producci\u00f3n y calidad de vida de los peque\u00f1os productores y la agricultura familiar campesina.<\/p>\n<p><a href=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2021\/03\/Franbuezas--scaled.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-18343 alignleft\" src=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2021\/03\/Franbuezas--586x391.jpeg\" alt=\"\" width=\"586\" height=\"391\" srcset=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2021\/03\/Franbuezas--586x391.jpeg 586w, https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2021\/03\/Franbuezas--1024x682.jpeg 1024w, https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2021\/03\/Franbuezas--768x512.jpeg 768w, https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2021\/03\/Franbuezas--scaled.jpeg 601w\" sizes=\"auto, (max-width: 586px) 100vw, 586px\" \/><\/a>&#8220;El trabajo que est\u00e1n desarrollando en frambuesas tendr\u00e1 un gran impacto en las regiones con menos ventajas dentro del pa\u00eds, donde hay gran presencia de comunidades ind\u00edgenas, peque\u00f1os productores y agricultura familiar campesina, lo cual queremos promover. Muchas veces pensamos en si se trata de fruta de exportaci\u00f3n o para el mercado interno, que si se trata de los grandes o peque\u00f1os productores, pero en la agricultura cabemos todos, por ello, es muy importante desarrollar la industria con esa visi\u00f3n&#8221;.<\/p>\n<p>El PMG del Frambueso, es dirigido por Marina Gamberdalla, acad\u00e9mica e investigadora de la Universidad Cat\u00f3lica de Chile, quien desarroll\u00f3 las primeras tres variedades de frambuesas de Chile, conocidas como las &#8220;Santas&#8221; del Consorcio.<\/p>\n<p>Al respecto, Marina Gambardella, Directora T\u00e9cnica del PMG del Frambueso del Consorcio, indic\u00f3:\u201cHemos ido avanzando en desarrollar nuevas variedades, que tienen que ser mucho mejor que las anteriores, lo cual significa m\u00e1s esfuerzo y trabajo. Llevamos unos cuatro a\u00f1os en esta nueva etapa, y tenemos selecciones bien interesantes que esperamos sacar al mercado muy pronto&#8221;.<\/p>\n<p>En cuanto a las caracter\u00edsticas de estos nuevos desarrollos, la profesional destac\u00f3 que, &#8220;adem\u00e1s de mantener la condici\u00f3n de la fruta de buena calidad, buen tama\u00f1o y alta producci\u00f3n, estamos apuntando a desarrollos resistentes a estr\u00e9s bi\u00f3tico y abi\u00f3tico. Entonces estamos implementando inoculaciones con hongos para saber si \u00e9stas tienen la resistencia al ataque de ara\u00f1ita roja (Tetranychus urticae) o el hongo Phytium. Adem\u00e1s, estamos apuntando a condiciones de calor y resistencia al estr\u00e9s h\u00eddrico, lo cual, es una necesidad frente al Cambio Clim\u00e1tico&#8221;, observ\u00f3.<\/p>\n<p>Finalmente, cabe destacar que la Ministra de Agricultura, al terminar antes de terminar su visita hizo una invitaci\u00f3n a seguir trabajando en forma coordinada entre el sector p\u00fablico, el mundo privado y la academia. &#8220;Cuenten con nosotros como Ministerio de Agricultura para ello, es parte de nuestro trabajo, que no es s\u00f3lo hacer pol\u00edticas p\u00fablicas, sino que tambi\u00e9n promover este tipo de vinculaciones para poder llegar a mejorar la calidad de vida de mucha gente que vive en torno a la fruticultura. Queremos estar como pa\u00edses orgullosos de eso, y tambi\u00e9n de adaptarnos a los diferentes desaf\u00edos, como es el cambio clim\u00e1tico, y las nuevas condiciones de consumo&#8221;, cerr\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Ministra de Agricultura, Mar\u00eda Emilia Undurraga visit\u00f3 el Huerto Santa Rosa, para conocer el trabajo que desarrolla el Consorcio Tecnol\u00f3gico de la Fruta de ASOEX<\/p>\n","protected":false},"author":2,"featured_media":18341,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1945],"tags":[2177,4292,2245,2035,5200,2715],"class_list":["post-18340","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agricultura","tag-asoex","tag-frambuezas","tag-frutas","tag-minagri","tag-ministra-undurraga","tag-ronald-bown"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ministra destac\u00f3 el trabajo del Consorcio Tecnol\u00f3gico de la Fruta de ASOEX para el desarrollo de frutas 100% chilenas - Mundoagropecuario<\/title>\n<meta name=\"description\" content=\"Ministra visit\u00f3 el Huerto Santa Rosa, para conocer el trabajo que desarrolla el Consorcio Tecnol\u00f3gico de la Fruta de ASOEX\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mundoagropecuario.cl\/new\/ministra-destaco-el-trabajo-del-consorcio-tecnologico-de-la-fruta-de-asoex-para-el-desarrollo-de-frutas-100-chilenas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ministra destac\u00f3 el trabajo del Consorcio Tecnol\u00f3gico de la Fruta de ASOEX para el desarrollo de frutas 100% chilenas - Mundoagropecuario\" \/>\n<meta property=\"og:description\" content=\"Ministra visit\u00f3 el Huerto Santa Rosa, para conocer el trabajo que desarrolla el Consorcio Tecnol\u00f3gico de la Fruta de ASOEX\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mundoagropecuario.cl\/new\/ministra-destaco-el-trabajo-del-consorcio-tecnologico-de-la-fruta-de-asoex-para-el-desarrollo-de-frutas-100-chilenas\/\" \/>\n<meta property=\"og:site_name\" content=\"Mundoagropecuario\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mundo.agropecuario.3\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-19T15:08:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-23T14:55:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2021\/03\/ministra-asoex-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mundo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MundoAgropecuar\" \/>\n<meta name=\"twitter:site\" content=\"@MundoAgropecuar\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mundo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/ministra-destaco-el-trabajo-del-consorcio-tecnologico-de-la-fruta-de-asoex-para-el-desarrollo-de-frutas-100-chilenas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/ministra-destaco-el-trabajo-del-consorcio-tecnologico-de-la-fruta-de-asoex-para-el-desarrollo-de-frutas-100-chilenas\\\/\"},\"author\":{\"name\":\"mundo\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/person\\\/4e9f74a82a7dac260eb1c44b7eebeb18\"},\"headline\":\"Ministra destac\u00f3 el trabajo del Consorcio Tecnol\u00f3gico de la Fruta de ASOEX para el desarrollo de frutas 100% chilenas\",\"datePublished\":\"2021-03-19T15:08:59+00:00\",\"dateModified\":\"2021-03-23T14:55:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/ministra-destaco-el-trabajo-del-consorcio-tecnologico-de-la-fruta-de-asoex-para-el-desarrollo-de-frutas-100-chilenas\\\/\"},\"wordCount\":1674,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/ministra-destaco-el-trabajo-del-consorcio-tecnologico-de-la-fruta-de-asoex-para-el-desarrollo-de-frutas-100-chilenas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/ministra-asoex-scaled.jpeg\",\"keywords\":[\"Asoex\",\"FRAMBUEZAS\",\"Frutas\",\"Minagri\",\"Ministra Undurraga\",\"Ronald Bown\"],\"articleSection\":[\"Agricultura\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/ministra-destaco-el-trabajo-del-consorcio-tecnologico-de-la-fruta-de-asoex-para-el-desarrollo-de-frutas-100-chilenas\\\/\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/ministra-destaco-el-trabajo-del-consorcio-tecnologico-de-la-fruta-de-asoex-para-el-desarrollo-de-frutas-100-chilenas\\\/\",\"name\":\"Ministra destac\u00f3 el trabajo del Consorcio Tecnol\u00f3gico de la Fruta de ASOEX para el desarrollo de frutas 100% chilenas - Mundoagropecuario\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/ministra-destaco-el-trabajo-del-consorcio-tecnologico-de-la-fruta-de-asoex-para-el-desarrollo-de-frutas-100-chilenas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/ministra-destaco-el-trabajo-del-consorcio-tecnologico-de-la-fruta-de-asoex-para-el-desarrollo-de-frutas-100-chilenas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/ministra-asoex-scaled.jpeg\",\"datePublished\":\"2021-03-19T15:08:59+00:00\",\"dateModified\":\"2021-03-23T14:55:18+00:00\",\"description\":\"Ministra visit\u00f3 el Huerto Santa Rosa, para conocer el trabajo que desarrolla el Consorcio Tecnol\u00f3gico de la Fruta de ASOEX\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/ministra-destaco-el-trabajo-del-consorcio-tecnologico-de-la-fruta-de-asoex-para-el-desarrollo-de-frutas-100-chilenas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/ministra-destaco-el-trabajo-del-consorcio-tecnologico-de-la-fruta-de-asoex-para-el-desarrollo-de-frutas-100-chilenas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/ministra-destaco-el-trabajo-del-consorcio-tecnologico-de-la-fruta-de-asoex-para-el-desarrollo-de-frutas-100-chilenas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/ministra-asoex-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/ministra-asoex-scaled.jpeg\",\"width\":600,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/ministra-destaco-el-trabajo-del-consorcio-tecnologico-de-la-fruta-de-asoex-para-el-desarrollo-de-frutas-100-chilenas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ministra destac\u00f3 el trabajo del Consorcio Tecnol\u00f3gico de la Fruta de ASOEX para el desarrollo de frutas 100% chilenas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#website\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/\",\"name\":\"Mundoagropecuario\",\"description\":\"Mundo Agropecuario\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#organization\",\"name\":\"Revista de Agricultura\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/PORTAL-1-1.png\",\"contentUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/PORTAL-1-1.png\",\"width\":1026,\"height\":100,\"caption\":\"Revista de Agricultura\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mundo.agropecuario.3\",\"https:\\\/\\\/x.com\\\/MundoAgropecuar\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/mundo-agropecuario-934009201\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/person\\\/4e9f74a82a7dac260eb1c44b7eebeb18\",\"name\":\"mundo\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/author\\\/mundo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ministra destac\u00f3 el trabajo del Consorcio Tecnol\u00f3gico de la Fruta de ASOEX para el desarrollo de frutas 100% chilenas - Mundoagropecuario","description":"Ministra visit\u00f3 el Huerto Santa Rosa, para conocer el trabajo que desarrolla el Consorcio Tecnol\u00f3gico de la Fruta de ASOEX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mundoagropecuario.cl\/new\/ministra-destaco-el-trabajo-del-consorcio-tecnologico-de-la-fruta-de-asoex-para-el-desarrollo-de-frutas-100-chilenas\/","og_locale":"es_ES","og_type":"article","og_title":"Ministra destac\u00f3 el trabajo del Consorcio Tecnol\u00f3gico de la Fruta de ASOEX para el desarrollo de frutas 100% chilenas - Mundoagropecuario","og_description":"Ministra visit\u00f3 el Huerto Santa Rosa, para conocer el trabajo que desarrolla el Consorcio Tecnol\u00f3gico de la Fruta de ASOEX","og_url":"https:\/\/www.mundoagropecuario.cl\/new\/ministra-destaco-el-trabajo-del-consorcio-tecnologico-de-la-fruta-de-asoex-para-el-desarrollo-de-frutas-100-chilenas\/","og_site_name":"Mundoagropecuario","article_publisher":"https:\/\/www.facebook.com\/mundo.agropecuario.3","article_published_time":"2021-03-19T15:08:59+00:00","article_modified_time":"2021-03-23T14:55:18+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2021\/03\/ministra-asoex-scaled.jpeg","type":"image\/jpeg"}],"author":"mundo","twitter_card":"summary_large_image","twitter_creator":"@MundoAgropecuar","twitter_site":"@MundoAgropecuar","twitter_misc":{"Escrito por":"mundo","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mundoagropecuario.cl\/new\/ministra-destaco-el-trabajo-del-consorcio-tecnologico-de-la-fruta-de-asoex-para-el-desarrollo-de-frutas-100-chilenas\/#article","isPartOf":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/ministra-destaco-el-trabajo-del-consorcio-tecnologico-de-la-fruta-de-asoex-para-el-desarrollo-de-frutas-100-chilenas\/"},"author":{"name":"mundo","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/person\/4e9f74a82a7dac260eb1c44b7eebeb18"},"headline":"Ministra destac\u00f3 el trabajo del Consorcio Tecnol\u00f3gico de la Fruta de ASOEX para el desarrollo de frutas 100% chilenas","datePublished":"2021-03-19T15:08:59+00:00","dateModified":"2021-03-23T14:55:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/ministra-destaco-el-trabajo-del-consorcio-tecnologico-de-la-fruta-de-asoex-para-el-desarrollo-de-frutas-100-chilenas\/"},"wordCount":1674,"publisher":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#organization"},"image":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/ministra-destaco-el-trabajo-del-consorcio-tecnologico-de-la-fruta-de-asoex-para-el-desarrollo-de-frutas-100-chilenas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2021\/03\/ministra-asoex-scaled.jpeg","keywords":["Asoex","FRAMBUEZAS","Frutas","Minagri","Ministra Undurraga","Ronald Bown"],"articleSection":["Agricultura"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.mundoagropecuario.cl\/new\/ministra-destaco-el-trabajo-del-consorcio-tecnologico-de-la-fruta-de-asoex-para-el-desarrollo-de-frutas-100-chilenas\/","url":"https:\/\/www.mundoagropecuario.cl\/new\/ministra-destaco-el-trabajo-del-consorcio-tecnologico-de-la-fruta-de-asoex-para-el-desarrollo-de-frutas-100-chilenas\/","name":"Ministra destac\u00f3 el trabajo del Consorcio Tecnol\u00f3gico de la Fruta de ASOEX para el desarrollo de frutas 100% chilenas - Mundoagropecuario","isPartOf":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/ministra-destaco-el-trabajo-del-consorcio-tecnologico-de-la-fruta-de-asoex-para-el-desarrollo-de-frutas-100-chilenas\/#primaryimage"},"image":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/ministra-destaco-el-trabajo-del-consorcio-tecnologico-de-la-fruta-de-asoex-para-el-desarrollo-de-frutas-100-chilenas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2021\/03\/ministra-asoex-scaled.jpeg","datePublished":"2021-03-19T15:08:59+00:00","dateModified":"2021-03-23T14:55:18+00:00","description":"Ministra visit\u00f3 el Huerto Santa Rosa, para conocer el trabajo que desarrolla el Consorcio Tecnol\u00f3gico de la Fruta de ASOEX","breadcrumb":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/ministra-destaco-el-trabajo-del-consorcio-tecnologico-de-la-fruta-de-asoex-para-el-desarrollo-de-frutas-100-chilenas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mundoagropecuario.cl\/new\/ministra-destaco-el-trabajo-del-consorcio-tecnologico-de-la-fruta-de-asoex-para-el-desarrollo-de-frutas-100-chilenas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoagropecuario.cl\/new\/ministra-destaco-el-trabajo-del-consorcio-tecnologico-de-la-fruta-de-asoex-para-el-desarrollo-de-frutas-100-chilenas\/#primaryimage","url":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2021\/03\/ministra-asoex-scaled.jpeg","contentUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2021\/03\/ministra-asoex-scaled.jpeg","width":600,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.mundoagropecuario.cl\/new\/ministra-destaco-el-trabajo-del-consorcio-tecnologico-de-la-fruta-de-asoex-para-el-desarrollo-de-frutas-100-chilenas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.mundoagropecuario.cl\/new\/"},{"@type":"ListItem","position":2,"name":"Ministra destac\u00f3 el trabajo del Consorcio Tecnol\u00f3gico de la Fruta de ASOEX para el desarrollo de frutas 100% chilenas"}]},{"@type":"WebSite","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#website","url":"https:\/\/www.mundoagropecuario.cl\/new\/","name":"Mundoagropecuario","description":"Mundo Agropecuario","publisher":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mundoagropecuario.cl\/new\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#organization","name":"Revista de Agricultura","url":"https:\/\/www.mundoagropecuario.cl\/new\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/logo\/image\/","url":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/11\/PORTAL-1-1.png","contentUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/11\/PORTAL-1-1.png","width":1026,"height":100,"caption":"Revista de Agricultura"},"image":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mundo.agropecuario.3","https:\/\/x.com\/MundoAgropecuar","https:\/\/www.linkedin.com\/in\/mundo-agropecuario-934009201\/"]},{"@type":"Person","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/person\/4e9f74a82a7dac260eb1c44b7eebeb18","name":"mundo","url":"https:\/\/www.mundoagropecuario.cl\/new\/author\/mundo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts\/18340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/comments?post=18340"}],"version-history":[{"count":1,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts\/18340\/revisions"}],"predecessor-version":[{"id":18344,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts\/18340\/revisions\/18344"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/media\/18341"}],"wp:attachment":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/media?parent=18340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/categories?post=18340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/tags?post=18340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}