{"id":15569,"date":"2020-01-21T10:40:55","date_gmt":"2020-01-21T13:40:55","guid":{"rendered":"http:\/\/www.mundoagropecuario.cl\/new\/?p=15569"},"modified":"2020-01-22T11:03:27","modified_gmt":"2020-01-22T14:03:27","slug":"los-rios-retoma-exportaciones-de-carne-bovina-a-china","status":"publish","type":"post","link":"https:\/\/www.mundoagropecuario.cl\/new\/los-rios-retoma-exportaciones-de-carne-bovina-a-china\/","title":{"rendered":"Los R\u00edos retoma exportaciones de carne bovina a China"},"content":{"rendered":"\n<ul class=\"wp-block-gallery columns-0 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Despu\u00e9s de 5 a\u00f1os, la planta faenadora de Valdivia realiz\u00f3 un nuevo env\u00edo hacia el mercado asi\u00e1tico. Autoridades sellaron junto al SAG container con m\u00e1s de 24 mil kilos de carne congelada (Mundo Agropecuario).<\/em><\/p>\n\n\n\n<p>Autoridades de la regi\u00f3n de Los R\u00edos participaron junto al Servicio Agr\u00edcola y Ganadero (SAG) en el sellado de un container que transportaba 24 mil 867 kilos de diversos cortes de carne bovina congelada hacia China, retomando as\u00ed el proceso exportador que se encontraba detenido desde el 2015 en la zona.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/01\/IMG_20200109_155602-1-1024x768.jpg\" alt=\"\" class=\"wp-image-15571\" srcset=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/01\/IMG_20200109_155602-1-1024x768.jpg 1024w, https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/01\/IMG_20200109_155602-1-586x440.jpg 586w, https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/01\/IMG_20200109_155602-1-768x576.jpg 768w, https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/01\/IMG_20200109_155602-1.jpg 533w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>La jornada se desarroll\u00f3 en la planta faenadora de Valdivia, de Carnes \u00d1uble, la cual se habilit\u00f3 el 2 de diciembre del 2019 para el mercado de China, seg\u00fan detall\u00f3 el Director Regional del SAG, Jorge Oltra. \u201cComo Servicios queremos apoyar el proceso exportador, resguardando siempre el estatus sanitario que poseemos, ya que es la principal puerta de entrada a los mercados m\u00e1s exigentes del mundo. Por ello, el equipo de inspecci\u00f3n SAG fue el responsable de realizar la verificaci\u00f3n del cumplimiento de todos los requisitos para China, previo a la firma del Certificado Zoosanitario de Exportaci\u00f3n, trabajo que permite sellar este env\u00edo\u201d, puntualiz\u00f3.<\/p>\n\n\n\n<p>El Intendente de Los R\u00edos, C\u00e9sar Asenjo, sostuvo que \u201cnuestra regi\u00f3n tiene una marcada vocaci\u00f3n silvoagropecuaria que debemos seguir potenciando. Tenemos atributos naturales \u00f3ptimos para la crianza de ganado bovino, por ello que esta primera exportaci\u00f3n de carne, apoyada por el Ministerio de Agricultura a una potencia mundial como China, es un gran paso para el desarrollo agr\u00edcola. Como Gobierno del Presidente Sebasti\u00e1n Pi\u00f1era, estamos comprometidos con fomentar la econom\u00eda y hoy reafirmamos ese compromiso, buscando apoyar a la empresa local, para tener m\u00e1s y mejores empleos, para que nuestros habitantes mejoren su calidad de vida y juntos hagamos de Los R\u00edos una potencia agr\u00edcola y una mejor regi\u00f3n para vivir\u201d.<\/p>\n\n\n\n<p>De acuerdo al bolet\u00edn de carne bovina de diciembre 2019 de ODEPA, el volumen de exportaci\u00f3n de carne bovina se increment\u00f3 un 95,3% en el per\u00edodo enero-noviembre 2019\/18. El total de carne exportada representa 17.135 toneladas, considerado un alza fuerte y con un valor FOB de 70,5 millones de USD. Al igual que meses anteriores, China corresponde al principal destino de los env\u00edos, con una participaci\u00f3n del 77% del valor durante 2019.<\/p>\n\n\n\n<p>As\u00ed se evidencia que el gigante asi\u00e1tico es un destino para la carne bovina nacional que crece sostenidamente, lo cual est\u00e1 dado por el aumento de la demanda de productos alimenticios para el consumo interno y donde la tendencia es crecer en sus importaciones de materias primas y alimentos para producci\u00f3n industrial.<\/p>\n\n\n\n<p>\u201cAbrir nuevos y mejores mercados para el sector silvoagropecuario es uno de los desaf\u00edos asumidos por el Ministerio de Agricultura. Queremos que cada d\u00eda una mayor cantidad de productores, independientemente de su tama\u00f1o, cumplan los requisitos de los mercados y as\u00ed puedan ser parte de la cadena productiva\u201d, indic\u00f3 la Seremi de Agricultura, Moira Henzi.<\/p>\n\n\n\n<p>Como apoyo al proceso de certificaci\u00f3n de exportaciones de carne bovina, el 2019 el SAG implement\u00f3 el Sistema Nacional de Control Predial (SINAP), cuyo objetivo es agilizar los env\u00edos a los principales mercados de destino. SINAP entrega garant\u00edas respecto del manejo de anab\u00f3licos, de f\u00e1rmacos y de indicadores de bienestar animal, ubicando a Chile a la vanguardia respecto de otros pa\u00edses exportadores.<\/p>\n\n\n\n<p><strong>Requisitos de exportaci\u00f3n<\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/01\/IMG_1916-1024x683.jpg\" alt=\"\" class=\"wp-image-15570\" width=\"394\" height=\"262\" srcset=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/01\/IMG_1916-1024x683.jpg 1024w, https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/01\/IMG_1916-586x391.jpg 586w, https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/01\/IMG_1916-768x512.jpg 768w, https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/01\/IMG_1916.jpg 600w\" sizes=\"auto, (max-width: 394px) 100vw, 394px\" \/><\/figure><\/div>\n\n\n\n<p>Dentro de los requisitos vigentes para exportar carne bovina a China el establecimiento faenador habilitado debe:<\/p>\n\n\n\n<p>&#8211; Exigir que los animales bovinos provengan de predios que pertenezcan al programa PABCO Bovino o ser predios \u201csin uso de anab\u00f3licos\u201d, lo cual debe ser verificado en el Sistema de Informaci\u00f3n Pecuaria Oficial (SIPEC).&nbsp;<\/p>\n\n\n\n<p>&#8211; Los animales bovinos deben cumplir con la trazabilidad al nacimiento y no presentar la condici\u00f3n \u201cuso de anab\u00f3licos\u201d en SIPEC (DIIO).<\/p>\n\n\n\n<p>&#8211; Los predios deben presentar el Certificado de Antecedentes del predio y el Formulario de Movimiento Animal (FMA) correspondiente, cada vez que se env\u00eden animales a faena con destino al mercado de China.&nbsp;&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s de 5 a\u00f1os, la planta faenadora de Valdivia realiz\u00f3 un nuevo env\u00edo hacia el mercado asi\u00e1tico. Autoridades sellaron junto al SAG container con m\u00e1s de 24 mil kilos de&#8230;<\/p>\n","protected":false},"author":2,"featured_media":15572,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1944],"tags":[3127,4603,4601,4602,4149],"class_list":["post-15569","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ganaderia","tag-agro","tag-carne-bovina-a-china","tag-exportacion-de-carne-a-china","tag-gaanado","tag-mundo-agropecuario"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los R\u00edos retoma exportaciones de carne bovina a China - Mundoagropecuario<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mundoagropecuario.cl\/new\/los-rios-retoma-exportaciones-de-carne-bovina-a-china\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los R\u00edos retoma exportaciones de carne bovina a China - Mundoagropecuario\" \/>\n<meta property=\"og:description\" content=\"Despu\u00e9s de 5 a\u00f1os, la planta faenadora de Valdivia realiz\u00f3 un nuevo env\u00edo hacia el mercado asi\u00e1tico. Autoridades sellaron junto al SAG container con m\u00e1s de 24 mil kilos de...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mundoagropecuario.cl\/new\/los-rios-retoma-exportaciones-de-carne-bovina-a-china\/\" \/>\n<meta property=\"og:site_name\" content=\"Mundoagropecuario\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mundo.agropecuario.3\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-21T13:40:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-22T14:03:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/01\/IMG_20200109_170649.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mundo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MundoAgropecuar\" \/>\n<meta name=\"twitter:site\" content=\"@MundoAgropecuar\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mundo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/los-rios-retoma-exportaciones-de-carne-bovina-a-china\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/los-rios-retoma-exportaciones-de-carne-bovina-a-china\\\/\"},\"author\":{\"name\":\"mundo\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/person\\\/4e9f74a82a7dac260eb1c44b7eebeb18\"},\"headline\":\"Los R\u00edos retoma exportaciones de carne bovina a China\",\"datePublished\":\"2020-01-21T13:40:55+00:00\",\"dateModified\":\"2020-01-22T14:03:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/los-rios-retoma-exportaciones-de-carne-bovina-a-china\\\/\"},\"wordCount\":697,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/los-rios-retoma-exportaciones-de-carne-bovina-a-china\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/IMG_20200109_170649.jpg\",\"keywords\":[\"Agro\",\"carne bovina a China\",\"Exportaci\u00f3n de carne a China\",\"Gaanado\",\"Mundo Agropecuario\"],\"articleSection\":[\"Ganader\u00eda\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/los-rios-retoma-exportaciones-de-carne-bovina-a-china\\\/\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/los-rios-retoma-exportaciones-de-carne-bovina-a-china\\\/\",\"name\":\"Los R\u00edos retoma exportaciones de carne bovina a China - Mundoagropecuario\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/los-rios-retoma-exportaciones-de-carne-bovina-a-china\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/los-rios-retoma-exportaciones-de-carne-bovina-a-china\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/IMG_20200109_170649.jpg\",\"datePublished\":\"2020-01-21T13:40:55+00:00\",\"dateModified\":\"2020-01-22T14:03:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/los-rios-retoma-exportaciones-de-carne-bovina-a-china\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/los-rios-retoma-exportaciones-de-carne-bovina-a-china\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/los-rios-retoma-exportaciones-de-carne-bovina-a-china\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/IMG_20200109_170649.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/IMG_20200109_170649.jpg\",\"width\":533,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/los-rios-retoma-exportaciones-de-carne-bovina-a-china\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los R\u00edos retoma exportaciones de carne bovina a China\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#website\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/\",\"name\":\"Mundoagropecuario\",\"description\":\"Mundo Agropecuario\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#organization\",\"name\":\"Revista de Agricultura\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/PORTAL-1-1.png\",\"contentUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/PORTAL-1-1.png\",\"width\":1026,\"height\":100,\"caption\":\"Revista de Agricultura\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mundo.agropecuario.3\",\"https:\\\/\\\/x.com\\\/MundoAgropecuar\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/mundo-agropecuario-934009201\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/person\\\/4e9f74a82a7dac260eb1c44b7eebeb18\",\"name\":\"mundo\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/author\\\/mundo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los R\u00edos retoma exportaciones de carne bovina a China - Mundoagropecuario","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mundoagropecuario.cl\/new\/los-rios-retoma-exportaciones-de-carne-bovina-a-china\/","og_locale":"es_ES","og_type":"article","og_title":"Los R\u00edos retoma exportaciones de carne bovina a China - Mundoagropecuario","og_description":"Despu\u00e9s de 5 a\u00f1os, la planta faenadora de Valdivia realiz\u00f3 un nuevo env\u00edo hacia el mercado asi\u00e1tico. Autoridades sellaron junto al SAG container con m\u00e1s de 24 mil kilos de...","og_url":"https:\/\/www.mundoagropecuario.cl\/new\/los-rios-retoma-exportaciones-de-carne-bovina-a-china\/","og_site_name":"Mundoagropecuario","article_publisher":"https:\/\/www.facebook.com\/mundo.agropecuario.3","article_published_time":"2020-01-21T13:40:55+00:00","article_modified_time":"2020-01-22T14:03:27+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/01\/IMG_20200109_170649.jpg","type":"image\/jpeg"}],"author":"mundo","twitter_card":"summary_large_image","twitter_creator":"@MundoAgropecuar","twitter_site":"@MundoAgropecuar","twitter_misc":{"Escrito por":"mundo","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mundoagropecuario.cl\/new\/los-rios-retoma-exportaciones-de-carne-bovina-a-china\/#article","isPartOf":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/los-rios-retoma-exportaciones-de-carne-bovina-a-china\/"},"author":{"name":"mundo","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/person\/4e9f74a82a7dac260eb1c44b7eebeb18"},"headline":"Los R\u00edos retoma exportaciones de carne bovina a China","datePublished":"2020-01-21T13:40:55+00:00","dateModified":"2020-01-22T14:03:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/los-rios-retoma-exportaciones-de-carne-bovina-a-china\/"},"wordCount":697,"publisher":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#organization"},"image":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/los-rios-retoma-exportaciones-de-carne-bovina-a-china\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/01\/IMG_20200109_170649.jpg","keywords":["Agro","carne bovina a China","Exportaci\u00f3n de carne a China","Gaanado","Mundo Agropecuario"],"articleSection":["Ganader\u00eda"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.mundoagropecuario.cl\/new\/los-rios-retoma-exportaciones-de-carne-bovina-a-china\/","url":"https:\/\/www.mundoagropecuario.cl\/new\/los-rios-retoma-exportaciones-de-carne-bovina-a-china\/","name":"Los R\u00edos retoma exportaciones de carne bovina a China - Mundoagropecuario","isPartOf":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/los-rios-retoma-exportaciones-de-carne-bovina-a-china\/#primaryimage"},"image":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/los-rios-retoma-exportaciones-de-carne-bovina-a-china\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/01\/IMG_20200109_170649.jpg","datePublished":"2020-01-21T13:40:55+00:00","dateModified":"2020-01-22T14:03:27+00:00","breadcrumb":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/los-rios-retoma-exportaciones-de-carne-bovina-a-china\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mundoagropecuario.cl\/new\/los-rios-retoma-exportaciones-de-carne-bovina-a-china\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoagropecuario.cl\/new\/los-rios-retoma-exportaciones-de-carne-bovina-a-china\/#primaryimage","url":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/01\/IMG_20200109_170649.jpg","contentUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/01\/IMG_20200109_170649.jpg","width":533,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.mundoagropecuario.cl\/new\/los-rios-retoma-exportaciones-de-carne-bovina-a-china\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.mundoagropecuario.cl\/new\/"},{"@type":"ListItem","position":2,"name":"Los R\u00edos retoma exportaciones de carne bovina a China"}]},{"@type":"WebSite","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#website","url":"https:\/\/www.mundoagropecuario.cl\/new\/","name":"Mundoagropecuario","description":"Mundo Agropecuario","publisher":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mundoagropecuario.cl\/new\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#organization","name":"Revista de Agricultura","url":"https:\/\/www.mundoagropecuario.cl\/new\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/logo\/image\/","url":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/11\/PORTAL-1-1.png","contentUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/11\/PORTAL-1-1.png","width":1026,"height":100,"caption":"Revista de Agricultura"},"image":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mundo.agropecuario.3","https:\/\/x.com\/MundoAgropecuar","https:\/\/www.linkedin.com\/in\/mundo-agropecuario-934009201\/"]},{"@type":"Person","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/person\/4e9f74a82a7dac260eb1c44b7eebeb18","name":"mundo","url":"https:\/\/www.mundoagropecuario.cl\/new\/author\/mundo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts\/15569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/comments?post=15569"}],"version-history":[{"count":1,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts\/15569\/revisions"}],"predecessor-version":[{"id":15573,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts\/15569\/revisions\/15573"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/media\/15572"}],"wp:attachment":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/media?parent=15569"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/categories?post=15569"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/tags?post=15569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}