{"id":15342,"date":"2020-01-06T01:44:23","date_gmt":"2020-01-06T04:44:23","guid":{"rendered":"http:\/\/www.mundoagropecuario.cl\/new\/?p=15342"},"modified":"2020-01-07T11:59:07","modified_gmt":"2020-01-07T14:59:07","slug":"la-promocion-de-las-frutas-chilenas-durante-el-super-bowl-de-eeuu","status":"publish","type":"post","link":"https:\/\/www.mundoagropecuario.cl\/new\/la-promocion-de-las-frutas-chilenas-durante-el-super-bowl-de-eeuu\/","title":{"rendered":"La promoci\u00f3n de las frutas chilenas durante el \u201cSuper Bowl\u201d de EEUU"},"content":{"rendered":"\n<ul class=\"wp-block-gallery columns-0 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><\/ul>\n\n\n\n<p class=\"has-medium-font-size\"><em>El concurso se llevar\u00e1 a cabo en ESPN.com y la aplicaci\u00f3n ESPN hasta el 19 de enero, pero&nbsp;&nbsp;los anuncios de las frutas chilenas continuar\u00e1n siendo difundidos hasta febrero (Mundo Agropecuario).<\/em><\/p>\n\n\n\n<p>Con la finalidad de celebrar la temporada de frutas de verano de Chile en Estados Unidos y aprovechando la coincidencia&nbsp;&nbsp;con el Supertaz\u00f3n o Super Bowl de Estados Unidos. La&nbsp;&nbsp;Chilean Fresh Fruit Association de Norteam\u00e9rica (CFFA) lanz\u00f3 su campa\u00f1a promocional \u201cSuper Fruit Bowl\u201d. La acci\u00f3n invita a los consumidores a descubrir la amplia gama de frutas frescas disponibles de Chile durante los meses de invierno y les ofrece la oportunidad de ganar boletos para el Big Game en Miami, Florida. <\/p>\n\n\n\n<p>Karen Brux, Directora de la CFFA, coment\u00f3: \u201cEsta campa\u00f1a resulta muy natural para nosotros. Estamos en el coraz\u00f3n de la temporada de la fruta chilena, con ar\u00e1ndanos, cerezas, uvas y fruta de carozos que ahora llegan a Norteam\u00e9rica. Con el \u201cS\u00faper Frutero\u201d, tenemos una gran oportunidad para atraer la atenci\u00f3n de los consumidores y crear conciencia sobre la fruta chilena. Los anuncios y videos digitales que aparecen en ESPN.com y la aplicaci\u00f3n ESPN llevar\u00e1n a los consumidores a una p\u00e1gina de inicio donde pueden aprender m\u00e1s sobre la fruta chilena y tambi\u00e9n ingresar para ganar 2 boletos y pases VIP para el Gran Juego, m\u00e1s USD$1.000 en dinero para gastos y una estad\u00eda de hotel de 1 noche\u201d.<\/p>\n\n\n\n<p>Esta acci\u00f3n centrada en el consumidor es solo un elemento de una campa\u00f1a m\u00e1s amplia de la fruta fresca chilena que se extender\u00e1 hasta abril, destac\u00f3 Brux. \u201c Es importante para nosotros crear conciencia en el consumidor sobre la fruta chilena y generar una mayor demanda de ella, pero tambi\u00e9n resulta&nbsp;&nbsp;esencial brindar a los minoristas el apoyo que necesitan para impulsar las ventas. Nuestro equipo de merchandisers trabaja en estrecha colaboraci\u00f3n con todos los segmentos de la industria, desarrollando programas que sean m\u00e1s efectivos para los minoristas. Tambi\u00e9n proporcionamos informes de cosecha y exportaci\u00f3n semanales a todos los involucrados en la venta y distribuci\u00f3n de nuestra fruta a trav\u00e9s de los cuales pueden tomar decisiones informadas basadas en las \u00faltimas actualizaciones&#8221;, agreg\u00f3 la profesional.<\/p>\n\n\n\n<p>Finalmente, Brux se\u00f1al\u00f3 que los barcos de ar\u00e1ndanos y cerezas de Chile est\u00e1n en marcha. Las promociones de cerezas se extender\u00e1n hasta enero, y los programas de ar\u00e1ndanos&nbsp;&nbsp;hasta febrero. La fruta de carozo se promocionar\u00e1 desde finales de enero hasta marzo, y las promociones de uva&nbsp;&nbsp;de mesa se llevar\u00e1n a cabo desde febrero hasta abril.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El concurso se llevar\u00e1 a cabo en ESPN.com y la aplicaci\u00f3n ESPN hasta el 19 de enero, pero&nbsp;&nbsp;los anuncios de las frutas chilenas continuar\u00e1n siendo difundidos hasta febrero (Mundo Agropecuario)&#8230;.<\/p>\n","protected":false},"author":2,"featured_media":15343,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1986],"tags":[2177,2861,4552],"class_list":["post-15342","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-frutas","tag-asoex","tag-fruta-chilena","tag-super-bowl-de-eeuu"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La promoci\u00f3n de las frutas chilenas durante el \u201cSuper Bowl\u201d de EEUU - Mundoagropecuario<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mundoagropecuario.cl\/new\/la-promocion-de-las-frutas-chilenas-durante-el-super-bowl-de-eeuu\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La promoci\u00f3n de las frutas chilenas durante el \u201cSuper Bowl\u201d de EEUU - Mundoagropecuario\" \/>\n<meta property=\"og:description\" content=\"El concurso se llevar\u00e1 a cabo en ESPN.com y la aplicaci\u00f3n ESPN hasta el 19 de enero, pero&nbsp;&nbsp;los anuncios de las frutas chilenas continuar\u00e1n siendo difundidos hasta febrero (Mundo Agropecuario)....\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mundoagropecuario.cl\/new\/la-promocion-de-las-frutas-chilenas-durante-el-super-bowl-de-eeuu\/\" \/>\n<meta property=\"og:site_name\" content=\"Mundoagropecuario\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mundo.agropecuario.3\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-06T04:44:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-07T14:59:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/01\/Fruta-Chilena.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mundo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MundoAgropecuar\" \/>\n<meta name=\"twitter:site\" content=\"@MundoAgropecuar\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mundo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/la-promocion-de-las-frutas-chilenas-durante-el-super-bowl-de-eeuu\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/la-promocion-de-las-frutas-chilenas-durante-el-super-bowl-de-eeuu\\\/\"},\"author\":{\"name\":\"mundo\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/person\\\/4e9f74a82a7dac260eb1c44b7eebeb18\"},\"headline\":\"La promoci\u00f3n de las frutas chilenas durante el \u201cSuper Bowl\u201d de EEUU\",\"datePublished\":\"2020-01-06T04:44:23+00:00\",\"dateModified\":\"2020-01-07T14:59:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/la-promocion-de-las-frutas-chilenas-durante-el-super-bowl-de-eeuu\\\/\"},\"wordCount\":470,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/la-promocion-de-las-frutas-chilenas-durante-el-super-bowl-de-eeuu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Fruta-Chilena.jpg\",\"keywords\":[\"Asoex\",\"fruta chilena\",\"Super Bowl\u201d de EEUU\"],\"articleSection\":[\"Frutas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/la-promocion-de-las-frutas-chilenas-durante-el-super-bowl-de-eeuu\\\/\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/la-promocion-de-las-frutas-chilenas-durante-el-super-bowl-de-eeuu\\\/\",\"name\":\"La promoci\u00f3n de las frutas chilenas durante el \u201cSuper Bowl\u201d de EEUU - Mundoagropecuario\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/la-promocion-de-las-frutas-chilenas-durante-el-super-bowl-de-eeuu\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/la-promocion-de-las-frutas-chilenas-durante-el-super-bowl-de-eeuu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Fruta-Chilena.jpg\",\"datePublished\":\"2020-01-06T04:44:23+00:00\",\"dateModified\":\"2020-01-07T14:59:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/la-promocion-de-las-frutas-chilenas-durante-el-super-bowl-de-eeuu\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/la-promocion-de-las-frutas-chilenas-durante-el-super-bowl-de-eeuu\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/la-promocion-de-las-frutas-chilenas-durante-el-super-bowl-de-eeuu\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Fruta-Chilena.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Fruta-Chilena.jpg\",\"width\":533,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/la-promocion-de-las-frutas-chilenas-durante-el-super-bowl-de-eeuu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La promoci\u00f3n de las frutas chilenas durante el \u201cSuper Bowl\u201d de EEUU\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#website\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/\",\"name\":\"Mundoagropecuario\",\"description\":\"Mundo Agropecuario\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#organization\",\"name\":\"Revista de Agricultura\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/PORTAL-1-1.png\",\"contentUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/PORTAL-1-1.png\",\"width\":1026,\"height\":100,\"caption\":\"Revista de Agricultura\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mundo.agropecuario.3\",\"https:\\\/\\\/x.com\\\/MundoAgropecuar\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/mundo-agropecuario-934009201\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/person\\\/4e9f74a82a7dac260eb1c44b7eebeb18\",\"name\":\"mundo\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/author\\\/mundo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La promoci\u00f3n de las frutas chilenas durante el \u201cSuper Bowl\u201d de EEUU - Mundoagropecuario","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mundoagropecuario.cl\/new\/la-promocion-de-las-frutas-chilenas-durante-el-super-bowl-de-eeuu\/","og_locale":"es_ES","og_type":"article","og_title":"La promoci\u00f3n de las frutas chilenas durante el \u201cSuper Bowl\u201d de EEUU - Mundoagropecuario","og_description":"El concurso se llevar\u00e1 a cabo en ESPN.com y la aplicaci\u00f3n ESPN hasta el 19 de enero, pero&nbsp;&nbsp;los anuncios de las frutas chilenas continuar\u00e1n siendo difundidos hasta febrero (Mundo Agropecuario)....","og_url":"https:\/\/www.mundoagropecuario.cl\/new\/la-promocion-de-las-frutas-chilenas-durante-el-super-bowl-de-eeuu\/","og_site_name":"Mundoagropecuario","article_publisher":"https:\/\/www.facebook.com\/mundo.agropecuario.3","article_published_time":"2020-01-06T04:44:23+00:00","article_modified_time":"2020-01-07T14:59:07+00:00","og_image":[{"width":600,"height":450,"url":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/01\/Fruta-Chilena.jpg","type":"image\/jpeg"}],"author":"mundo","twitter_card":"summary_large_image","twitter_creator":"@MundoAgropecuar","twitter_site":"@MundoAgropecuar","twitter_misc":{"Escrito por":"mundo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mundoagropecuario.cl\/new\/la-promocion-de-las-frutas-chilenas-durante-el-super-bowl-de-eeuu\/#article","isPartOf":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/la-promocion-de-las-frutas-chilenas-durante-el-super-bowl-de-eeuu\/"},"author":{"name":"mundo","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/person\/4e9f74a82a7dac260eb1c44b7eebeb18"},"headline":"La promoci\u00f3n de las frutas chilenas durante el \u201cSuper Bowl\u201d de EEUU","datePublished":"2020-01-06T04:44:23+00:00","dateModified":"2020-01-07T14:59:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/la-promocion-de-las-frutas-chilenas-durante-el-super-bowl-de-eeuu\/"},"wordCount":470,"publisher":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#organization"},"image":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/la-promocion-de-las-frutas-chilenas-durante-el-super-bowl-de-eeuu\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/01\/Fruta-Chilena.jpg","keywords":["Asoex","fruta chilena","Super Bowl\u201d de EEUU"],"articleSection":["Frutas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.mundoagropecuario.cl\/new\/la-promocion-de-las-frutas-chilenas-durante-el-super-bowl-de-eeuu\/","url":"https:\/\/www.mundoagropecuario.cl\/new\/la-promocion-de-las-frutas-chilenas-durante-el-super-bowl-de-eeuu\/","name":"La promoci\u00f3n de las frutas chilenas durante el \u201cSuper Bowl\u201d de EEUU - Mundoagropecuario","isPartOf":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/la-promocion-de-las-frutas-chilenas-durante-el-super-bowl-de-eeuu\/#primaryimage"},"image":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/la-promocion-de-las-frutas-chilenas-durante-el-super-bowl-de-eeuu\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/01\/Fruta-Chilena.jpg","datePublished":"2020-01-06T04:44:23+00:00","dateModified":"2020-01-07T14:59:07+00:00","breadcrumb":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/la-promocion-de-las-frutas-chilenas-durante-el-super-bowl-de-eeuu\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mundoagropecuario.cl\/new\/la-promocion-de-las-frutas-chilenas-durante-el-super-bowl-de-eeuu\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoagropecuario.cl\/new\/la-promocion-de-las-frutas-chilenas-durante-el-super-bowl-de-eeuu\/#primaryimage","url":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/01\/Fruta-Chilena.jpg","contentUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/01\/Fruta-Chilena.jpg","width":533,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.mundoagropecuario.cl\/new\/la-promocion-de-las-frutas-chilenas-durante-el-super-bowl-de-eeuu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.mundoagropecuario.cl\/new\/"},{"@type":"ListItem","position":2,"name":"La promoci\u00f3n de las frutas chilenas durante el \u201cSuper Bowl\u201d de EEUU"}]},{"@type":"WebSite","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#website","url":"https:\/\/www.mundoagropecuario.cl\/new\/","name":"Mundoagropecuario","description":"Mundo Agropecuario","publisher":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mundoagropecuario.cl\/new\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#organization","name":"Revista de Agricultura","url":"https:\/\/www.mundoagropecuario.cl\/new\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/logo\/image\/","url":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/11\/PORTAL-1-1.png","contentUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/11\/PORTAL-1-1.png","width":1026,"height":100,"caption":"Revista de Agricultura"},"image":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mundo.agropecuario.3","https:\/\/x.com\/MundoAgropecuar","https:\/\/www.linkedin.com\/in\/mundo-agropecuario-934009201\/"]},{"@type":"Person","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/person\/4e9f74a82a7dac260eb1c44b7eebeb18","name":"mundo","url":"https:\/\/www.mundoagropecuario.cl\/new\/author\/mundo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts\/15342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/comments?post=15342"}],"version-history":[{"count":2,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts\/15342\/revisions"}],"predecessor-version":[{"id":15354,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts\/15342\/revisions\/15354"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/media\/15343"}],"wp:attachment":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/media?parent=15342"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/categories?post=15342"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/tags?post=15342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}