{"id":15336,"date":"2020-01-06T01:23:11","date_gmt":"2020-01-06T04:23:11","guid":{"rendered":"http:\/\/www.mundoagropecuario.cl\/new\/?p=15336"},"modified":"2020-01-07T11:57:47","modified_gmt":"2020-01-07T14:57:47","slug":"en-marzo-llegan-al-mercado-gomitas-a-base-de-pulpa-de-manzana","status":"publish","type":"post","link":"https:\/\/www.mundoagropecuario.cl\/new\/en-marzo-llegan-al-mercado-gomitas-a-base-de-pulpa-de-manzana\/","title":{"rendered":"En marzo llegan al mercado gomitas a base de pulpa de manzana"},"content":{"rendered":"\n<ul class=\"wp-block-gallery columns-0 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-medium-font-size\"><em>Suplemento alimenticio en polvo a base de la c\u00e1scara de la manzana, es impulsado por FIA.  Sus creadores la empresa C\u00e1scara Foods lanzan en marzo la versi\u00f3n Azana gummies (Mundo Agropecuario).<\/em><\/p>\n\n\n\n<p>Se trata de un formato m\u00e1s pr\u00e1ctico donde las personas podr\u00e1n comprar cuatro unidades de gomitas que equivale a 6 gramos de fibra formulado con pulpa de manzana verde. La cual proviene de las materias org\u00e1nicas no utilizadas por la industria de jugos al momento de prensar la fruta. Las c\u00e1scaras concentran el 90% de la fibra total de la fruta.<\/p>\n\n\n\n<p>\u201cLa idea es que quienes consumen Azana tengan m\u00e1s de una alternativa de ingesta seg\u00fan sus necesidades. Por ejemplo, puede que comas este suplemento todos los d\u00edas, pero una ma\u00f1ana no tuviste tiempo como para mezclar con algo, y ah\u00ed puedes optar las gummies, por su inmediatez. Las personas quieren aquello que les agrega valor y les resuelve un problema\u201d, explic\u00f3 Domingo Chong, cofundador de C\u00e1scara Foods.<\/p>\n\n\n\n<p>Adem\u00e1s, Chong argument\u00f3 que el prop\u00f3sito de la empresa es aumentar \u2013 de la mano con el concepto de econom\u00eda circular, es decir, reducir el impacto ambiental con una producci\u00f3n que reutiliza las materias org\u00e1nicas \u2013 el 12% de ingesta de fibra por persona en nuestro pa\u00eds, dado que, seg\u00fan los estudios, idealmente el organismo debe recibir al menos \u201centre 25 y 30 gramos diarios para una dieta de 2 mil calor\u00edas\u201d.<\/p>\n\n\n\n<p><strong>Frutos<\/strong><\/p>\n\n\n\n<p>De ah\u00ed la raz\u00f3n de porqu\u00e9 ForoInnovaci\u00f3n primero los identifica y luego los reconoce \u2013 en diciembre \u2013 con el Premio Nacional Avonni 2019 categor\u00eda Alimentaci\u00f3n Saludable. Decisi\u00f3n validada por el director ejecutivo de la Fundaci\u00f3n para la Innovaci\u00f3n Agraria (FIA), \u00c1lvaro Eyzaguirre; quien, a su vez, coment\u00f3 la llegada de Azana gummies al mercado nacional de los alimentos de origen vegetal.<\/p>\n\n\n\n<p>\u201cUno de los pilares de FIA es apoyar el emprendimiento innovador que fomente el desarrollo de nuevos negocios o la generaci\u00f3n de nuevas tecnolog\u00edas que tengan impacto en el sector silvoagroalimentario. En este caso, estos j\u00f3venes han puesto en el mercado un producto que busca ser eficiente para las personas y, adem\u00e1s, llama a la comunidad a ser consciente de la sustentabilidad. Es muy rescatable que un producto, al a\u00f1o de su creaci\u00f3n y gracias al aumento sostenible de un 20% en ventas, logre dar vida a un segundo alimento. Nos sentimos orgullosos del avance\u201d, se\u00f1al\u00f3.<\/p>\n\n\n\n<p><strong>El camino<\/strong><\/p>\n\n\n\n<p>De acuerdo con la informaci\u00f3n se\u00f1alada por el cofundador de C\u00e1scara Foods, Domingo Chong, las gomitas a base de pulpa de manzana verde est\u00e1n, a la fecha, en proceso de testeo de mercado (etapa piloto) para que pueda ser distribuida su venta a trav\u00e9s de la p\u00e1gina web (www.cascarasfoods.com) y las Farmacias Knop en marzo. Si bien comenta que no fue un camino f\u00e1cil de recorrer, valora quienes creyeron desde el comienzo en su proyecto.<\/p>\n\n\n\n<p>\u201cUno de los actores que confi\u00f3 desde un principio en nosotros es la Fundaci\u00f3n para Innovaci\u00f3n Agraria. Cuando partimos trabajando con ellos s\u00f3lo ten\u00edamos un prototipo, y ellos nos ayudaron con financiamiento y asesor\u00eda en la parte t\u00e9cnica. Sin ellos habr\u00eda sido muy complejo lograr partir. Le recomiendo a cualquier emprendimiento relacionado con el sector agro y alimentaci\u00f3n buscar involucrarse con ellos\u201d, puntualiz\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Suplemento alimenticio en polvo a base de la c\u00e1scara de la manzana, es impulsado por FIA. Sus creadores la empresa C\u00e1scara Foods lanzan en marzo la versi\u00f3n Azana gummies (Mundo&#8230;<\/p>\n","protected":false},"author":2,"featured_media":15337,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1986],"tags":[3127,4549,2124,4149,4548],"class_list":["post-15336","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-frutas","tag-agro","tag-azana-gummies","tag-fia","tag-mundo-agropecuario","tag-pulpa-de-manzana"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>En marzo llegan al mercado gomitas a base de pulpa de manzana - Mundoagropecuario<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mundoagropecuario.cl\/new\/en-marzo-llegan-al-mercado-gomitas-a-base-de-pulpa-de-manzana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En marzo llegan al mercado gomitas a base de pulpa de manzana - Mundoagropecuario\" \/>\n<meta property=\"og:description\" content=\"Suplemento alimenticio en polvo a base de la c\u00e1scara de la manzana, es impulsado por FIA. Sus creadores la empresa C\u00e1scara Foods lanzan en marzo la versi\u00f3n Azana gummies (Mundo...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mundoagropecuario.cl\/new\/en-marzo-llegan-al-mercado-gomitas-a-base-de-pulpa-de-manzana\/\" \/>\n<meta property=\"og:site_name\" content=\"Mundoagropecuario\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mundo.agropecuario.3\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-06T04:23:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-07T14:57:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/01\/Pepas-de-manzana.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mundo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MundoAgropecuar\" \/>\n<meta name=\"twitter:site\" content=\"@MundoAgropecuar\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mundo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/en-marzo-llegan-al-mercado-gomitas-a-base-de-pulpa-de-manzana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/en-marzo-llegan-al-mercado-gomitas-a-base-de-pulpa-de-manzana\\\/\"},\"author\":{\"name\":\"mundo\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/person\\\/4e9f74a82a7dac260eb1c44b7eebeb18\"},\"headline\":\"En marzo llegan al mercado gomitas a base de pulpa de manzana\",\"datePublished\":\"2020-01-06T04:23:11+00:00\",\"dateModified\":\"2020-01-07T14:57:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/en-marzo-llegan-al-mercado-gomitas-a-base-de-pulpa-de-manzana\\\/\"},\"wordCount\":582,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/en-marzo-llegan-al-mercado-gomitas-a-base-de-pulpa-de-manzana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Pepas-de-manzana.jpg\",\"keywords\":[\"Agro\",\"Azana gummies\",\"FIA\",\"Mundo Agropecuario\",\"pulpa de manzana\"],\"articleSection\":[\"Frutas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/en-marzo-llegan-al-mercado-gomitas-a-base-de-pulpa-de-manzana\\\/\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/en-marzo-llegan-al-mercado-gomitas-a-base-de-pulpa-de-manzana\\\/\",\"name\":\"En marzo llegan al mercado gomitas a base de pulpa de manzana - Mundoagropecuario\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/en-marzo-llegan-al-mercado-gomitas-a-base-de-pulpa-de-manzana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/en-marzo-llegan-al-mercado-gomitas-a-base-de-pulpa-de-manzana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Pepas-de-manzana.jpg\",\"datePublished\":\"2020-01-06T04:23:11+00:00\",\"dateModified\":\"2020-01-07T14:57:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/en-marzo-llegan-al-mercado-gomitas-a-base-de-pulpa-de-manzana\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/en-marzo-llegan-al-mercado-gomitas-a-base-de-pulpa-de-manzana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/en-marzo-llegan-al-mercado-gomitas-a-base-de-pulpa-de-manzana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Pepas-de-manzana.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Pepas-de-manzana.jpg\",\"width\":600,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/en-marzo-llegan-al-mercado-gomitas-a-base-de-pulpa-de-manzana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En marzo llegan al mercado gomitas a base de pulpa de manzana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#website\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/\",\"name\":\"Mundoagropecuario\",\"description\":\"Mundo Agropecuario\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#organization\",\"name\":\"Revista de Agricultura\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/PORTAL-1-1.png\",\"contentUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/PORTAL-1-1.png\",\"width\":1026,\"height\":100,\"caption\":\"Revista de Agricultura\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mundo.agropecuario.3\",\"https:\\\/\\\/x.com\\\/MundoAgropecuar\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/mundo-agropecuario-934009201\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/person\\\/4e9f74a82a7dac260eb1c44b7eebeb18\",\"name\":\"mundo\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/author\\\/mundo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En marzo llegan al mercado gomitas a base de pulpa de manzana - Mundoagropecuario","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mundoagropecuario.cl\/new\/en-marzo-llegan-al-mercado-gomitas-a-base-de-pulpa-de-manzana\/","og_locale":"es_ES","og_type":"article","og_title":"En marzo llegan al mercado gomitas a base de pulpa de manzana - Mundoagropecuario","og_description":"Suplemento alimenticio en polvo a base de la c\u00e1scara de la manzana, es impulsado por FIA. Sus creadores la empresa C\u00e1scara Foods lanzan en marzo la versi\u00f3n Azana gummies (Mundo...","og_url":"https:\/\/www.mundoagropecuario.cl\/new\/en-marzo-llegan-al-mercado-gomitas-a-base-de-pulpa-de-manzana\/","og_site_name":"Mundoagropecuario","article_publisher":"https:\/\/www.facebook.com\/mundo.agropecuario.3","article_published_time":"2020-01-06T04:23:11+00:00","article_modified_time":"2020-01-07T14:57:47+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/01\/Pepas-de-manzana.jpg","type":"image\/jpeg"}],"author":"mundo","twitter_card":"summary_large_image","twitter_creator":"@MundoAgropecuar","twitter_site":"@MundoAgropecuar","twitter_misc":{"Escrito por":"mundo","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mundoagropecuario.cl\/new\/en-marzo-llegan-al-mercado-gomitas-a-base-de-pulpa-de-manzana\/#article","isPartOf":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/en-marzo-llegan-al-mercado-gomitas-a-base-de-pulpa-de-manzana\/"},"author":{"name":"mundo","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/person\/4e9f74a82a7dac260eb1c44b7eebeb18"},"headline":"En marzo llegan al mercado gomitas a base de pulpa de manzana","datePublished":"2020-01-06T04:23:11+00:00","dateModified":"2020-01-07T14:57:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/en-marzo-llegan-al-mercado-gomitas-a-base-de-pulpa-de-manzana\/"},"wordCount":582,"publisher":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#organization"},"image":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/en-marzo-llegan-al-mercado-gomitas-a-base-de-pulpa-de-manzana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/01\/Pepas-de-manzana.jpg","keywords":["Agro","Azana gummies","FIA","Mundo Agropecuario","pulpa de manzana"],"articleSection":["Frutas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.mundoagropecuario.cl\/new\/en-marzo-llegan-al-mercado-gomitas-a-base-de-pulpa-de-manzana\/","url":"https:\/\/www.mundoagropecuario.cl\/new\/en-marzo-llegan-al-mercado-gomitas-a-base-de-pulpa-de-manzana\/","name":"En marzo llegan al mercado gomitas a base de pulpa de manzana - Mundoagropecuario","isPartOf":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/en-marzo-llegan-al-mercado-gomitas-a-base-de-pulpa-de-manzana\/#primaryimage"},"image":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/en-marzo-llegan-al-mercado-gomitas-a-base-de-pulpa-de-manzana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/01\/Pepas-de-manzana.jpg","datePublished":"2020-01-06T04:23:11+00:00","dateModified":"2020-01-07T14:57:47+00:00","breadcrumb":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/en-marzo-llegan-al-mercado-gomitas-a-base-de-pulpa-de-manzana\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mundoagropecuario.cl\/new\/en-marzo-llegan-al-mercado-gomitas-a-base-de-pulpa-de-manzana\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoagropecuario.cl\/new\/en-marzo-llegan-al-mercado-gomitas-a-base-de-pulpa-de-manzana\/#primaryimage","url":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/01\/Pepas-de-manzana.jpg","contentUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/01\/Pepas-de-manzana.jpg","width":600,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.mundoagropecuario.cl\/new\/en-marzo-llegan-al-mercado-gomitas-a-base-de-pulpa-de-manzana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.mundoagropecuario.cl\/new\/"},{"@type":"ListItem","position":2,"name":"En marzo llegan al mercado gomitas a base de pulpa de manzana"}]},{"@type":"WebSite","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#website","url":"https:\/\/www.mundoagropecuario.cl\/new\/","name":"Mundoagropecuario","description":"Mundo Agropecuario","publisher":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mundoagropecuario.cl\/new\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#organization","name":"Revista de Agricultura","url":"https:\/\/www.mundoagropecuario.cl\/new\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/logo\/image\/","url":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/11\/PORTAL-1-1.png","contentUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/11\/PORTAL-1-1.png","width":1026,"height":100,"caption":"Revista de Agricultura"},"image":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mundo.agropecuario.3","https:\/\/x.com\/MundoAgropecuar","https:\/\/www.linkedin.com\/in\/mundo-agropecuario-934009201\/"]},{"@type":"Person","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/person\/4e9f74a82a7dac260eb1c44b7eebeb18","name":"mundo","url":"https:\/\/www.mundoagropecuario.cl\/new\/author\/mundo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts\/15336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/comments?post=15336"}],"version-history":[{"count":1,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts\/15336\/revisions"}],"predecessor-version":[{"id":15338,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts\/15336\/revisions\/15338"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/media\/15337"}],"wp:attachment":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/media?parent=15336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/categories?post=15336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/tags?post=15336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}