{"id":15198,"date":"2019-12-16T12:17:24","date_gmt":"2019-12-16T15:17:24","guid":{"rendered":"http:\/\/www.mundoagropecuario.cl\/new\/?p=15198"},"modified":"2019-12-18T11:15:11","modified_gmt":"2019-12-18T14:15:11","slug":"vinos-en-lata-y-bebidas-ready-to-drink-son-las-nuevas-tendencias-en-consumo","status":"publish","type":"post","link":"https:\/\/www.mundoagropecuario.cl\/new\/vinos-en-lata-y-bebidas-ready-to-drink-son-las-nuevas-tendencias-en-consumo\/","title":{"rendered":"Vinos en lata y bebidas ready to drink son las nuevas tendencias en consumo"},"content":{"rendered":"\n<ul class=\"wp-block-gallery columns-0 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><\/ul>\n\n\n\n<p class=\"has-medium-font-size\"><em>Los Millenials y la Generaci\u00f3n Z, buscan bebidas que sean f\u00e1ciles de llevar y amigables con el medio ambiente, esto llama a que las empresas del rubro deban innovar en sus productos para captar la atenci\u00f3n de este p\u00fablico (Mundo Agropecuario).<\/em><\/p>\n\n\n\n<p>Tragos f\u00e1ciles de llevar y opciones ready to drink (listos para tomar), son algunas de las nuevas formas de consumo que han debido ser adoptadas por las empresas que buscan llegar a nuevas generaciones.<\/p>\n\n\n\n<p>Nacieron con la tecnolog\u00eda y despu\u00e9s de los a\u00f1os 80; son preocupados por su salud y buscan alternativas que sean amigables con el medio ambiente. Estas son las caracter\u00edsticas de los Millenials y la Generaci\u00f3n Z, grupos que al momento de decidir qu\u00e9 tomar, optan por productos que tengan un valor agregado.<\/p>\n\n\n\n<p>Pero, \u00bfcu\u00e1l es el trago favorito de esta generaci\u00f3n? Un estudio de Wine Market Council revel\u00f3 que la bebida preferida de los Millenials es el vino y que, en instancias de consumo, toman alrededor de tres copas. Esto ha hecho que las empresas del rubro apuesten por nuevas alternativas con el fin de captar a estas generaciones, una de ellas son los vinos en lata.<\/p>\n\n\n\n<p>Este formato ha sido implementado con \u00e9xito en pa\u00edses europeos y Estados Unidos. De acuerdo con datos de Nielsen, el mercado de los vinos en lata alcanz\u00f3 en 2018 un valor de US$ 70 millones en EE.UU., lo que represent\u00f3 un aumento de 70%. En el Reino Unido, la categor\u00eda ha aumentado un 125% interanual hasta agosto de 2019, y con un valor cercano a los \u00a3 3.6 millones. \u201cLos vinos enlatados cada d\u00eda ganan m\u00e1s terreno y los datos sugieren que esta ser\u00e1 una tendencia duradera, no una moda pasajera\u201d, comentaron a Forbes desde Nielsen.<\/p>\n\n\n\n<p>Es as\u00ed como nuestro pa\u00eds no se quiso quedar atr\u00e1s y vi\u00f1as nacionales se han sumado a esta tendencia. La primera que entr\u00f3 en esta categor\u00eda fue Vi\u00f1a Santa Rita. La empresa lanz\u00f3 este a\u00f1o, Rita Ros\u00e9, el primer ros\u00e9 en lata y, hace un par de meses, sum\u00f3 Rita Blanc \u2014un Sauvignon Blanc\u2014 y Rita Sparkling, un espumante brut bajo en calor\u00edas.<\/p>\n\n\n\n<p>Adem\u00e1s de ser f\u00e1cil de llevar, el vino en este formato es amigable con nuestro planeta: \u201cLos consumidores est\u00e1n cada vez m\u00e1s preocupado por el cuidado del medio ambiente y las latas de aluminios son uno de los contenedores de bebida m\u00e1s reciclado a nivel mundial\u201d, destaca el Gerente de Marketing Corporativo de Vi\u00f1a Santa Rita, Jaime de la Barra, quien adem\u00e1s asegura que un 70% de cada uno de los contenedores est\u00e1 hecho con aluminio que fue previamente reciclado.<\/p>\n\n\n\n<p><strong>\u00a1Abrir y tomar!<\/strong><\/p>\n\n\n\n<p>Otra de las caracter\u00edsticas que demandan las nuevas generaciones es el ready to drink. Antes la gente buscaba hacer sus propias preparaciones, hoy los m\u00e1s j\u00f3venes quieren abrir el producto y que est\u00e9 listo para tomar.<\/p>\n\n\n\n<p>Al respecto, Bernardo Serrano, director de La Coctelera, asegura que la categor\u00eda ready to drink es una de las que m\u00e1s est\u00e1 creciendo y no solo con vinos y espumantes: \u201cSe han sumado muchas marcas reconocidas del rubro de los destilados que ofrecen cocteler\u00eda cl\u00e1sica, que basta con poner la mezcla en un vaso, agregar una decoraci\u00f3n o nuestro toque y la preparaci\u00f3n est\u00e1 lista\u201d.<\/p>\n\n\n\n<p>Por lo mismo, podemos ver que actualmente en el mercado nacional hay disponibles diferentes opciones en este formato, entre ellas se destaca el pisco to go, los spritzers, sangr\u00edas e incluso whiskys que vienen con bebidas cola o t\u00f3nicas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los Millenials y la Generaci\u00f3n Z, buscan bebidas que sean f\u00e1ciles de llevar y amigables con el medio ambiente, esto llama a que las empresas del rubro deban innovar en&#8230;<\/p>\n","protected":false},"author":2,"featured_media":15199,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1986],"tags":[4519,4520],"class_list":["post-15198","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-frutas","tag-vinos-en-lata","tag-vinos-en-lata-y-bebidas-ready"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vinos en lata y bebidas ready to drink son las nuevas tendencias en consumo - Mundoagropecuario<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mundoagropecuario.cl\/new\/vinos-en-lata-y-bebidas-ready-to-drink-son-las-nuevas-tendencias-en-consumo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vinos en lata y bebidas ready to drink son las nuevas tendencias en consumo - Mundoagropecuario\" \/>\n<meta property=\"og:description\" content=\"Los Millenials y la Generaci\u00f3n Z, buscan bebidas que sean f\u00e1ciles de llevar y amigables con el medio ambiente, esto llama a que las empresas del rubro deban innovar en...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mundoagropecuario.cl\/new\/vinos-en-lata-y-bebidas-ready-to-drink-son-las-nuevas-tendencias-en-consumo\/\" \/>\n<meta property=\"og:site_name\" content=\"Mundoagropecuario\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mundo.agropecuario.3\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-16T15:17:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-18T14:15:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2019\/12\/01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mundo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MundoAgropecuar\" \/>\n<meta name=\"twitter:site\" content=\"@MundoAgropecuar\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mundo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/vinos-en-lata-y-bebidas-ready-to-drink-son-las-nuevas-tendencias-en-consumo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/vinos-en-lata-y-bebidas-ready-to-drink-son-las-nuevas-tendencias-en-consumo\\\/\"},\"author\":{\"name\":\"mundo\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/person\\\/4e9f74a82a7dac260eb1c44b7eebeb18\"},\"headline\":\"Vinos en lata y bebidas ready to drink son las nuevas tendencias en consumo\",\"datePublished\":\"2019-12-16T15:17:24+00:00\",\"dateModified\":\"2019-12-18T14:15:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/vinos-en-lata-y-bebidas-ready-to-drink-son-las-nuevas-tendencias-en-consumo\\\/\"},\"wordCount\":621,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/vinos-en-lata-y-bebidas-ready-to-drink-son-las-nuevas-tendencias-en-consumo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/01.jpg\",\"keywords\":[\"Vinos en lata\",\"Vinos en lata y bebidas ready\"],\"articleSection\":[\"Frutas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/vinos-en-lata-y-bebidas-ready-to-drink-son-las-nuevas-tendencias-en-consumo\\\/\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/vinos-en-lata-y-bebidas-ready-to-drink-son-las-nuevas-tendencias-en-consumo\\\/\",\"name\":\"Vinos en lata y bebidas ready to drink son las nuevas tendencias en consumo - Mundoagropecuario\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/vinos-en-lata-y-bebidas-ready-to-drink-son-las-nuevas-tendencias-en-consumo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/vinos-en-lata-y-bebidas-ready-to-drink-son-las-nuevas-tendencias-en-consumo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/01.jpg\",\"datePublished\":\"2019-12-16T15:17:24+00:00\",\"dateModified\":\"2019-12-18T14:15:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/vinos-en-lata-y-bebidas-ready-to-drink-son-las-nuevas-tendencias-en-consumo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/vinos-en-lata-y-bebidas-ready-to-drink-son-las-nuevas-tendencias-en-consumo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/vinos-en-lata-y-bebidas-ready-to-drink-son-las-nuevas-tendencias-en-consumo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/01.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/01.jpg\",\"width\":400,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/vinos-en-lata-y-bebidas-ready-to-drink-son-las-nuevas-tendencias-en-consumo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vinos en lata y bebidas ready to drink son las nuevas tendencias en consumo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#website\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/\",\"name\":\"Mundoagropecuario\",\"description\":\"Mundo Agropecuario\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#organization\",\"name\":\"Revista de Agricultura\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/PORTAL-1-1.png\",\"contentUrl\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/PORTAL-1-1.png\",\"width\":1026,\"height\":100,\"caption\":\"Revista de Agricultura\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mundo.agropecuario.3\",\"https:\\\/\\\/x.com\\\/MundoAgropecuar\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/mundo-agropecuario-934009201\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/#\\\/schema\\\/person\\\/4e9f74a82a7dac260eb1c44b7eebeb18\",\"name\":\"mundo\",\"url\":\"https:\\\/\\\/www.mundoagropecuario.cl\\\/new\\\/author\\\/mundo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vinos en lata y bebidas ready to drink son las nuevas tendencias en consumo - Mundoagropecuario","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mundoagropecuario.cl\/new\/vinos-en-lata-y-bebidas-ready-to-drink-son-las-nuevas-tendencias-en-consumo\/","og_locale":"es_ES","og_type":"article","og_title":"Vinos en lata y bebidas ready to drink son las nuevas tendencias en consumo - Mundoagropecuario","og_description":"Los Millenials y la Generaci\u00f3n Z, buscan bebidas que sean f\u00e1ciles de llevar y amigables con el medio ambiente, esto llama a que las empresas del rubro deban innovar en...","og_url":"https:\/\/www.mundoagropecuario.cl\/new\/vinos-en-lata-y-bebidas-ready-to-drink-son-las-nuevas-tendencias-en-consumo\/","og_site_name":"Mundoagropecuario","article_publisher":"https:\/\/www.facebook.com\/mundo.agropecuario.3","article_published_time":"2019-12-16T15:17:24+00:00","article_modified_time":"2019-12-18T14:15:11+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2019\/12\/01.jpg","type":"image\/jpeg"}],"author":"mundo","twitter_card":"summary_large_image","twitter_creator":"@MundoAgropecuar","twitter_site":"@MundoAgropecuar","twitter_misc":{"Escrito por":"mundo","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mundoagropecuario.cl\/new\/vinos-en-lata-y-bebidas-ready-to-drink-son-las-nuevas-tendencias-en-consumo\/#article","isPartOf":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/vinos-en-lata-y-bebidas-ready-to-drink-son-las-nuevas-tendencias-en-consumo\/"},"author":{"name":"mundo","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/person\/4e9f74a82a7dac260eb1c44b7eebeb18"},"headline":"Vinos en lata y bebidas ready to drink son las nuevas tendencias en consumo","datePublished":"2019-12-16T15:17:24+00:00","dateModified":"2019-12-18T14:15:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/vinos-en-lata-y-bebidas-ready-to-drink-son-las-nuevas-tendencias-en-consumo\/"},"wordCount":621,"publisher":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#organization"},"image":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/vinos-en-lata-y-bebidas-ready-to-drink-son-las-nuevas-tendencias-en-consumo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2019\/12\/01.jpg","keywords":["Vinos en lata","Vinos en lata y bebidas ready"],"articleSection":["Frutas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.mundoagropecuario.cl\/new\/vinos-en-lata-y-bebidas-ready-to-drink-son-las-nuevas-tendencias-en-consumo\/","url":"https:\/\/www.mundoagropecuario.cl\/new\/vinos-en-lata-y-bebidas-ready-to-drink-son-las-nuevas-tendencias-en-consumo\/","name":"Vinos en lata y bebidas ready to drink son las nuevas tendencias en consumo - Mundoagropecuario","isPartOf":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/vinos-en-lata-y-bebidas-ready-to-drink-son-las-nuevas-tendencias-en-consumo\/#primaryimage"},"image":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/vinos-en-lata-y-bebidas-ready-to-drink-son-las-nuevas-tendencias-en-consumo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2019\/12\/01.jpg","datePublished":"2019-12-16T15:17:24+00:00","dateModified":"2019-12-18T14:15:11+00:00","breadcrumb":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/vinos-en-lata-y-bebidas-ready-to-drink-son-las-nuevas-tendencias-en-consumo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mundoagropecuario.cl\/new\/vinos-en-lata-y-bebidas-ready-to-drink-son-las-nuevas-tendencias-en-consumo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoagropecuario.cl\/new\/vinos-en-lata-y-bebidas-ready-to-drink-son-las-nuevas-tendencias-en-consumo\/#primaryimage","url":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2019\/12\/01.jpg","contentUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2019\/12\/01.jpg","width":400,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.mundoagropecuario.cl\/new\/vinos-en-lata-y-bebidas-ready-to-drink-son-las-nuevas-tendencias-en-consumo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.mundoagropecuario.cl\/new\/"},{"@type":"ListItem","position":2,"name":"Vinos en lata y bebidas ready to drink son las nuevas tendencias en consumo"}]},{"@type":"WebSite","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#website","url":"https:\/\/www.mundoagropecuario.cl\/new\/","name":"Mundoagropecuario","description":"Mundo Agropecuario","publisher":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mundoagropecuario.cl\/new\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#organization","name":"Revista de Agricultura","url":"https:\/\/www.mundoagropecuario.cl\/new\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/logo\/image\/","url":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/11\/PORTAL-1-1.png","contentUrl":"https:\/\/www.mundoagropecuario.cl\/new\/wp-content\/uploads\/2020\/11\/PORTAL-1-1.png","width":1026,"height":100,"caption":"Revista de Agricultura"},"image":{"@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mundo.agropecuario.3","https:\/\/x.com\/MundoAgropecuar","https:\/\/www.linkedin.com\/in\/mundo-agropecuario-934009201\/"]},{"@type":"Person","@id":"https:\/\/www.mundoagropecuario.cl\/new\/#\/schema\/person\/4e9f74a82a7dac260eb1c44b7eebeb18","name":"mundo","url":"https:\/\/www.mundoagropecuario.cl\/new\/author\/mundo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts\/15198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/comments?post=15198"}],"version-history":[{"count":1,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts\/15198\/revisions"}],"predecessor-version":[{"id":15200,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/posts\/15198\/revisions\/15200"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/media\/15199"}],"wp:attachment":[{"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/media?parent=15198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/categories?post=15198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mundoagropecuario.cl\/new\/wp-json\/wp\/v2\/tags?post=15198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}